{"id":19568,"date":"2025-11-09T10:17:00","date_gmt":"2025-11-09T09:17:00","guid":{"rendered":"https:\/\/instytutpolski.pl\/leipzig\/?p=19568"},"modified":"2026-06-05T10:25:05","modified_gmt":"2026-06-05T08:25:05","slug":"rueckkehr-des-feuervogels","status":"publish","type":"post","link":"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/","title":{"rendered":"3. Sinfoniekonzert: R\u00fcckkehr des Feuervogels"},"content":{"rendered":"\n<p><strong>Termine:<br \/><\/strong>Sa \/ 07.11.2026 \/ 19:00<br \/>So \/ 08.11.2026 \/ 11:00<br \/>Mo \/ 09.11.2026, \/19:00<\/p>\n<p>Konzerteinf\u00fchrung jeweils 45 Minuten vor Beginn im Opernkeller der Semperoper<\/p>\n<p>Zwei Werke aus der Welt der musikalischen Moderne: farbenreich, schillernd, von Energie durchzogen. <strong><a href=\"https:\/\/de.wikipedia.org\/wiki\/Karol_Szymanowski\">Karol Szymanowskis<\/a><\/strong> zweites Violinkonzert entstand 1933 in enger Zusammenarbeit mit dem Geiger <a href=\"https:\/\/de.wikipedia.org\/wiki\/Paul_Kochanski\">Pawe\u0142 Kocha\u0144ski<\/a>. Es verbindet virtuose Brillanz mit einer frei flie\u00dfenden, fast improvisatorischen Form. Den Solopart \u00fcbernimmt Leonidas Kavakos, einer der pr\u00e4genden Interpreten dieses Repertoires.<\/p>\n<div id=\"attachment_11643\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11643\" class=\"wp-image-11643\" src=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2024\/03\/Karol-Szymanowski-Public-Domain_strona.jpg\" alt=\"\" width=\"700\" height=\"437\" srcset=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2024\/03\/Karol-Szymanowski-Public-Domain_strona.jpg 1361w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2024\/03\/Karol-Szymanowski-Public-Domain_strona-300x187.jpg 300w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2024\/03\/Karol-Szymanowski-Public-Domain_strona-1024x639.jpg 1024w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2024\/03\/Karol-Szymanowski-Public-Domain_strona-768x479.jpg 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-11643\" class=\"wp-caption-text\">Karol Szymanowski (1922)<\/p><\/div>\n<p>Igor Strawinskys \u201eFeuervogel\u201c, 1910 f\u00fcr die Ballets Russes komponiert, machte seinen Sch\u00f6pfer \u00fcber Nacht ber\u00fchmt. In m\u00e4rchenhafter Handlung und leuchtender Orchesterpalette verbinden sich russische Folklore, t\u00e4nzerische Impulse und klangliche Raffinesse zu einem musikalischen Zauber von ungebrochener Wirkung. <em>[Text: Semperoper Dresden]<\/em><\/p>\n<div id=\"attachment_19580\" style=\"width: 472px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19580\" class=\"wp-image-19580\" src=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2025\/11\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Pawel-Kochanski-1921-Public-Domain.jpg\" alt=\"\" width=\"462\" height=\"700\" srcset=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2025\/11\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Pawel-Kochanski-1921-Public-Domain.jpg 960w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2025\/11\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Pawel-Kochanski-1921-Public-Domain-198x300.jpg 198w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2025\/11\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Pawel-Kochanski-1921-Public-Domain-677x1024.jpg 677w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2025\/11\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Pawel-Kochanski-1921-Public-Domain-768x1162.jpg 768w\" sizes=\"auto, (max-width: 462px) 100vw, 462px\" \/><p id=\"caption-attachment-19580\" class=\"wp-caption-text\">Pawe\u0142 Kocha\u0144ski (ca. 1921)<\/p><\/div>\n<p>Auff\u00fchrende:<br \/><strong>Robin Ticciati <\/strong>(Dirigent)<br \/><strong>Leonidas Kavakos<\/strong> (Violine)<br \/><strong>S\u00e4chsische Staatskapelle Dresden<\/strong><\/p>\n<p>Veranstalter: Semperoper Dresden<\/p>\n<p><strong>Info:<\/strong> <a href=\"https:\/\/www.staatskapelle-dresden.de\/konzerte-und-tickets\/details\/2026-27\/3-sinfoniekonzert\/\">staatskapelle-dresden.de\/konzerte-und-tickets\/details\/2026-27\/3-sinfoniekonzert\/<\/a><br \/><strong>Eintritt:<\/strong> 12\u201382 EUR<br \/><strong>Ort:<\/strong> Semperoper, Theaterplatz 2, 01067 Dresden<\/p>\n<p>\u00a0<\/p>\n\n\n<h3>Empfehlungen des Polnischen Instituts:<\/h3><div class=\"event_loop event_list  no-list\" id=\"event_list1\" style=\"height:auto;\" ><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode category-Ausstellung post_tag-Ausstellung language-Deutsch post_tag-Dresden category-Empfehlungen post_tag-Film post_tag-Literatur\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/10\/25\/mit-glanz-und-gloria\/\"><h5>Mit Glanz und Gloria <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"\u015broda 10 grudnia 2025\" data-end=\"niedziela 25 pa\u017adziernika 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2025-12-10T00:00:00+00:00\">10 grudnia 2025<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-10-25T00:00:00+00:00\">25 pa\u017adziernika 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/17048.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Mit+Glanz+und+Gloria&#038;dates=20251210%2F20261025&#038;location=Kraszewski-Museum%2C+Nordstr.+28%2C+01099+Dresden&#038;details=Vor+40+Jahren+wurde+J%C3%B3zef+Ignacy+Kraszewskis+%E2%80%9ESachsen-Trilogie%E2%80%9C+verfilmt.+%E2%80%9ESachsens+Glanz+und+Preu%C3%9Fens+Gloria%E2%80%9C+war+die+gr%C3%B6%C3%9Fte+und+aufwendigste+Filmproduktion+der+DDR.+Weniger+bekannt+ist+die+polnische+Filmproduktion+%E2%80%9EGr%C3%A4fin+Cosel%E2%80%9C+%281960%29+von+Jerzy+Antczak.+Dies+wiederum+war+die+bis+dahin+kosteng%C3%BCnstigste+Produktion+der+polnischen+Kinematografie%2C+was+aber+keinerlei+Einfluss+auf+die+Qualit%C3%A4t+und+Popularit%C3%A4t+des+Films+hatte.%0ABeleuchtet+werden+die+historische+Zeit+der+S%C3%A4chsisch-polnischen+Union%2C+Hintergr%C3%BCnde+und+Entstehung+der+Filmproduktionen+sowie+Kraszewskis+Romanvorlagen.+Wie+entstanden+sie%3F+Wie+sah+und+beurteilte+der+polnische+Schriftsteller+August+den+Starken+und+den+s%C3%A4chsisch-polnischen+Hof%3F+Und+wie+ging+es+am+polnischen+Hof+zu%2C+den+die+Wettiner+von+1697+bis+1763+regierten%3F%0AVeranstalter%3A+Kraszewski-Museum+Dresden+unter+der+Schirmherrschaft+von+Dr.+Christine+Gr%C3%A4fin+von+Br%C3%BChl%0AInfo%3A+kraszewski-dresden.deEintritt%3A+4%2F3+EUR%C3%96ffnungszeiten%3A+Mi%E2%80%93So+%26amp%3B+Feiertage+12%3A00%E2%80%9317%3A00%2C+Freitag+ab+12%3A00+Uhr+frei+%28au%C3%9Fer+Feiertage%29Ort%3A+Kraszewski-Museum%2C+Nordstr.+28%2C+01099+Dresden%0A%C2%A0%0A%C2%A0%0AGrafiken+%C2%A9+Kraszewski-Museum+Dresden%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F10%2F25%2Fmit-glanz-und-gloria%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/17048.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Ausstellung <\/span>\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"17048\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nKraszewski-Museum, Nordstr. 28, 01099 Dresden\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch category-Empfehlungen category-Film category-Online\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/12\/31\/swiatloczula-photosensitive\/\"><h5>\u015awiat\u0142oczu\u0142a \/ Photosensitive. Das Licht in deinen Augen <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"czwartek 12 marca 2026\" data-end=\"czwartek 31 grudnia 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-03-12T00:00:00+00:00\">12 marca 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-12-31T00:00:00+00:00\">31 grudnia 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/18168.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=%C5%9Awiat%C5%82oczu%C5%82a+%2F+Photosensitive.+Das+Licht+in+deinen+Augen&#038;dates=20260312%2F20261231&#038;location=im+Stream&#038;details=Spielfilm%2C+R%3A+Tadeusz+%C5%9Aliwa%2C+PL+2025%2C+92+min%2C+FSK12%2C+deutsche+Synchronisation%2C+OmdU+sowie+Untertitel+f%C3%BCr+H%C3%B6rgesch%C3%A4digte+%26amp%3B+Audiodeskription%0Amit+Matylda+Gieg%C5%BCno%2C+Ignacy+Liss%2C+Bart%C5%82omiej+Deklewa%2C+Aleksandra+Pisula+u.a.%0ARobert+%28Ignacy+Liss%29+ist+auf+dem+Sprung+zur+ganz+gro%C3%9Fen+Karriere+%E2%80%93+als+Fotograf%2C+gefeiert+f%C3%BCr+seinen+besonderen+Blick+auf+die+Welt.+Doch+als+er+das+Model+Agata+%28Matylda+Gieg%C5%BCno%29+vor+der+Kamera+hat%2C+spielt+all+das+pl%C3%B6tzlich+keine+Rolle+mehr%3A+Der+Hype%2C+die+Erwartungen+%E2%80%93+die+Mauer%2C+die+er+zwischen+sich+und+der+Au%C3%9Fenwelt+hochgezogen+hat%2C+bekommt+Risse.%0AWas+er+nicht+ahnt%3A+Agata+ist+blind.+Doch+sie+sieht+Dinge%2C+die+ihm+verborgen+bleiben.+Mit+ihrer+unersch%C3%BCtterlichen+Art+zu+f%C3%BChlen%2C+zu+leben+und+zu+lieben+zieht+sie+ihn+in+ihren+Bann.+Zwischen+Spazierg%C3%A4ngen+ohne+Ziel%2C+Gespr%C3%A4chen+bis+tief+in+die+Nacht+und+Momenten+voller+Unsicherheit+w%C3%A4chst+etwas+Echtes+zwischen+ihnen.+Aber+als+die+M%C3%B6glichkeit+auftaucht%2C+dass+Agata+vielleicht+wieder+sehen+kann%2C+wird+alles+auf+die+Probe+gestellt.+Was+passiert%2C+wenn+sich+pl%C3%B6tzlich+die+Perspektive+%C3%A4ndert%3F%0A%5Bgallery+size%3D%22large%22+link%3D%22file%22+ids%3D%2218201%2C18200%2C18199%22%5D%0ADer+Film+feierte+seine+Deutschlandpremiere+auf+den+59.+Internationalen+Hofer+Filmtagen.+F%C3%BCr+ihre+Hauptrolle+als+blinde+Agata+wurde+Matylda+Gieg%C5%BCno+2025+beim+50.+Polnischen+Spielfilmfestival+in+Gdynia+als+beste+Hauptdarstellerin+ausgezeichnet%2C+au%C3%9Ferdem+gewann+der+Film+Publikumspreise+auf+Festivals+%C2%A0in+Seattle%2C+Sydney+und+Krak%C3%B3w.%0ATrailer%3A+https%3A%2F%2Fwww.youtube.com%2Fwatch%3Fv%3DUb9hWYJQZXs%0AVerleih%3A+Atlas+Film+GmbH%0AInfo%3A+atlas-film.de%2Fphotosensitive-das-licht-in-deinen-augen.htmlOrt%3A+als+Stream+bei+Amazon%2C+Google+Play+Store%2C+RakutenTV+%26amp%3B+Videoload%0A%C2%A0%0AFotos+%C2%A9+Karolina+Grabowska%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F12%2F31%2Fswiatloczula-photosensitive%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/18168.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span>\t\t\t\t\t<span  class=\"event_category\">Film <\/span>\t\t\t\t\t<span  class=\"event_category\">Online <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"18168\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nim Stream\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode category-Ausstellung post_tag-Ausstellung language-Deutsch post_tag-Dresden category-Empfehlungen post_tag-Leipzig\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/18\/festgehalten-verschleppt-aus-deutschland-1938-1945\/\"><h5>Festgehalten \u2013 Verschleppt aus Deutschland 1938\u20131945 <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"wtorek 12 maja 2026\" data-end=\"\u015broda 18 listopada 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-05-12T00:00:00+00:00\">12 maja 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-11-18T00:00:00+00:00\">18 listopada 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/18787.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Festgehalten+%E2%80%93+Verschleppt+aus+Deutschland+1938%E2%80%931945&#038;dates=20260512%2F20261118&#038;location=Sachsenburg%2C+Dresden%2C+Leipzig%2C+Zwickau%2C+Plauen+%26+Chemnitz&#038;details=Aus+dem+Deutschen+Reich+wurden+zwischen+1938+und+1945+mehr+als+200.000+Menschen+deportiert.+Die+meisten+von+ihnen+wurden+in+den+Vernichtungslagern+ermordet%2C+nur+wenige+%C3%BCberlebten.+Zahlreiche+dieser+Deportationen+sind+fotografisch+dokumentiert.+Aus+fast+siebzig+deutschen+St%C3%A4dten+sind+Bilder+von+Deportationen+%C3%BCberliefert+%E2%80%93+viele+weitere+Aufnahmen+sind+m%C3%B6glicherweise+noch+unentdeckt.%0ADas%C2%A0Forschungsprojekt+%23LastSeen%C2%A0sichert%2C+sammelt%2C+erforscht+und+ver%C3%B6ffentlicht+seit+2021+diese+Fotos+in+einem+digitalen+Atlas+und+stellt+sie+f%C3%BCr+Forschungs-%2C+Bildungs-+und+Gedenkarbeit+zur+Verf%C3%BCgung.+Daf%C3%BCr+ist+das+Projekt+schon+mit+zahlreichen+Preisen+ausgezeichnet+worden.+Der+Bildatlas+des+Projekts+ist+unter+atlas.lastseen.org+abrufbar.%0A%E2%80%9EFestgehalten%E2%80%9D+zeigt+ausgew%C3%A4hlte+Fotografien+der+Deportationen+von+J%C3%BCdinnen+und+Juden%2C+Sinti%2A+und+Roma%2A+sowie+von+Opfern+der+NS-%E2%80%9EEuthanasie%E2%80%9C.+Sie+zeigt+auch+die+T%C3%A4ter%2Ainnen+und+Zuschauende%2C+die+bei+den+Deportationen+anwesend+waren.+Denn+Deportationen+waren+sichtbar.+Sie+fanden+am+helllichten+Tag+statt.+Viele+Menschen+entschieden+sich%2C+bei+der+Verschleppung+ihrer+Nachbar%2Ainnen+zuzusehen+und+oftmals+auch+mitzuwirken.%0ADie+Ausstellung+fordert+auf%2C+sich+mit+der+Rolle+des+Publikums+auseinanderzusetzen.+Dies+ist+gerade+jetzt+wichtig+f%C3%BCr+die+deutsche+Erinnerungskultur.+Was+bedeutet+es%2C+wenn+Menschen+zuschauen%2C+wegschauen+oder+sich+beteiligen%2C+w%C3%A4hrend+ihre+Bekannten+und+Nachbar%2Ainnen+verschleppt+werden%3F+Was+wussten+die+Einzelnen%2C+welche+pers%C3%B6nlichen+Entscheidungen+trafen+sie+und+welche+individuelle+Handlungsmacht+hatten+sie%3F+Zwei+weitere+Bereiche+der+Ausstellung+setzen+sich+mit+der+Geschichte+der+Deportationen+und+mit+der+Geschichte+der+Deportationsfotografien+auseinander.%0ABegleitend+zur+Ausstellung+erm%C3%B6glicht+das+interaktive+Online-Entdeckerspiel+%23LastSeen+historische+Fotos+von+nationalsozialistischen+Deportationen+lesen+und+interpretieren+zu+lernen.+Spieler%2Ainnen+schl%C3%BCpfen+in+die+Rolle+eines+Bloggers+oder+einer+Bloggerin+und+gestalten+ihren+pers%C3%B6nlichen+Artikel+zu+den+historischen+Fotos.+Sie+untersuchen+die+Fotos+und+k%C3%B6nnen+zus%C3%A4tzliche+Quellen+zu+der+Geschichte+auf+einem+Dachboden+entdecken%2C+die+beim+Lesen+der+Fotos+helfen.%0A%5Bcaption+id%3D%22attachment_18811%22+align%3D%22aligncenter%22+width%3D%22800%22%5D+Online-Entdeckerspiel+%23LastSeen+%C2%A9+%26amp%3Bwhy%5B%2Fcaption%5D%0ADen+s%C3%A4chsischen+Auftakt+der+kompakten%2C+interaktiven+Ausstellung+bildet+eine+Er%C3%B6ffnungsveranstaltung+im+Mitteldeutschen+Rundfunk+am+12.+Mai+2026.%0ADie+Ausstellung+wird+an+folgenden+weiteren+Orten+in+Sachsen+zu+sehen+sein%3A%0A30.05.%E2%80%9307.06.2026+%7C+SachsenburgA.d.+Zschopau+6%2C+Frankenberg07.06.2026%2C+13%3A00+Uhr+Vortrag+zur+Ausstellung+mit+Dr.+Alina+Bothe+im+Rahmen+des+Sachsenburger+Dialogs%0A14.06.%E2%80%9328.06.2026+%7C+DresdenHole+of+Fame%2C+K%C3%B6nigsbr%C3%BCcker+Str.+39%2C+Dresden14.06.2026+Er%C3%B6ffnung+mit+Dr.+Alina+Bothe+und+Dr.+Daniel+Ristau%0A17.08.%E2%80%9314.09.2026+%7C+LeipzigAriowitsch-Haus%2C+Hinrichsenstr.+14%2C+Leipzig17.08.2026%2C+18%3A00+Uhr+Er%C3%B6ffnung+mit+Dr.+Ramona+Br%C3%A4u-HergetDie+Ausstellung+ist+vom+17.+August+bis+14.+September+immer+Montag+bis+Donnerstag%C2%A0von+14+bis+18+Uhr+bei+freier+Raumkapazit%C3%A4t+und+sonntags+zu+Veranstaltungen+f%C3%BCr%C2%A0Besucher%2Ainnen+ge%C3%B6ffnet.%0A15.09.%E2%80%9317.10.2026+%7C+ZwickauPriesterh%C3%A4user%2C+Domhof+5%E2%80%938%2C+Zwickau15.09.2026+Er%C3%B6ffnung%0A19.10.%E2%80%9307.11.2026+%7C+Plauencolorido-Treff%2C+Dittrichplatz+8%2C+Plauen%2FVogtland19.10.2026+Er%C3%B6ffnung+im+Rahmen+der+J%C3%BCdischen+Kulturtage%0A09.11.+%E2%80%93+18.11.2026+%7C+ChemnitzTechnische+Universit%C3%A4t+Chemnitz%2C+H%C3%B6rsaalgeb%C3%A4ude+C10Reichenhainer+Str.+90%2C+Chemnitz09.11.2026+Er%C3%B6ffnung+mit+Dr.+Ramona+Br%C3%A4u-Herget%0AOrte%3A+Sachsenburg%2C+Dresden%2C+Leipzig%2C+Zwickau%2C+Plauen+%26amp%3B+ChemnitzInfo%3A+lastseen.org%0A%C2%A0%0AFoto%3A+Fernaufnahme+der+Deportation+der+Juden+und+J%C3%BCdinnen+aus+Halberstadt+am+12.04.1942.+Am+Rand+des+Bildes+in+der+nicht+abgebildeten+Version+ist+handschriftlich+vermerkt%3A+%E2%80%9EThe+man+in+front+is+our+father.+To+his+right+our+mother.%E2%80%9C+%C2%A9+Archiv+Familie+Beverstein%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F11%2F18%2Ffestgehalten-verschleppt-aus-deutschland-1938-1945%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/18787.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Ausstellung <\/span>\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"18787\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nSachsenburg, Dresden, Leipzig, Zwickau, Plauen &#038; Chemnitz\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch category-Empfehlungen post_tag-Gewandhaus post_tag-Leipzig category-Musik post_tag-Musik category-Theater\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/10\/11\/eurydike\/\"><h5>Eurydike <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"sobota 30 maja 2026\" data-end=\"niedziela 11 pa\u017adziernika 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-05-30T00:00:00+00:00\">30 maja 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-10-11T00:00:00+00:00\">11 pa\u017adziernika 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19088.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Eurydike&#038;dates=20260530%2F20261011&#038;location=Oper%2C+Augustusplatz+12%2C+04109+Leipzig&#038;details=2+h+mit+Pause+%2F+ab+15+J.+%2F+Einf%C3%BChrung+30+min+vor+Vorstellungsbeginn+im+Konzertfoyer%0ATermine%3A%0A30.05.2026+%2F+19%3A00+%2F+Premiere06.06.2026+%2F+19%3A0014.06.2026+%2F+17%3A0019.06.2026+%2F+19%3A3024.06.2026+%2F+19%3A3026.06.2026+%2F+19%3A3019.09.2026+%2F+19%3A0026.09.2026+%2F+19%3A0002.10.2026+%2F+19%3A3011.10.2026+%2F+17%3A00%0AEurydike+bleibt+zur%C3%BCck.+Ihre+Geschichte%2C+oft+erz%C3%A4hlt+im+Schatten+von+Orpheus%E2%80%99+Gesang%2C+zeichnet+Fran+D%C3%ADaz+f%C3%BCr+das+Leipziger+Ballett+neu+nach.+Eurydike+ist+keine+Randfigur%2C+keine+Muse%2C+keine+Gefangene+einer+Liebe%2C+die+f%C3%BCr+sie+bestimmt+wurde.+Sie+ist+eine+Frau%2C+die+ihren+Weg+sucht+%E2%80%93+in+einer+Welt%2C+die+ihre+W%C3%BCnsche+formt+und+verweigert+zugleich.%0AEurydikes+Mythos+entfaltet+sich+in+einer+Gesellschaft%2C+die+st%C3%A4ndig+nach+vorne+strebt+und+dennoch+oft+im+Zur%C3%BCckblicken+stecken+bleibt.+In+einer+Welt%2C+in+der+Menschen+zu+Rollen+und+Beziehungen+zu+Erwartungen+werden%2C+wird+Eurydike+zu+einem+Spiegel+f%C3%BCr+Fragen+unserer+Zeit%3A+Was+bedeutet+Freiheit%3F+Und+wie+entkommen+wir+einem+System%2C+das+uns+definiert%2C+bevor+wir+uns+selbst+finden+k%C3%B6nnen%3F%0AMit+feinem+Gesp%C3%BCr+f%C3%BCr+das+M%C3%A4rchenhafte+und+das+Zeitlose+%C3%B6ffnet+Choreograph+Fran+D%C3%ADaz+den+Raum%2C+um+Eurydike+neu+zu+entdecken+%E2%80%93+als+Symbol+f%C3%BCr+den+Widerstand+gegen+das+Verloren-gehen+im+Strudel+aus+Vorgaben%2C+Tr%C3%A4umen+und+Sehns%C3%BCchten%2C+die+nicht+die+eigenen+sind.%C2%A0%5BText%3A+Gewandhaus+zu+Leipzig%5D%0A%C2%A0%0A%5Bcaption+id%3D%22attachment_19227%22+align%3D%22aligncenter%22+width%3D%22700%22%5D+Marcelino+Libao+2026+im+St%C3%BCck+%E2%80%9EJeune+Homme%E2%80%9C+von+Uwe+Scholz+%C2%A9+Ida+Zenna+%2F+Oper+Leipzig%5B%2Fcaption%5D%0A%C2%A0%0AGewandhausorchesterLeipziger+BallettMusikalische+Leitung%3A+Yura+YangChoreographie%3A+Fran+D%C3%ADazB%C3%BChne%3A+Laura+L%C3%B8weKost%C3%BCme%3A+Anna+Philippa+M%C3%BCllerDramaturgie%3A+Anna+Diepold%0ARepertoire%3AWojciech+Kilar+%E2%80%93+%E2%80%9EOrawa%E2%80%9C+f%C3%BCr+StreicherKrzysztof+Penderecki+%E2%80%93+Adagietto+f%C3%BCr+Englischhorn+und+StreichorchesterKrzysztof+Penderecki+%E2%80%93+Intermezzo+f%C3%BCr+24+StreicherKrzysztof+Penderecki+%E2%80%93+Ciaccona+f%C3%BCr+Streichorchester+-+aus+dem+Polnischen+RequiemKrzysztof+Penderecki+%E2%80%93+Sinfonietta+Nr.+3+%28Fassung+f%C3%BCr+Streichorchester%29Henryk+Miko%C5%82aj+G%C3%B3recki+%E2%80%93+Quasi+una+fantasia+op.+78%0AVeranstalter%3A+Oper+zu+Leipzig%0AInfo%3A+oper-leipzig.de%2Fde%2Fprogramm%2Feurydike%2F795Eintritt%3A+18%E2%80%9395+EUROrt%3A+Oper%2C+Augustusplatz+12%2C+04109+Leipzig%0A%C2%A0%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F10%2F11%2Feurydike%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19088.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span>\t\t\t\t\t<span  class=\"event_category\">Musik <\/span>\t\t\t\t\t<span  class=\"event_category\">Theater <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19088\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nOper, Augustusplatz 12, 04109 Leipzig\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch category-Empfehlungen category-Film\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/12\/31\/dobry-chlopiec-good-boy\/\"><h5>Dobry chlopiec \/ Good Boy \u2013 Wir wollen nur dein Bestes <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"czwartek 4 czerwca 2026\" data-end=\"czwartek 31 grudnia 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-06-04T00:00:00+00:00\">4 czerwca 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-12-31T00:00:00+00:00\">31 grudnia 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19501.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Dobry+chlopiec+%2F+Good+Boy+%E2%80%93+Wir+wollen+nur+dein+Bestes&#038;dates=20260604%2F20261231&#038;location=im+Kino&#038;details=Spielfilm%2C+R%3A+Jan+Komasa%2C+PL%2FUK+2026%2C+111+min%2C+eng.+OmdU+%26amp%3B+deutsche+Synchronfassung%2C+FSK+16%0Au.a.+im+Regina-Palast%2C+Passage+Kinos%2C+Schauburg+%28Leipzig%29%2C+Clubkino+Sigmar+%28Chemnitz%29%2C+Astoria+%28Zwickau%29%2C+Lichthaus+%28Weimar%29%2C+UCI%2C+Schauburg%2C+Programmkino+Ost+%26amp%3B+Zentralkino+%28Dresden%29%0ADer+19-j%C3%A4hrige+Tommy+%28Anson+Boon%29+genie%C3%9Ft+sein+Leben+als+Krimineller%2C+treibt+seine+Freunde+immer+wieder+zu+grausamen+Gewalttaten+an+und+prahlt+damit+auf+Social+Media+%E2%80%93+bis+er+eines+Nachts+von+einem+Fremden+entf%C3%BChrt+wird.+Als+Tommy+erwacht%2C+findet+er+sich+angekettet+im+Keller+eines+abgelegenen+Vorstadthauses+wieder%2C+in+dem+sein+Entf%C3%BChrer+Chris+%28Stephen+Graham%29+mit+seiner+Frau+Kathryn+%28Andrea+Riseborough%29+und+ihrem+jungen+Sohn+Jonathan+lebt.%0ADie+Familie+setzt+alles+daran%2C+Tommys+unkontrolliertes+Verhalten+zu+%E2%80%9Ereformieren%E2%80%9C%2C+und+unterzieht+ihn+zahlreichen+psychologischen+Spielchen%2C+um+aus+ihm+einen+%E2%80%9Ebraven+Jungen%E2%80%9C+zu+machen.+W%C3%A4hrend+Tommy+sich+mit+allen+Mitteln+dagegen+wehrt%2C+wird+er+immer+tiefer+in+die+dysfunktionale+Familiendynamik+von+Chris%2C+Kathryn+und+Jonathan+hineingezogen%2C+aber+auch+mit+seinen+eigenen+Sehns%C3%BCchten+konfrontiert.+Schleichend+merkt+Tommy%2C+dass+seine+Gef%C3%BChle+zwischen+Hass+und+Sympathie%2C+zwischen+Fluchtreflex+und+dem+Bed%C3%BCrfnis+nach+N%C3%A4he+verschwimmen.%0AMit+seinem+Film+%E2%80%9EGood+Boy+%E2%80%93+Wir+wollen+nur+dein+Bestes%E2%80%9C+legt+der+oscar-nominierte+Regisseur+Jan+Komasa+%28%E2%80%9ESala+samob%C3%B3jc%C3%B3w+%2F+Suicide+Room%E2%80%9C%2C+%E2%80%9EMiasto+44+%2F+Warschau+%C2%B444%E2%80%9C%2C+%E2%80%9EBo%C5%BCe+cia%C5%82o+%2F+Corpus+Christi%E2%80%9C%29+einen+provokanten+Gesellschaftsthriller+vor%2C+der+vom+Guardian+mit+Kubricks+%E2%80%9EClockwork+Orange%E2%80%9C+verglichen+wurde.+%5BText%3A+X-Verleih%5D%0AB%3A+Bartosz+BartosikK%3A+Micha%C5%82+DymekM%3A+Abel+KorzeniowskiS%3A+Agnieszka+Gli%C5%84skaD%3A+Andrea+Riseborough%2C+Stephen+Graham%2C+Anson+Boon%2C+Kit+Rakusen%2C+Monika+Frajczyk+u.a.%0AVertrieb%3A+X-Verleih%0AInfo%3A+x-verleih.de%2Ffilme%2Fgood-boy-wir-wollen-nur-dein-bestes%0AFotos+%C2%A9+Lukasz+Bak+%2F+X-Verleih+%2F+RPC+Good+Boy+Limited+%2F+Skopia+Film%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F12%2F31%2Fdobry-chlopiec-good-boy%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19501.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span>\t\t\t\t\t<span  class=\"event_category\">Film <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19501\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nim Kino\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch category-Empfehlungen post_tag-Gewandhaus post_tag-Leipzig post_tag-Musik category-Theater\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/10\/28\/fischer-fritz\/\"><h5>Fischer Fritz <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"wtorek 16 czerwca 2026\" data-end=\"\u015broda 28 pa\u017adziernika 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-06-16T00:00:00+00:00\">16 czerwca 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-10-28T00:00:00+00:00\">28 pa\u017adziernika 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19173.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Fischer+Fritz&#038;dates=20260616%2F20261028&#038;location=Staatsschauspiel%2C+Kleines+Haus+3%2C+Glacisstr.+28%2C+01099+Dresden&#038;details=Sprechtheater+von+Raphaela+Bardutzky%C3%9Cbersetzung+der+polnischen+Passagen+von+Aleksandra+Lukoszek%0ATermine%3A10.06.2026+%2F+20%3A0020.10.2026+%2F+19%3A3028.10.2026+%2F+20%3A00Sein+Leben+lang+fischt+Fischer+Fritz+frische+Fische+%E2%80%93+wie+schon+sein+Vater+und+sein+Gro%C3%9Fvater.+Doch+nun%2C+nach+einem+Schlaganfall%2C+nicht+mehr.+Da+muss+er+m%C3%BChsam+mit+Sprachspielen+die+Worte+wiederfinden.+Nach+langem+Schweigen+und+wenigen+Worten+willigt+er+ein%2C+dass+eine+polnische+Pflegekraft+bei+ihm+einzieht%2C+die+sich+rund+um+die+Uhr+um+ihn+k%C3%BCmmert.+Piotra+hatte+sich+ihr+Leben+in+Deutschland+anders+vorgestellt%3A+Heimweh+und+Eint%C3%B6nigkeit+durchziehen+ihre+Tage.+Doch+irgendwann+kommen+sich+Pflegerin+und+Patient+in+ihrer+Einsamkeit%2C+dem+Ringen+um+die+neue+und+die+verlorene+Sprache+und+ihrem+Wissen+um+in+Vergessenheit+geratene+Fischrezepte+n%C3%A4her.+Ein+St%C3%BCck%2C+das+vom+%C3%9Cberwinden+der+sprachlichen%2C+kulturellen+und+auch+pers%C3%B6nlichen+Barrieren+erz%C3%A4hlt+und+deutsch-polnische+Kulturbegegnungen+nahbar+macht.%0AMit+Witz+und+Sensibilit%C3%A4t+erz%C3%A4hlt+Raphaela+Bardutzky+von+den+Herausforderungen+des+Altwerdens%2C+von+Care-Arbeit%2C+Generationskonflikten+und+den+vielf%C3%A4ltigen+M%C3%B6glichkeiten%2C+miteinander+ins+Gespr%C3%A4ch+zu+kommen%2C+wenn+sich+Sprachen%2C+Dialekte+und+Lebenswege+unterscheiden.+Die+Autorin+erhielt+f%C3%BCr+FISCHER+FRITZ%2C+das+2021+beim+Heidelberger+St%C3%BCckemarkt+nominiert+war%2C+den+Publikumspreis+zum+F%C3%B6rderpreis+f%C3%BCr+Neue+Dramatik+an+den+M%C3%BCnchner+Kammerspielen.+2022+geh%C3%B6rte+Raphaela+Bardutzky+mit+der+Urauff%C3%BChrung+des+St%C3%BCckes+vom+Schauspiel+Leipzig+zu+den+Gewinner%2Ainnen+der+Autor%2Ainnentheatertage+am+Deutschen+Theater+in+Berlin.+%5BText%3A+Staatsschauspiel+Dresden%2C+bearbeitet%5D%0A%5Bgallery+size%3D%22large%22+link%3D%22file%22+ids%3D%2219221%2C19220%2C19218%22%5D%0ADauer%3A+ca.+1%3A40+h%2C+keine+Pause%0ATrailer%3A+youtube.com%2Fwatch%3Fv%3DYst1H16ek5g%0ADamian+Popp+%28Regie%29Tanja+Maderner+%28B%C3%BChne+und+Kost%C3%BCme%29Jonas+Schilling+%28Musik%29Timo+Fischer+%28Lichtdesign%29Uta+Girod+%28Dramaturgie%29%0ADarsteller%2Ainnen%3AHolger+H%C3%BCbnerSven+H%C3%B6nigKarina+Plachetka+%28geb.+1975+in+Strzelce+Opolskie%29%0AVeranstalter%3A+Staatsschauspiel+Dresden%0AInfo%3A+staatsschauspiel-dresden.deEintritt%3A+7%E2%80%9314+EUR+%28Tickets%29Ort%3A+Staatsschauspiel%2C+Kleines+Haus+3%2C+Glacisstr.+28%2C+01099+Dresden%0A%C2%A0%0AFotos%C2%A0%C2%A9%C2%A0Sebastian+Hoppe+%2F+Staatsschauspiel+Dresden%0A%C2%A0%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F10%2F28%2Ffischer-fritz%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19173.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span>\t\t\t\t\t<span  class=\"event_category\">Theater <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19173\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nStaatsschauspiel, Kleines Haus 3, Glacisstr. 28, 01099 Dresden\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch category-Empfehlungen category-Film\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/12\/31\/ojczyzna-vaterland\/\"><h5>Ojczyzna \/ Vaterland <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"tomorrow\" data-end=\"czwartek 31 grudnia 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-09-03T00:00:00+00:00\">tomorrow<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-12-31T00:00:00+00:00\">31 grudnia 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19813.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Ojczyzna+%2F+Vaterland&#038;dates=20260903%2F20261231&#038;location=im+Kino&#038;details=Spielfilm%2C+R%3A+Pawe%C5%82+Pawlikowski%2C+PL%2FD%2FFRA+2026%2C+82+min%2C+dt.+Fassung%0Amit+Sandra+H%C3%BCller%2C+Hanns+Zischler%2C+August+Diehl%2C+Devid+Striesow%2C+Joanna+Kulig%2C+Marcin+Masecki%2C+Andrzej+K%C5%82ak+u.a.%0ALeipzig-Premiere+mit+Sandra+H%C3%BCller+am+26.08.+um+19%3A00+und+19%3A15+Uhr+in+den+Passage+Kinos%0ANach+dem+Ende+des+Zweiten+Weltkriegs+begeben+sich+Literaturnobelpreistr%C3%A4ger+Thomas+Mann+%28Hanns+Zischler%29+und+seine+Tochter%2C+die+Schauspielerin%2C+Autorin+und+Kabarettistin+Erika+%28Sandra+H%C3%BCller%29%2C+auf+eine+Reise+durch+ein+Deutschland+in+Tr%C3%BCmmern+%E2%80%93+von+Frankfurt%2FMain+in+der+amerikanischen+Besatzungszone+bis+ins+sowjetisch+kontrollierte+Weimar.+Zum+Goethe-Jubil%C3%A4um+w%C3%BCnscht+man+sich+auf+beiden+Seiten+der+innerdeutschen+Grenze+Worte+des+Trostes%2C+der+Zustimmung+und+der+Vergebung+vom+gr%C3%B6%C3%9Ften+aller+Erz%C3%A4hler.%0AZwischen+euphorischen+Wagner-Erben+und+literarisch+versierten+Gener%C3%A4len+wird+Deutschlands+wichtigster+Schriftsteller+hofiert+und+manchmal+auch+beschimpft%2C+w%C3%A4hrend+das+Drama+seiner+eigenen+Familie+leise+eskaliert.+Es+ist+das+erste+Mal+seit+dem+Krieg%2C+dass+Thomas+Mann+in+sein+Heimatland+zur%C3%BCckkehrt%2C+aus+dem+er+einst+ins+Exil+geflohen+war.+Eine+Reise+in+die+verwundete+deutsche+Seele%2C+die+heilen+soll+%E2%80%93+sie+wird+f%C3%BCr+Erika+und+den+Zauberer%2C+wie+seine+Kinder+Thomas+Mann+oft+nannten%2C+zu+einer+Reise+ins+Innerste.%0ANach+dem+Oscar-pr%C3%A4mierten+%E2%80%9EIda%E2%80%9C+und+dem+vielfach+ausgezeichneten+Drama+%E2%80%9EZimna+Wojna+%2F+Cold+War+%E2%80%93+Der+Breitengrad+der+Liebe%E2%80%9C+%28Beste+Regie+in+Cannes%2C+f%C3%BCnf+Europ%C3%A4ische+Filmpreise%2C+darunter+f%C3%BCr+den+Besten+Film%29+erz%C3%A4hlt+Pawe%C5%82+Pawlikowski+in+%C3%BCberragenden+Kinobildern+eine+gro%C3%9Fe+deutsche+Familiengeschichte+im+Tumult+der+Nachkriegszeit.+Mit+zarter+Unerbittlichkeit+%C3%BCberblendet+%E2%80%9EOjczyzna+%2F+Vaterland%E2%80%9C+den+Nullpunkt+der+deutschen+Geschichte+mit+dem+Finale+einer+Familiensaga.+Eine+intensive+filmische+Erfahrung%2C+getragen+von+einem+%C3%BCberragenden+Ensemble.%0A%E2%80%9EWie+meine+fr%C3%BCheren+Filme+besch%C3%A4ftigt+sich+auch+%E2%80%9AVaterland%E2%80%98+mit+den+Wirren+der+Geschichte%2C+mit+dem+Exil+und+mit+unserem+tiefen+Bed%C3%BCrfnis+nach+Heimat+und+Zugeh%C3%B6rigkeit.+Au%C3%9Ferdem+verbindet+der+Film+einen+dramatischen+historischen+Moment+mit+einer+ganz+besonderen+pers%C3%B6nlichen+Geschichte.%E2%80%9C%28Pawe%C5%82+Pawlikowski%29%0A%5Bgallery+columns%3D%222%22+link%3D%22file%22+size%3D%22large%22+ids%3D%2219815%2C19816%22%5D%0ABuch%3A+Pawe%C5%82+Pawlikowski%2C+Henk+HandloegtenKamera%3A+%C5%81ukasz+%C5%BBalSzenografie+%26amp%3B+Innenaustattung%3A+Katarzyna+Soba%C5%84ska%2C+Marcel+S%C5%82awi%C5%84skiMaske%3A+Waldemar+PokromskiKost%C3%BCmbild%3A+Aleksandra+StaszkoTon%3A+Lars+Ginzel%2C+Tarn+WillersSchnitt%3A+Pawe%C5%82+Pawlikowski%2C+Piotr+W%C3%B3jcikProduktionsleitung%3A+Marcin+Kupiecki%0ADer+polnische+Filmemacher+Pawe%C5%82+Pawlikowski+begann+seine+Karriere+als+Regisseur+von+preisgekr%C3%B6nten+Dokumentarfilmen+in+Gro%C3%9Fbritannien%2C+bevor+er+sich+mit+%E2%80%9EOstatnie+wyj%C5%9Bcie+%2F+Last+Resort%E2%80%9C+%282000%29+und+%E2%80%9ELato+mi%C5%82o%C5%9Bci+%2F+My+Summer+of+Love%E2%80%9D+%282004%29+dem+Spielfilm+widmete.+Beide+Filme+wurden+mit+dem+BAFTA+ausgezeichnet.+Sein+Film+%E2%80%9EIda%E2%80%9C+%282013%29+gewann+als+erster+polnischer+Film+den+Oscar+als+Bester+Fremdsprachiger+Film+und+wurde+zudem+mit+f%C3%BCnf+European+Film+Awards+geehrt%2C+u.a.+f%C3%BCr+den+Besten+Film%2C+die+Beste+Regie+und+das+Beste+Drehbuch.+%E2%80%9EZimna+Wojna+%2F+Cold+War+%E2%80%93+Der+Breitengrad+der+Liebe%E2%80%9C+%282018%29+feierte+seine+Premiere+im+Wettbewerb+der+Filmfestspiele+in+Cannes%2C+wo+Pawlikowski+mit+dem+Preis+f%C3%BCr+die+Beste+Regie+ausgezeichnet+wurde.+Der+Film+erhielt+danach+drei+Oscar-Nominierungen%2C+darunter+f%C3%BCr+die+Beste+Regie%2C+und+gewann+2018+f%C3%BCnf+European+Film+Awards%2C+u.a.+in+der+Kategorie+Bester+Film%2C+Beste+Regie+und+Bestes+Drehbuch.%0A%5Bgallery+link%3D%22file%22+columns%3D%222%22+size%3D%22large%22+ids%3D%2219817%2C19818%22%5D%0AVerleih%3A+Neue+Visionen%0APresseheft+als+Download+%283+MB%29Info%3A+neuevisionen.de%2Fde%2Ffilme%2Fvaterland-196Orte%3A+Kinos+in+Deutschland%0A%C2%A0%0AFotos+%C2%A9+Neue+Visionen+%2F+Agata+Grzybowska%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F12%2F31%2Fojczyzna-vaterland%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19813.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span>\t\t\t\t\t<span  class=\"event_category\">Film <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19813\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nim Kino\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch category-Empfehlungen category-Theater post_tag-Theater\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2026\/01\/16\/yvonne-die-burgunderprinzessin\/\"><h5>Yvonne, die Burgunderprinzessin <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"niedziela 6 wrze\u015bnia 2026\" data-end=\"sobota 16 stycznia 2027\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-09-06T00:00:00+00:00\">6 wrze\u015bnia 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2027-01-16T00:00:00+00:00\">16 stycznia 2027<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19929.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Yvonne%2C+die+Burgunderprinzessin&#038;dates=20260906%2F20270116&#038;location=Theater+Gera+%26+Theater+Altenburg&#038;details=Theaterzelt+Altenburg06.09.2026+%2F+11%3A00+%2F+Matinee+im+Heizhaus+%2F+Eintritt+frei12.09.2026+%2F+19%3A30+%2F+Premiere16.09.2026+%2F+14%3A3019.09.2026+%2F+19%3A3003.10.2026+%2F+19%3A3024.10.2026+%2F+19%3A3013.11.2026+%2F+19%3A30%0AGro%C3%9Fes+Haus+Gera15.11.+%2F+11%3A00+%2F+Matinee+auf+der+B%C3%BChne+am+Park+%2F+Eintritt+frei20.11.2026+%2F+19%3A30+%2F+Premiere22.11.2026+%2F+14%3A3013.12.2026+%2F+14%3A3015.01.2027+%2F+19%3A3016.01.2027+%2F+19%3A30%0AAus+einer+Laune+heraus+stellt+Prinz+Philipp%2C+der+burgundische+Thronfolger%2C+dem+K%C3%B6nigspaar+und+dem+Hofstaat+die+nicht+besonders+ansehnliche%2C+wortkarge+und+apathische+Yvonne+als+seine+Verlobte+vor.+Um+dem+Ganzen+die+Krone+aufzusetzen%2C+kommt+Yvonne+noch+dazu+aus+dem+einfachen+Volk.+Ihre+Passivit%C3%A4t+bringt+letztlich+nicht+nur+das+K%C3%B6nigspaar+und+den+Hof%2C+sondern+auch+den+Prinzen+selbst+auf+die+Palme.+Dennoch%3A+Verlobt+ist+nun+einmal+verlobt.+Es+scheint+nur+noch+einen+letzten+Ausweg+aus+der+royalen+Misere+zu+geben%3A+Yvonne+muss+weg+%E2%80%93+und+zwar+schnell.%0ADas+Meisterwerk+des+absurden+Theaters+des+polnischen+Schriftstellers+Witold+Gombrowicz+aus+dem+Jahr+1935+h%C3%A4lt+der+aristokratischen+Gesellschaft+den+Spiegel+vor+%E2%80%93+bitterb%C3%B6se%2C+provokativ+und+hochgradig+komisch.+Das+St%C3%BCck+%C3%BCber+die+Angst+vor+dem+Fremden+wird+gemeinsam+von+den+Sparten+Schauspiel+und+Puppentheater+auf+die+B%C3%BChne+gebracht+wird.+%5BText%3A+Theater+Altenburg+Gera%5D%0ABeteiligte%3A%0AAntonia+Marie+Wa%C3%9Fmund+%28Prinz+%2F+Volk%29Charlotte+Ronas+%28K%C3%B6nigin+%2F+Volk+%2F+Hofdame%29Thomas+C.+Zinke+%28K%C3%B6nig+%2F+Volk+%2F+Hofdame%29Melis+Teichert+%28Innozenz+%2F+Volk+%2F+Hofdame%29Johannes+Emmrich+%28Cyrill+%2F+Hofdame%29Rufus+G%C3%BClland+%26amp%3B+Tobias+Weishaupt+%28Tante+%2F+Volk+%2F+Hofdame%29%0AFrank+Alexander+Engel+%28Inszenierung+%2F+B%C3%BChne%29Kerstin+Schmidt+%28Kost%C3%BCme+%2F+Puppen%29Susanne+Koschig+%26amp%3B+Felix+J.+Mohr+%28Dramaturgie%29%C2%A0%C2%A0+%0AVeranstalter%3A+Theater+Altenburg+Gera%0AInfo%3A+theater-altenburg-gera.de%2Fstuecke-konzerte%2Fyvonne-die-burgunderprinzessin-2154Eintritt%3A+19-27+EUROrte%3A+Theater+Gera%2C+Theaterplatz+1%2C+07548+Gera+%2FTheater+Altenburg%2C+Teichpromenade+36%2C+04600+Altenburg%0A%C2%A0%0AFoto+%C2%A9+Ronny+Ristok+%2F+Theater+Altenburg+Gera%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2026%2F01%2F16%2Fyvonne-die-burgunderprinzessin%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19929.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span>\t\t\t\t\t<span  class=\"event_category\">Theater <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19929\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nTheater Gera &#038; Theater Altenburg\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch post_tag-Dresden category-Empfehlungen category-Theater post_tag-Theater\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/09\/19\/omer-krieger-amphi-ii\/\"><h5>Omer Krieger: Amphi II <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"pi\u0105tek 18 wrze\u015bnia 2026\" data-end=\"sobota 19 wrze\u015bnia 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-09-18T00:00:00+00:00\">18 wrze\u015bnia 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-09-19T00:00:00+00:00\">19 wrze\u015bnia 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19751.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Omer+Krieger%3A+Amphi+II&#038;dates=20260918%2F20260919&#038;location=Freiluftb%C3%BChne+am+K%C3%B6nigsufer+%26+Festspielhaus+Hellerau%2C+Dresden&#038;details=Programmreihe+%E2%80%9EFragments+of+Life+and+Art+%E2%80%93+J%C3%BCdisches+Leben+in+Kunst+und+Kultur%E2%80%9C+%2817.09.2026%E2%80%9331.10.2026%29%0A18.09.2026+%2F+19%3A00+%2F+Prolog+%2F+Freiluftb%C3%BChne+am+K%C3%B6nigsufer+%2F+Eintritt+frei19.09.2026+%2F+19%3A00+%2F+Performance+%2F+Festspielhaus+Hellerau%0A%E2%80%9EAmphi+II%E2%80%9C+ist+eine+Performance+im+%C3%B6ffentlichen+Raum%2C+die+sich+mit+faschistischen+Kr%C3%A4ften+der+Vergangenheit+und+Gegenwart+auseinandersetzt.+Das+St%C3%BCck+basiert+auf+einem+Tanz%2C+den+die+Choreografin+Noa+Eshkol+1953+f%C3%BCr+eine+Gedenkfeier+zum+zehnten+Jahrestag%C2%A0des+Aufstands+im+Warschauer+Ghetto%C2%A0komponierte.+Das+Werk+wurde+nur+einmal+Amphitheater+vom+Haus+der+Ghettok%C3%A4mpfer+in+Israel+aufgef%C3%BChrt.%0AOmer+Kriegers+%E2%80%9EAmphi+II%E2%80%9C+%C3%BCbersetzt+das+Originalwerk+und+sein+k%C3%BCnstlerisches+und+politisches+Vokabular+in+die+Gegenwart.+Die+Choreografie+verbindet+archivarische+Spuren+mit+Bewegungen%2C+die+zwischen+Disziplin+und+Losl%C3%B6sung%2C+Trauer+und+Erneuerung%2C+Stille+und+Energie+wechseln.+Es+ist+ein+bewegtes+Denkmal%2C+das+Erinnerungen+an+Massenbewegungen+im+%C3%B6ffentlichen+Raum+wiederbelebt.+F%C3%BCr+Dresden+entwickelt+Omer+Krieger+eine+neue+Version+des+Werks%2C+die+sich+zwischen+zwei+historisch+bedeutsamen+Orten+entfaltet%3A+der+ehemaligen+Kundgebungsterrasse+der+NS-Zeit+im+Stadtzentrum+an+der+Elbe+und+dem+Festspielhaus+Hellerau%2C+das+als+Rhythmikschule+gegr%C3%BCndet+und+im+Nationalsozialismus+zum+Standort+der+Polizeischule+und+Polizeiwaffenschule+sowie+anschlie%C3%9Fend+von+der+Roten+Armee+genutzt+wurde.%0A%C3%9Cber+zwei+Tage+hinweg+bewegt+sich+%E2%80%9EAmphi%E2%80%9C+zwischen+Gedenktanz+und+%C3%B6ffentlicher+Aktion.+Es+arbeitet+mit+historischen+Gesten+im+aktuellen+politischen+Kontext+und+fragt%2C+wie+sich+K%C3%B6rper+versammeln+k%C3%B6nnen%2C+ohne+uniform+zu+werden%2C+und+wie+Gedenken+eine+aktive+Form+annehmen+kann.+Es+erprobt+eine+Form+des+Miteinanders%2C+die+offen+und+wachsam+bleibt+gegen%C3%BCber+den+Risiken+und+dem+Potenzial+von+Massenbewegungen.%0AOmer+Krieger+komponiert+performative+Aktionen%2C+soziale+Situationen%2C+Versammlungsformen+und+zivile+Choreografien+in+%C3%B6ffentlichen+R%C3%A4umen+Er+interessiert+sich+f%C3%BCr+die+Beziehungen+zwischen+Kunst%2C+Zivilgesellschaft+und+Aktion.%C2%A0%5BText%3A+HELLERAU+%E2%80%93+Europ%C3%A4isches+Zentrum+der+K%C3%BCnste%5D%0ADauer+der+Auff%C3%BChrung%3A+ca.+1+h+ohne+Pause%0AVeranstalter%3A+HELLERAU+%E2%80%93+Europ%C3%A4isches+Zentrum+der+K%C3%BCnste+in+Kooperation+mit+dem+Master-Studiengang+Choreografie+der+Palucca+Hochschule+f%C3%BCr+Tanz+Dresden%0AInfo%3A+hellerau.org%2F2026-27%2Famphi-iiEintritt+%28Hellerau%29%3A+16%E2%80%9324+EUROrt%3A+Freiluftb%C3%BChne+am+K%C3%B6nigsufer%2C+01097+Dresden-Neustadt+%2FFestspielhaus+Hellerau%2C+Karl-Liebknecht-Str.+56%2C+01109+Dresden-Klotzsche%0A%C2%A0%0AFoto+%C2%A9+Omer+Krieger+%2F+Any+Studio%0A%C2%A0%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F09%2F19%2Fomer-krieger-amphi-ii%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19751.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span>\t\t\t\t\t<span  class=\"event_category\">Theater <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19751\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nFreiluftb\u00fchne am K\u00f6nigsufer &#038; Festspielhaus Hellerau, Dresden\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode category-Andere language-Deutsch category-Empfehlungen category-Vortrag post_tag-Vortrag\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/10\/03\/steffen-moeller-praesident-osterode\/\"><h5>Steffen M\u00f6ller: Pr\u00e4sident von Polschland <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"sobota 3 pa\u017adziernika 2026\" data-end=\"sobota 3 pa\u017adziernika 2026\">\n\t\t\t\t\t\t\t<time itemprop=\"dtstart\" datetime=\"2026-10-03T20:00:00+02:00\"><span class=\"date date-single\">3 pa\u017adziernika 2026<\/span> <span class=\"linking_word linking_word-from\">from<\/span> <span class=\"time time-start\">20:00<\/span> <span class=\"linking_word linking_word-to\">to<\/span> <span class=\"time time-end\">22:00<\/span>\n\t\t\t\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/17021.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Steffen+M%C3%B6ller%3A+Pr%C3%A4sident+von+Polschland&#038;dates=20261003T200000%2F20261003T220000&#038;location=Stadthalle%2C+D%C3%B6rgestr.+28%2C+37520+Osterode+am+Harz&#038;details=Ein+Deutscher%2C+der+in+Polen+auf+der+Stra%C3%9Fe+h%C3%A4ufiger+gegr%C3%BC%C3%9Ft+wird+als+in+Deutschland%3F+F%C3%BCr+Steffen+M%C3%B6ller+gilt+das+auf+jeden+Fall.+Als+Dauergast+einer+polnischen+Endlos-Ferienserie+hat+er+einen+legend%C3%A4ren+Kultstatus+im+Nachbarland+erreicht.+Und+er+ist+ein+leidenschaftlicher+Botschafter+f%C3%BCr+Polen+in+Deutschland.+Deswegen+wurde+Steffen+M%C3%B6ller+auch+2013+mit+dem+Internationalen+Br%C3%BCckepreis+der+Europastadt+G%C3%B6rlitz-Zgorzelec+geehrt.%0AIn+seinem+neuen+B%C3%BChnenprogramm+treibt+Steffen+M%C3%B6ller+dies+nun+auf+die+Spitze.+Als+%E2%80%9EPr%C3%A4sident+von+Polschland%E2%80%9C+f%C3%BChrt+er+zwei+Welten+zu+einem+perfekten+Land+zusammen.+Nur+das+Beste+wird+zugelassen%2C+kulinarisch%2C+kulturell+und+sprachlich%3A+deutsche+Currywurst+und+polnische+Piroggen%2C+deutsche+Planung+und+polnische+Improvisation.+Viele+vertraute+Dinge+wird+es+dagegen+nicht+mehr+geben%2C+zum+Beispiel+zehnmin%C3%BCtige+Schaffneransagen+im+ICE.+F%C3%BCr+verm%C3%B6gende+Zuschauer+interessant%3A+Es+sind+noch+Minister%C3%A4mter+zu+vergeben%21%0AInfo%3A+steffen.pl%2C+osterode-stadthalle.deEintritt%3A+30%2C70+EUR+%28Tickets+hier%29Ort%3A+Stadthalle%2C+D%C3%B6rgestr.+28%2C+37520+Osterode+am+Harz%0A%C2%A0%0AFoto+%C2%A9+Wikipedia+%2F+Ralf+Lotys+%2F+CC+BY+4.0%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F10%2F03%2Fsteffen-moeller-praesident-osterode%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/17021.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Andere <\/span>\t\t\t\t\t<span  class=\"event_category\">Empfehlungen <\/span>\t\t\t\t\t<span  class=\"event_category\">Vortrag <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"17021\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nStadthalle, D\u00f6rgestr. 28, 37520 Osterode am Harz\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><\/div><!-- .event_loop -->\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Termine:Sa \/ 07.11.2026 \/ 19:00So \/ 08.11.2026 \/ 11:00Mo \/ 09.11.2026, \/19:00 Konzerteinf\u00fchrung jeweils 45 Minuten vor Beginn im Opernkeller der Semperoper Zwei Werke aus der Welt der musikalischen Moderne: farbenreich, schillernd, von Energie durchzogen. Karol Szymanowskis zweites Violinkonzert entstand 1933 in enger Zusammenarbeit mit dem Geiger Pawe\u0142 Kocha\u0144ski. Es verbindet virtuose Brillanz mit einer [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":19569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1,63],"tags":[482,438,420],"class_list":["post-19568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empfehlungen","category-musik-de","tag-festival-de","tag-halle-de","tag-musik-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>3. Sinfoniekonzert: R\u00fcckkehr des Feuervogels - Instytut Polski w Lipsku<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3. Sinfoniekonzert: R\u00fcckkehr des Feuervogels - Instytut Polski w Lipsku\" \/>\n<meta property=\"og:description\" content=\"Termine:Sa \/ 07.11.2026 \/ 19:00So \/ 08.11.2026 \/ 11:00Mo \/ 09.11.2026, \/19:00 Konzerteinf\u00fchrung jeweils 45 Minuten vor Beginn im Opernkeller der Semperoper Zwei Werke aus der Welt der musikalischen Moderne: farbenreich, schillernd, von Energie durchzogen. Karol Szymanowskis zweites Violinkonzert entstand 1933 in enger Zusammenarbeit mit dem Geiger Pawe\u0142 Kocha\u0144ski. Es verbindet virtuose Brillanz mit einer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/\" \/>\n<meta property=\"og:site_name\" content=\"Instytut Polski w Lipsku\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-09T09:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T08:25:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1165\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rainer Mende\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rainer Mende\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"event\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/\",\"url\":\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/\",\"name\":\"3. Sinfoniekonzert: R\u00fcckkehr des Feuervogels\",\"isPartOf\":{\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/#primaryimage\"},\"image\":[\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg\",\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona-300x175.jpg\",\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona-1024x596.jpg\",\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg\"],\"thumbnailUrl\":\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg\",\"datePublished\":\"2025-11-09T09:17:00+02:00\",\"dateModified\":\"2026-06-05T08:25:05+02:00\",\"author\":{\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/a74d20cf3dac53f5579b2a3ec40f22dd\"},\"breadcrumb\":{\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/\"]}],\"@context\":\"https:\/\/schema.org\",\"startDate\":\"2026-11-07\",\"endDate\":\"2026-11-09\",\"eventStatus\":\"EventScheduled\",\"eventAttendanceMode\":\"OfflineEventAttendanceMode\",\"location\":{\"@type\":\"place\",\"name\":\"Semperoper, Theaterplatz 2, 01067 Dresden\",\"address\":\"Semperoper, Theaterplatz 2, 01067 Dresden\",\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"51.28362182766469\",\"longitude\":\"12.376354797697585\"}},\"description\":\"Termine:Sa \/ 07.11.2026 \/ 19:00So \/ 08.11.2026 \/ 11:00Mo \/ 09.11.2026, \/19:00\\nKonzerteinf\u00fchrung jeweils 45 Minuten vor Beginn im Opernkeller der Semperoper\\nZwei Werke aus der Welt der musikalischen Moderne: farbenreich, schillernd, von Energie durchzogen. Karol Szymanowskis zweites Violinkonzert entstand 1933 in enger Zusammenarbeit mit dem Geiger Pawe\u0142 Kocha\u0144ski. Es verbindet virtuose Brillanz mit einer frei flie\u00dfenden, fast improvisatorischen Form. Den Solopart \u00fcbernimmt Leonidas Kavakos, einer der pr\u00e4genden Interpreten dieses Repertoires.\\n[caption id=\\\"attachment_11643\\\" align=\\\"aligncenter\\\" width=\\\"700\\\"] Karol Szymanowski (1922)[\/caption]\\nIgor Strawinskys \u201eFeuervogel\u201c, 1910 f\u00fcr die Ballets Russes komponiert, machte seinen Sch\u00f6pfer \u00fcber Nacht ber\u00fchmt. In m\u00e4rchenhafter Handlung und leuchtender Orchesterpalette verbinden sich russische Folklore, t\u00e4nzerische Impulse und klangliche Raffinesse zu einem musikalischen Zauber von ungebrochener Wirkung. [Text: Semperoper Dresden]\\n[caption id=\\\"attachment_19580\\\" align=\\\"aligncenter\\\" width=\\\"462\\\"] Pawe\u0142 Kocha\u0144ski (ca. 1921)[\/caption]\\nAuff\u00fchrende:Robin Ticciati (Dirigent)Leonidas Kavakos (Violine)S\u00e4chsische Staatskapelle Dresden\\nVeranstalter: Semperoper Dresden\\nInfo: staatskapelle-dresden.de\/konzerte-und-tickets\/details\/2026-27\/3-sinfoniekonzert\/Eintritt: 12\u201382 EUROrt: Semperoper, Theaterplatz 2, 01067 Dresden\\n\u00a0\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/#primaryimage\",\"url\":\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg\",\"contentUrl\":\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg\",\"width\":2000,\"height\":1165},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/instytutpolski.pl\/leipzig\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3. Sinfoniekonzert: R\u00fcckkehr des Feuervogels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#website\",\"url\":\"https:\/\/instytutpolski.pl\/leipzig\/\",\"name\":\"Instytut Polski w Lipsku\",\"description\":\"Kolejna witryna sieci &#8222;Instytuty Polskie&#8221;\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/instytutpolski.pl\/leipzig\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/a74d20cf3dac53f5579b2a3ec40f22dd\",\"name\":\"Rainer Mende\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/61382ed949dec269ce106c2fd5871a60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/61382ed949dec269ce106c2fd5871a60?s=96&d=mm&r=g\",\"caption\":\"Rainer Mende\"},\"url\":\"https:\/\/instytutpolski.pl\/leipzig\/author\/mender\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3. Sinfoniekonzert: R\u00fcckkehr des Feuervogels - Instytut Polski w Lipsku","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/","og_locale":"pl_PL","og_type":"article","og_title":"3. Sinfoniekonzert: R\u00fcckkehr des Feuervogels - Instytut Polski w Lipsku","og_description":"Termine:Sa \/ 07.11.2026 \/ 19:00So \/ 08.11.2026 \/ 11:00Mo \/ 09.11.2026, \/19:00 Konzerteinf\u00fchrung jeweils 45 Minuten vor Beginn im Opernkeller der Semperoper Zwei Werke aus der Welt der musikalischen Moderne: farbenreich, schillernd, von Energie durchzogen. Karol Szymanowskis zweites Violinkonzert entstand 1933 in enger Zusammenarbeit mit dem Geiger Pawe\u0142 Kocha\u0144ski. Es verbindet virtuose Brillanz mit einer [&hellip;]","og_url":"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/","og_site_name":"Instytut Polski w Lipsku","article_published_time":"2025-11-09T09:17:00+00:00","article_modified_time":"2026-06-05T08:25:05+00:00","og_image":[{"width":2000,"height":1165,"url":"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg","type":"image\/jpeg"}],"author":"Rainer Mende","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Rainer Mende","Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"event","@id":"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/","url":"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/","name":"3. Sinfoniekonzert: R\u00fcckkehr des Feuervogels","isPartOf":{"@id":"https:\/\/instytutpolski.pl\/leipzig\/#website"},"primaryImageOfPage":{"@id":"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/#primaryimage"},"image":["https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg","https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona-300x175.jpg","https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona-1024x596.jpg","https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg"],"thumbnailUrl":"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg","datePublished":"2025-11-09T09:17:00+02:00","dateModified":"2026-06-05T08:25:05+02:00","author":{"@id":"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/a74d20cf3dac53f5579b2a3ec40f22dd"},"breadcrumb":{"@id":"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/"]}],"@context":"https:\/\/schema.org","startDate":"2026-11-07","endDate":"2026-11-09","eventStatus":"EventScheduled","eventAttendanceMode":"OfflineEventAttendanceMode","location":{"@type":"place","name":"Semperoper, Theaterplatz 2, 01067 Dresden","address":"Semperoper, Theaterplatz 2, 01067 Dresden","geo":{"@type":"GeoCoordinates","latitude":"51.28362182766469","longitude":"12.376354797697585"}},"description":"Termine:Sa \/ 07.11.2026 \/ 19:00So \/ 08.11.2026 \/ 11:00Mo \/ 09.11.2026, \/19:00\nKonzerteinf\u00fchrung jeweils 45 Minuten vor Beginn im Opernkeller der Semperoper\nZwei Werke aus der Welt der musikalischen Moderne: farbenreich, schillernd, von Energie durchzogen. Karol Szymanowskis zweites Violinkonzert entstand 1933 in enger Zusammenarbeit mit dem Geiger Pawe\u0142 Kocha\u0144ski. Es verbindet virtuose Brillanz mit einer frei flie\u00dfenden, fast improvisatorischen Form. Den Solopart \u00fcbernimmt Leonidas Kavakos, einer der pr\u00e4genden Interpreten dieses Repertoires.\n[caption id=\"attachment_11643\" align=\"aligncenter\" width=\"700\"] Karol Szymanowski (1922)[\/caption]\nIgor Strawinskys \u201eFeuervogel\u201c, 1910 f\u00fcr die Ballets Russes komponiert, machte seinen Sch\u00f6pfer \u00fcber Nacht ber\u00fchmt. In m\u00e4rchenhafter Handlung und leuchtender Orchesterpalette verbinden sich russische Folklore, t\u00e4nzerische Impulse und klangliche Raffinesse zu einem musikalischen Zauber von ungebrochener Wirkung. [Text: Semperoper Dresden]\n[caption id=\"attachment_19580\" align=\"aligncenter\" width=\"462\"] Pawe\u0142 Kocha\u0144ski (ca. 1921)[\/caption]\nAuff\u00fchrende:Robin Ticciati (Dirigent)Leonidas Kavakos (Violine)S\u00e4chsische Staatskapelle Dresden\nVeranstalter: Semperoper Dresden\nInfo: staatskapelle-dresden.de\/konzerte-und-tickets\/details\/2026-27\/3-sinfoniekonzert\/Eintritt: 12\u201382 EUROrt: Semperoper, Theaterplatz 2, 01067 Dresden\n\u00a0"},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/#primaryimage","url":"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg","contentUrl":"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2026\/06\/2026-11-07-MUSIK-3.-Sinfoniekonzert-DD-Semperoper-Pixarbay_strona.jpg","width":2000,"height":1165},{"@type":"BreadcrumbList","@id":"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/09\/rueckkehr-des-feuervogels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/instytutpolski.pl\/leipzig\/"},{"@type":"ListItem","position":2,"name":"3. Sinfoniekonzert: R\u00fcckkehr des Feuervogels"}]},{"@type":"WebSite","@id":"https:\/\/instytutpolski.pl\/leipzig\/#website","url":"https:\/\/instytutpolski.pl\/leipzig\/","name":"Instytut Polski w Lipsku","description":"Kolejna witryna sieci &#8222;Instytuty Polskie&#8221;","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/instytutpolski.pl\/leipzig\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Person","@id":"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/a74d20cf3dac53f5579b2a3ec40f22dd","name":"Rainer Mende","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/61382ed949dec269ce106c2fd5871a60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61382ed949dec269ce106c2fd5871a60?s=96&d=mm&r=g","caption":"Rainer Mende"},"url":"https:\/\/instytutpolski.pl\/leipzig\/author\/mender\/"}]}},"_links":{"self":[{"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/posts\/19568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/comments?post=19568"}],"version-history":[{"count":10,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/posts\/19568\/revisions"}],"predecessor-version":[{"id":19582,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/posts\/19568\/revisions\/19582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/media\/19569"}],"wp:attachment":[{"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/media?parent=19568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/categories?post=19568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/tags?post=19568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}