{"id":7580,"date":"2022-01-22T10:49:00","date_gmt":"2022-01-22T09:49:00","guid":{"rendered":"https:\/\/instytutpolski.pl\/leipzig\/?p=7580"},"modified":"2023-01-23T10:53:13","modified_gmt":"2023-01-23T09:53:13","slug":"das-hamlet-syndrom-le","status":"publish","type":"post","link":"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/","title":{"rendered":"Syndrom Hamleta \/ Das Hamlet Syndrom"},"content":{"rendered":"\n<p><a href=\"https:\/\/twitter.com\/hashtag\/SolidarityWithUkraine?src=hashtag_click\">#SolidarityWithUkraine<\/a><\/p>\n<p>R: Elwira Niewiera &amp; Piotr Roso\u0142owski, D\/PL 2022, 85 min, OmdU<\/p>\n<p>Leipzig-Premiere der deutschen Kino-Fassung mit der Regisseurin <strong>Elwira Niewiera<\/strong><br \/>Moderation: <strong>Rainer Mende<\/strong> (Polnisches Institut Berlin \u2013 Filiale Leipzig)<\/p>\n<p>Wenige Monate vor der Invasion Russlands in die Ukraine 2022 nehmen f\u00fcnf junge Frauen und M\u00e4nner an einem einzigartigen Theaterprojekt teil. Darin versuchen sie, ihre Kriegserfahrungen mit Shakespeares Theaterst\u00fcck \u201eHamlet\u201c in Beziehung zu setzen. Die B\u00fchne ist eine Plattform, auf der sie ihre Trauer und Traumata anhand der ber\u00fchmten Frage \u201eSein oder Nichtsein\u201c reflektieren k\u00f6nnen, die sich in ihrem Leben widerspiegelt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7451\" src=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-3-Kundschafter-Filmproduktion_web.jpg\" alt=\"\" width=\"2000\" height=\"1081\" srcset=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-3-Kundschafter-Filmproduktion_web.jpg 2000w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-3-Kundschafter-Filmproduktion_web-300x162.jpg 300w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-3-Kundschafter-Filmproduktion_web-1024x553.jpg 1024w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-3-Kundschafter-Filmproduktion_web-768x415.jpg 768w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-3-Kundschafter-Filmproduktion_web-1536x830.jpg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p>Die Protagonist*innen k\u00e4mpfen an gegen Entt\u00e4uschung, Ohnmacht und Wut. Sie versuchen, ihr Leben wieder zu ordnen und gleichzeitig die schmerzhafte Vergangenheit zu verarbeiten: Slavik, der als Soldat durch die H\u00f6lle des Krieges und der Gefangenschaft gegangen ist, Katya, die in den Krieg zog und sich nun nach der Vergebung ihrer Mutter sehnt, weil sie in den Krieg zog, Rodion, der aus dem Donbas geflohen ist und nun mit wachsender Homophobie konfrontiert ist, Roman, der immer noch mit den traumatischen Erinnerungen als Sanit\u00e4ter auf dem Schlachtfeld k\u00e4mpft, und Oxana, die einfach nur vergessen und das Land verlassen will.<\/p>\n<p>Die Proben f\u00fcr das St\u00fcck werden mit einem intensiven Einblick in das Leben der Protagonist*innen kombiniert: ein kraftvolles Portr\u00e4t einer Generation, die mit dem Trauma des Krieges zurechtzukommen versucht, der seit 2014 in der Ostukraine andauert und nun nach dem Einmarsch Russlands in die Ukraine noch verst\u00e4rkt ihre Gegenwart und Zukunft pr\u00e4gt.<\/p>\n<p><a href=\"https:\/\/youtu.be\/BxySD52pheg\">https:\/\/youtu.be\/BxySD52pheg<\/a><\/p>\n<p><strong>Elwira Niewiera und Piotr Roso\u0142owski<\/strong> drehten gemeinsam bereits die preisgekr\u00f6nten Dokumentarfilme &#8222;Efekt Domina \/ Domino Effekt&#8221; und &#8222;Ksi\u0105\u017c\u0119 i dybuk \/ Der Prinz und der Dibbuk&#8221;, die ebenfalls deutsch-polnische Koproduktionen waren. &#8222;Syndrom Hamleta \/ Das Hamlet Syndrom&#8221; wurde u.a. auf Filmfestivals in Adelaide, Krak\u00f3w und Opole ausgezeichnet.<\/p>\n<p>Veranstalter: Passage Kinos Leipzig in Kooperation mit dem Polnischen Institut Berlin \u2013 Filiale Leipzig<\/p>\n\n\n\n<p>Veranstaltung auf <a href=\"https:\/\/www.facebook.com\/events\/540571754696838\/?\">Facebook<\/a><strong><br \/>Info:<\/strong> <a href=\"https:\/\/www.realfictionfilme.de\/das-hamlet-syndrom.html\">realfictionfilme.de\/das-hamlet-syndrom.html<\/a><strong>, <\/strong><a href=\"https:\/\/www.facebook.com\/TheHamletSyndrome\">facebook.com\/TheHamletSyndrome<\/a>, <a href=\"https:\/\/passage-kinos.de\/das-hamlet-syndrom\">passage-kinos.de\/das-hamlet-syndrom<\/a><strong><br \/><\/strong><strong>Ort:<\/strong> Passage Kinos, Hainstra\u00dfe 19a, 04109 Leipzig<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7449\" src=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Plakat.jpg\" alt=\"\" width=\"1757\" height=\"2482\" srcset=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Plakat.jpg 1757w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Plakat-212x300.jpg 212w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Plakat-725x1024.jpg 725w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Plakat-768x1085.jpg 768w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Plakat-1087x1536.jpg 1087w, https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Plakat-1450x2048.jpg 1450w\" sizes=\"auto, (max-width: 1757px) 100vw, 1757px\" \/><\/p>\n<pre>Fotos \u00a9 Kundschafter Filmproduktion<br \/><br \/><\/pre>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\" \/>\n\n\n<h3>Programm des Polnischen Instituts:<\/h3><div class=\"event_loop event_list  no-list\" id=\"event_list1\" style=\"height:auto;\" ><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode category-Andere language-Deutsch category-Diskussion post_tag-Diskussion category-Film post_tag-Film post_tag-Leipzig category-Literatur post_tag-Literatur category-Musik post_tag-Musik category-Programm\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2024\/12\/31\/cafe-ukraina-monatliche-meet-ups\/\"><h5>Caf\u00e9 Ukra\u0457na \u2013 monatliche Meet-Ups <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"pi\u0105tek 12 lipca 2024\" data-end=\"czwartek 31 grudnia 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2024-07-12T00:00:00+00:00\">12 lipca 2024<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-12-31T00:00:00+00:00\">31 grudnia 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/12122.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Caf%C3%A9+Ukra%D1%97na+%E2%80%93+monatliche+Meet-Ups&#038;dates=20240712%2F20261231&#038;location=Polnisches+Institut%2C+Markt+10%2C+04109+Leipzig&#038;details=%23SolidarityWithUkraine%0ASeit+jeher+ist+das+Polnische+Institut+Berlin+%E2%80%93+Filiale+Leipzig+ein+Ort+europ%C3%A4ischer+Begegnungen%2C+seit+ca.+25+Jahren+insbesondere+auch+mit+Polens+Nachbarland+Ukraine.+Davon+zeugen+Ausstellungen%2C+Lesungen%2C+Konzerte+und+Diskussionen.+Besonders+seit+dem+landesweiten+russischen+Angriffskrieg+vom+Februar+2022+ist+das+Institut+verst%C3%A4rkt+Ort+der+Begegnung+mit+ukrainischer+Kultur+und+mit+Ukrainer%2Ainnen+geworden.+Gemeinsam+mit+dem+Freundeskreis+der+Ukraine+in+Leipzig+%C3%B6ffnet+es+seit+Juli+2024+seine+R%C3%A4ume+f%C3%BCr+monatliche+Treffen%2C+bei+denen+die+Ukraine+im+Mittelpunkt+steht+%E2%80%93+mit+Gespr%C3%A4chsrunden%2C+Autor%2Ainnenabenden%2C+Filmvorf%C3%BChrungen%2C+Konzerten+und+vielem+mehr.+Sie+bieten+die+Gelegenheit%2C+im+Kreise+Gleichgesinnter+zu+sein+und+diesen+Kreis+zu+erweitern.%0A%D0%94%D0%BE%D1%80%D0%BE%D0%B3%D1%96+%D0%94%D1%80%D1%83%D0%B7%D1%96+%D0%A3%D0%BA%D1%80%D0%B0%D1%97%D0%BD%D0%B8%21%0A%D0%90%D0%B3%D1%80%D0%B5%D1%81%D0%B8%D0%B2%D0%BD%D0%B0+%D0%B2%D1%96%D0%B9%D0%BD%D0%B0+%D1%80%D0%BE%D1%81%D1%96%D1%97+%D0%BF%D1%80%D0%BE%D1%82%D0%B8+%D0%A3%D0%BA%D1%80%D0%B0%D1%97%D0%BD%D0%B8+%D1%82%D1%80%D0%B8%D0%B2%D0%B0%D1%94+%D0%B2%D0%B6%D0%B5+12%D0%B9+%D1%80%D1%96%D0%BA%2C+%D1%82%D0%B0+%D0%B2%D0%B6%D0%B5+%D1%87%D0%BE%D1%82%D0%B8%D1%80%D0%B8+%D1%80%D0%BE%D0%BA%D0%B8+%D1%82%D1%80%D0%B8%D0%B2%D0%B0%D1%94+%D0%BF%D0%BE%D0%B2%D0%BD%D0%BE%D0%BC%D0%B0%D1%81%D1%88%D1%82%D0%B0%D0%B1%D0%BD%D0%B5+%D0%B2%D1%82%D0%BE%D1%80%D0%B3%D0%BD%D0%B5%D0%BD%D0%BD%D1%8F.+%D0%9F%D1%80%D0%BE%D1%82%D1%8F%D0%B3%D0%BE%D0%BC+%D1%86%D1%8C%D0%BE%D0%B3%D0%BE+%D1%87%D0%B0%D1%81%D1%83+%D1%82%D0%B2%D0%BE%D1%80%D0%B8%D1%82%D1%8C%D1%81%D1%8F+%D1%96%D1%81%D1%82%D0%BE%D1%80%D1%96%D1%8F%2C+%D0%BF%D0%BE%D1%88%D0%B8%D1%80%D1%8E%D0%B2%D0%B0%D1%82%D0%B8+%D1%8F%D0%BA%D1%83+%D1%94+%D0%BD%D0%B5+%D1%82%D1%96%D0%BB%D1%8C%D0%BA%D0%B8+%D0%BD%D0%B0%D1%88%D0%BE%D1%8E+%D0%BF%D1%80%D0%B8%D0%B2%D1%96%D0%BB%D0%B5%D1%94%D1%8E%2C+%D1%8F%D0%BA+%D0%B6%D0%B8%D1%82%D0%B5%D0%BB%D1%96%D0%B2+%D0%84%D0%B2%D1%80%D0%BE%D0%B5%D0%B9%D1%81%D1%8C%D0%BE%D0%B3%D0%BE+%D0%A1%D0%BE%D1%8E%D0%B7%D1%83+%D1%82%D0%B0+%D0%B2%D1%96%D0%BB%D1%8C%D0%BD%D0%BE%D0%B3%D0%BE+%D1%81%D0%B2%D1%96%D1%82%D1%83%2C+%D0%B0%D0%BB%D0%B5+%D1%96+%D1%82%D0%B0%D0%BA%D0%BE%D0%B6+%D0%BD%D0%B0%D1%88%D0%B8%D0%BC+%D0%BE%D0%B1%D0%BE%D0%B2%E2%80%99%D1%8F%D0%B7%D0%BA%D0%BE%D0%BC.+%D0%9D%D1%96%D1%85%D1%82%D0%BE.+%D0%9D%D0%B5+%D0%BC%D0%B0%D1%94.+%D0%97%D0%B0%D0%B1%D1%83%D1%82%D0%B8.%D0%A1%D0%B0%D0%BC%D0%B5+%D1%82%D0%BE%D0%BC%D1%83+der+Freundeskreis+der+Ukraine+in+Leipzig+%D0%BF%D0%BE%D1%87%D0%B8%D0%BD%D0%B0%D1%94+%D1%80%D0%B5%D0%B3%D1%83%D0%BB%D1%8F%D1%80%D0%BD%D1%96+%D1%89%D0%BE%D0%BC%D1%96%D1%81%D1%8F%D1%87%D0%BD%D1%96+%D0%B7%D1%83c%D1%82%D1%80%D1%96%D1%87%D1%96%2C+%D0%B4%D0%B5+%D0%BC%D0%B8+%D1%83%D1%81%D1%96%2C+%D0%B7%D0%BC%D0%BE%D0%B6%D0%B5%D0%BC%D0%BE+%D0%BE%D0%B1%D0%B3%D0%BE%D0%B2%D0%BE%D1%80%D0%B8%D1%82%D0%B8+%D0%BF%D0%BE%D0%BB%D1%96%D1%82%D0%B8%D1%87%D0%BD%D1%83+%D1%81%D0%B8%D1%82%D1%83%D0%B0%D1%86%D1%96%D1%8E%2C+%D0%BF%D1%96%D0%B7%D0%BD%D0%B0%D1%82%D0%B8+%D0%B1%D1%96%D0%BB%D1%8C%D1%88%D0%B5+%D0%BF%D1%80%D0%BE+%D1%96%D1%81%D1%82%D0%BE%D1%80%D1%96%D1%8E+%D1%82%D0%B0+%D0%BA%D1%83%D0%BB%D1%8C%D1%82%D1%83%D1%80%D1%83+%D0%A3%D0%BA%D1%80%D0%B0%D1%97%D0%BD%D0%B8%2C+%D0%B7%D0%B1%D0%B8%D1%80%D0%B0%D1%82%D0%B8+%D0%BF%D0%BE%D0%B6%D0%B5%D1%80%D1%82%D0%B2%D0%B8%2C+%D0%BE%D0%BF%D0%B8%D0%BD%D0%B8%D1%82%D0%B8%D1%81%D1%8F+%D0%B2+%D0%BA%D0%BE%D0%BB%D1%96+%D0%BE%D0%B4%D0%BD%D0%BE%D0%B4%D1%83%D0%BC%D1%86%D1%96%D0%B2%2C+%D1%82%D0%B0+%D1%80%D0%BE%D0%B7%D1%88%D0%B8%D1%80%D1%8E%D0%B2%D0%B0%D1%82%D0%B8+%D1%86%D0%B5+%D0%BA%D0%BE%D0%BB%D0%BE%21%0A%D0%A3%D1%81%D1%96%D1%85+%D1%89%D0%B8%D1%80%D0%BE+%D0%B7%D0%B0%D0%BF%D1%80%D0%BE%D1%88%D1%83%D1%94%D0%BC%D0%BE%21%D0%A1%D0%BB%D0%B0%D0%B2%D0%B0+%D0%A3%D0%BA%D1%80%D0%B0%D1%97%D0%BD%D1%96%21%0A%2A%2A%2A%0ALiebe+Freund%2Ainnen+der+Ukraine%21%0ADer+aggressive+und+b%C3%B6se+Krieg+Russlands+gegen+die+Ukraine+dauert+bereits+das+zw%C3%B6lfte+Jahr+und+die+Gro%C3%9Fe+Invasion+dauert+seit+vier+Jahren+an.+In+diesem+Zeitraum+wird+Geschichte+geschrieben+und+die+Verbreitung+dieser+Geschichte+ist+nicht+nur+unser+Vorrecht+als+Einwohner+der+Europ%C3%A4ischen+Union+und+der+freien+Welt%2C+sondern+auch+unsere+Pflicht.Niemand+darf+vergessen%21Deswegen+startet+der+Freundeskreis+der+Ukraine+in+Leipzig+regelm%C3%A4%C3%9Fige+monatliche+Meetups.+Bei+diesen+Treffen+wird+die+politische+Situation+besprochen%2C+Interessantes+%C3%BCber+die+Geschichte+und+Kultur+der+Ukraine+vermittelt+und+Spenden+gesammelt.+Sie+bieten+die+Gelegenheit%2C+im+Kreise+Gleichgesinnter+zu+sein+und+diesen+Kreis+weiter+zu+erweitern.%0AAlle+sind+herzlich+eingeladen%21Slava+Ukraini%21%0AVeranstalter%3A+Freundeskreis+Ukraine+in+Leipzig+mit+Unterst%C3%BCtzung+des+Polnischen+Instituts+Berlin+%E2%80%93+Filiale+Leipzig%0AInfo%3A+freundeskreisukrleipzig.wordpress.comEintritt%3A+freiOrt%3A+Polnisches+Institut%2C+Markt+10%2C+04109+Leipzig%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2024%2F12%2F31%2Fcafe-ukraina-monatliche-meet-ups%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/12122.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Andere <\/span>\t\t\t\t\t<span  class=\"event_category\">Diskussion <\/span>\t\t\t\t\t<span  class=\"event_category\">Film <\/span>\t\t\t\t\t<span  class=\"event_category\">Literatur <\/span>\t\t\t\t\t<span  class=\"event_category\">Musik <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"12122\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nPolnisches Institut, Markt 10, 04109 Leipzig\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch category-Film post_tag-Film category-Programm\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/12\/31\/andrzej-wajda-jahr-2026\/\"><h5>Andrzej-Wajda-Jahr 2026 <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"czwartek 1 stycznia 2026\" data-end=\"czwartek 31 grudnia 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-01-01T00:00:00+00:00\">1 stycznia 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-12-31T00:00:00+00:00\">31 grudnia 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/17298.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Andrzej-Wajda-Jahr+2026&#038;dates=20260101%2F20261231&#038;location=weltweit&#038;details=Am+6.+M%C3%A4rz+2026+w%C3%A4re+Andrzej+Wajda+100+Jahre+alt+geworden.+Aus+diesem+Anlass+hat+der+Senat+der+Republik+Polen+am+14.+Mai+2025+das+Jahr+2026+offiziell+als+%E2%80%9EAndrzej-Wajda-Jahr%E2%80%9C+ausgerufen.+Im+Programm+des+Polnischen+Instituts+sind+Wajdas+Filme+Dauerg%C3%A4ste+-+im+Rahmen+des+Festivals+filmPOLSKA+ebenso+wie+in+Einzelvorstellungen%2C+in+der+Retrospektive+%E2%80%9EMeister+der+Regie%E2%80%9C+in+den+Technischen+Sammlungen+Dresden+%282017%29+oder+in+den+Vortr%C3%A4gen+%E2%80%9EWajda+und+die+anderen%E2%80%9C+%282016+in+S%C5%82ubice%29+und+%E2%80%9EWajda+und+seine+Erben%E2%80%9C+%282022+in+Halle%2FSaale%29.%0A%C3%9Cber+Andrzej+Wajda%0A%5Bcaption+id%3D%22attachment_17337%22+align%3D%22alignleft%22+width%3D%22200%22%5D+Andrzej+Wajda+2016+in+Gdynia%2C+drei+Wochen+vor+seinem+Tod%5B%2Fcaption%5D%0AWajda+wurde+am+6.+M%C3%A4rz+1926+in+Suwa%C5%82ki+geboren%2C+wo+er+auch+seine+Kindheit+und+fr%C3%BChe+Jugend+verlebte.+Die+Kriegsjahre+verbrachte+er+in+Radom%2C+wo+sein+Vater+Jakub+Wajda+%E2%80%93+Berufsoffizier+der+polnischen+Armee+%E2%80%93+stationiert+war.+In+Radom+besuchte+er+als+Teenager+geheime+Kurse+und+lernte+kurzzeitig+an+einer+privaten+Malereischule%2C+w%C3%A4hrend+er+gleichzeitig+als+Lagerist%2C+Tr%C3%A4ger%2C+K%C3%BCfer%2C+Schlosser+und+Zeichner+im+Eisenbahnb%C3%BCro+arbeitete.%0ANach+dem+Zweiten+Weltkrieg+studierte+Wajda+1946%E2%80%931950+Malerei+an+der+Akademie+der+Bildenden+K%C3%BCnste+in+Krak%C3%B3w+und+anschlie%C3%9Fend+Regie+an+der+neu+gegr%C3%BCndeten+Filmhochschule+in+%C5%81%C3%B3d%C5%BA.+1955+begann+er+mit+seinem+Kinodeb%C3%BCt+%E2%80%9EPokolenie%E2%80%9D+%28Eine+Generation%29%2C+nach+einem+Weg+zu+suchen%2C+um+eines+seiner+wichtigsten+k%C3%BCnstlerischen+und+ethischen+Ziele+zu+verwirklichen+%E2%80%93+f%C3%BCr+diejenigen+zu+sprechen%2C+welche+den+Zweiten+Weltkrieg+nicht+%C3%BCberlebt+hatten.+Seine+n%C3%A4chsten+Filme+%E2%80%9EKana%C5%82%E2%80%9C+%28Der+Kanal%29+und+%E2%80%9EPopi%C3%B3%C5%82+i+diament%E2%80%9C+%28Asche+und+Diamant%2C+nach+einem+Roman+von+Jerzy+Andrzejewski%29+machten+den+damals+32-j%C3%A4hrigen+K%C3%BCnstler+zu+einem+der+wichtigsten+Regisseure+der+jungen+Generation+in+Europa+und+begr%C3%BCndeten+eine+%E2%80%9Epolnische+Filmschule%E2%80%9C+genannte+Str%C3%B6mung%2C+welche+die+polnische+martyrologische+Tradition+und+und+den+romantischen+Heroismus+in+Frage+stellte.%0AIn+%C3%BCber+60+Jahren+vielseitiger+kreativer+T%C3%A4tigkeit%2C+die+auch+Dokumentarfilme%2C+Fernsehproduktionen%2C+Theaterst%C3%BCcke%2C+Zeichnungen%2C+Gem%C3%A4lde+und+Drehb%C3%BCcher+hervorbrachte%2C+drehte+Wajda+%C3%BCber+40+Langspielfilme.+Viele+davon+werden+heute+zu+den+Meilensteinen+des+polnischen+und+internationalen+Kinos+gez%C3%A4hlt.+Von+der+internationalen+Filmwelt+gesch%C3%A4tzt%2C+wurde+Wajda+betitelt+als+%E2%80%9ES%C3%A4nger+der+schwierigen+polnischen+Geschichte%2C+der+ihr+eine+universelle+Dimension+zu+verleihen+wusste%E2%80%9C%2C+als+%E2%80%9EFilmpoet+verlorener+Dinge%E2%80%9C%2C+als+%E2%80%9Ewichtigster+Filmregisseur+Polens+der+Nachkriegszeit%E2%80%9C%2C+als+%E2%80%9EChronist+seines+Landes%2C+moralische+Instanz%2C+Gesellschaftskritiker+mit+der+Kamera%E2%80%9C+oder+als+%E2%80%9Eeiner+der+gro%C3%9Fen+Regisseure+der+Welt%2C+dank+denen+das+20.+Jahrhundert+zu+einem+gro%C3%9Fen+Jahrhundert+des+Kinos+wurde%E2%80%9C.%0AWajda+gilt+als+Regisseur%2C+der+mit+seinen+Filmen+in+die+polnische+Geschichte+eingreifen+wollte%2C+indem+er+Asche%2C+Verbitterung+und+historische+Qualen+in+Filme+verwandelte%2C+die+wie+Diamanten+gl%C3%A4nzten+%E2%80%93+und+als+ein+K%C3%BCnstler%2C+der+sich+bis+zum+Ende+f%C3%BCr+Freiheit+und+Demokratie+in+Polen+engagierte.%0AInhalt%0A1+%2F+Filmregisseur2+%2F+Theaterregisseur3+%2F+B%C3%BCrger4+%2F+Lehrer5+%2F+Preistr%C3%A4ger6+%2F+Filmografie%0A%C2%A0%0A%C2%A0%0A%C2%A0%0A%C2%A0%0A1+%2F+FILMREGISSEUR%0ANach+dem+Abschluss+eines+Studiums+an+der+Filmhochschule+in+%C5%81%C3%B3d%C5%BA+arbeitete+Andrzej+Wajda+bei+Alexander+Ford+an+dessen+Filmen+%E2%80%9EChopins+Jugend%E2%80%9C+%281952%29+und+%E2%80%9EDie+F%C3%BCnf+aus+der+Barskastra%C3%9Fe%E2%80%9C+%281954%29+mit.%0ASeine+Laufbahn+als+Regisseur+begann+er+in+der+%C3%84ra+des+sog.+sozialistischen+Realismus%2C+widersetzte+sich+jedoch+dessen+Leitlinien.+Stattdessen+verhandelte+er+in+seinen+ersten+drei+Filmen+bewegende+und+ethisch+komplexe+Themen.+Seine+Trilogie+zeigte+das+Drama+junger+Menschen%2C+die+vom+Krieg+gezeichnet+und+in+ein+neues+System+hineingeworfen+wurden%2C+welches+sie+auseinander+treibt+und+vor+ungewollte+Herausforderungen+stellt%2C+die+vielleicht+noch+schwieriger+sind+als+der+%C3%9Cberlebenskampf.+%E2%80%9EEine+Generation%E2%80%9C+%281955%29%2C+%E2%80%9EDer+Kanal%E2%80%9C+%281957%29+und+%E2%80%9EAsche+und+Diamant%E2%80%9C+%281958%29%2C+beschrieben+die+Qualen+und+Spaltungen+Polens+im+Zweiten+Weltkrieg+sowie+der+Nachkriegszeit+und+brachten+Wajda+internationale+Anerkennung.+Bereits+in+seinen+ersten+Filmen+erwies+sich+der+Regisseur+als+K%C3%BCnstler%2C+der+die+Realit%C3%A4t+genau+beobachtete+und+die+Zeit+mit+ihren+Widerspr%C3%BCchen+und+Herausforderungen+einfing+%E2%80%93+als+ein+Sch%C3%B6pfer%2C+der+sehr+sensibel+f%C3%BCr+Form+und+Symbolik+war+und+einen+originellen+Filmstil+entwickelte.%0AWajda+kehrte+immer+wieder+zum+Thema+%E2%80%9EKrieg%E2%80%9C+zur%C3%BCck%2C+welches+seine+Generation+tief+gepr%C3%A4gt+hatte+%E2%80%93+in+%E2%80%9ELotna%E2%80%9C+%281959%29%2C+%E2%80%9ESamson%E2%80%9C+%281961%29%2C+%E2%80%9ELandschaft+nach+der+Schlacht%E2%80%9C+%281970%29%2C+%E2%80%9ELiebe+zwischen+den+Fronten%E2%80%9C+%281993%29%2C+%E2%80%9EKorczak%E2%80%9C+%281990%29%2C+%E2%80%9EDie+Karwoche%E2%80%9C+%281995%29+und+%E2%80%9EDas+Masaker+von+Katyn%E2%80%9C+%282007%29.+Der+letztgenannte+Titel+war+auch+eine+R%C3%BCckkehr+zu+einem+pers%C3%B6nlichen+Trauma%2C+mit+dem+Wajda+sein+ganzes+Leben+lang+gerungen+hatte+%E2%80%93+in+Katyn+war+der+Vater+des+Regisseurs+ermordet+worden.+In+seinem+Drang%2C+vergangene+Ereignisse+zu+beschreiben%2C+ihre+tragische+Erinnerung+zu+bewahren+und+Figuren+dem+Vergessen+zu+entrei%C3%9Fen%2C+war+Wajda+%E2%80%93+mit+seinem+Imperativ%2C+den+Verstorbenen+Gerechtigkeit+widerfahren+zu+lassen+%E2%80%93+ein+Geistesverwandter+Maria+Janions%2C+der+Autorin+des+Buchs+%E2%80%9EDo+Europy+tak%2C+ale+z+naszymi+umar%C5%82ymi%E2%80%9C+%28Ja+nach+Europa%2C+aber+mit+unseren+Toten%29.%0AEin+eigenes+Kapitel+in+Andrzej+Wajdas+Schaffen+bilden+seine+Literaturverfilmungen+%E2%80%93+vision%C3%A4re+Adaptionen+unter+anderem+von+Stefan+%C5%BBeromskis+%E2%80%9EZwischen+Feuer+und+Asche%E2%80%9C+%281965%29%2C+Jaros%C5%82aw+Iwaszkiewiczs+%E2%80%9EDas+Birkenw%C3%A4ldchen%E2%80%9C+%281970%29+und+%E2%80%9EDie+M%C3%A4dchen+von+Wilko%E2%80%9C+%281979%29%2C+%E2%80%9EDie+Hochzeit%E2%80%9C+%281973%29+von+Stanis%C5%82aw+Wyspia%C5%84ski%2C+das+als+Meisterwerk+des+Weltkinos+gefeierte+Epos+%E2%80%9EDas+gelobte+Land%E2%80%9C+%281975%29+nach+einem+Roman+von+Stanis%C5%82aw+Reymont%2C+die+Klassiker+%E2%80%9EDie+Rache%E2%80%9C+%282002%29+nach+Aleksander+Fredro+und+%E2%80%9EPan+Tadeusz%E2%80%9C+%281999%29+nach+Adam+Mickiewicz%2C+der+in+Frankreich+gedrehte+%E2%80%9EDanton%E2%80%9C+%281983%29+nach+einem+Drama+von+Stanis%C5%82awa+Przybyszewska+und+die+Joseph-Conrad-Verfilmung+%E2%80%9EDie+Schattenlinie%E2%80%9C+%281976%29.+Durch+seine+Besch%C3%A4ftigung+mit+Literaturklassikern+pr%C3%A4gte+Wajda+im+Laufe+seiner+gesamten+Karriere+das+Bild+Polens+in+der+Vorstellung+und+kollektiven+Identit%C3%A4t+seiner+Landsleute+%E2%80%93+mit+all+seinen+Klassenunterschieden%2C+seinen+Archetypen+und+Symbolen+sowie+seiner+immer+noch+pr%C3%A4senten%2C+von+nationalen+D%C3%A4monen+gepr%C3%A4gte+Vergangenheit.+In+Zeiten+versch%C3%A4rfter+Zensur+w%C3%A4hlte+Wajda+literarische+Texte+als+Vorlagen%2C+um+Polen+weiterhin+auf+eindringliche+und+kritische+Weise+thematisieren+zu+k%C3%B6nnen.+Mit+jeder+dieser+kritischen+Reflexionen+der+Vergangenheit+war+f%C3%BCr+ihn+aber+auch+die+Aufforderung+verbunden%2C+in+die+Zukunft+zu+schauen%2C+nationale+Schemata+zu+durchbrechen+und+Verantwortung+%C3%BCbernehmen.%C2%A0%0AAndrzej+Wajda+begleitete+mit+seinen+Filmen+ebenso+die+polnische+Zeitgeschichte+%E2%80%93+mehr+noch%2C+die+Filme+selbst+spielten+eine+wichtige+Rolle+bei+den+politischen+Umw%C3%A4lzungen+der+70er-+und+80er-Jahre.+Seine+Arbeiten+%E2%80%9EDer+Mann+aus+Marmor%E2%80%9C+%281977%29%2C+%E2%80%9EDer+Mann+aus+Eisen%E2%80%9C+%281981%29+und+%E2%80%9EWa%C5%82%C4%99sa+%E2%80%93+Der+Mann+der+Hoffnung%E2%80%9C+%282013%29%2C+die+%E2%80%93+wie+der+Regisseur+einr%C3%A4umte+%E2%80%93+teilweise+%E2%80%9Eim+Auftrag%E2%80%9D+der+am+Solidarno%C5%9B%C4%87-Aufstand+beteiligten+Arbeiter+gedreht+worden+waren+und+von+der+westlichen+Presse+als+%E2%80%9ECitizen+Kane+des+Ostblocks%E2%80%9D+bezeichnet+wurden%2C+portr%C3%A4tierten+die+Gewerkschaften+als+eine+Bewegung+des+Widerstands+gegen+die+Regierung+und+des+romantischen+Patriotismus.+In+%E2%80%9EOhne+Bet%C3%A4ubung%E2%80%9C+%281978%29+%E2%80%93+einem+der+bedeutendsten+Werke+des+sog.+%E2%80%9EKinos+der+moralischen+Unruhe%E2%80%9C+%E2%80%93+machte+Wajda+auf+staatliche+Mechanismen+zur+Zerst%C3%B6rung+au%C3%9Fergew%C3%B6hnlicher+Individuen+aufmerksam.+Zu+diesem+Thema+kehrte+er+in+seinem+letzten+Werk+%E2%80%9EAfterimages%E2%80%9C+%282016%29+noch+einmal+zur%C3%BCck%2C+das+zu+einem+von+Sorge+um+die+politische+Zukunft+Polens+gepr%C3%A4gten+Verm%C3%A4chtnis+des+Regisseurs+wurde.%0AEine+eigene+Kategorie+in+Wajdas+Schaffen+bilden+pers%C3%B6nliche%2C+subjektiv+gepr%C3%A4gte+Filme.+Sie+setzten+sich+zusammen+aus+Fragmenten+genial+beobachteter+Realit%C3%A4t%2C+Emotionen+und+dem+Versuch%2C+dem+Unaussprechlichen+Form+zu+verleihen.+Wajda+webte+seine+Sprache+und+filmische+Empfindsamkeit+aus+Erinnerungen+an+einst+gesehene+Bilder%2C+Lichtfragmenten%2C+ungew%C3%B6hnlichen+Landschaften+und+abgelauschten+Dialogen+sowie+%C3%BCberraschend+treffenden+Metaphern.+Wie+kein+anderer+konnte+er+vom+Prozess+des+Abschiednehmens+erz%C3%A4hlen+%28%E2%80%9EDer+Kalmus%E2%80%9C+2009%29+oder+von+den+Versuchen%2C+sich+mit+einer+pl%C3%B6tzlichen+Abwesenheit+zu+arrangieren+und+mit+einem+Leben%2C+das+seine+Substanz+in+einen+leeren%2C+scheinbar+unf%C3%BCllbaren+Raum+gie%C3%9Ft+%28%E2%80%9EAlles+zu+verkaufen%E2%80%9C+1968%29.+Als+Werke%2C+welche+vom+Geist+eines+gesellschaftlichen+Umbruchs+und+von+einer+fieberhaften+Suche+nach+sich+selbst+in+dieser+neuen+Realit%C3%A4t+erz%C3%A4hlen%2C+sind+Filme+wie+%E2%80%9EDie+unschuldigen+Zauberer%E2%80%9C+%281960%29+oder+%E2%80%9EFliegenjagd%E2%80%9C+%281969%29+in+Erinnerung+geblieben.%0A2+%2F+THEATERREGISSEUR%0AIm+Theater+machte+sich+Andrzej+Wajda+als+versierter+und+aufmerksamer+Interpret+von+Dostojewski%2C+Wyspia%C5%84ski+und+Shakespeare+einen+Namen.+Sein+B%C3%BChnenwerk+mit+fast+50+Inszenierungen+pr%C3%A4gte+die+Geschichte+des+polnischen+Theaters.%0AWajda+arbeitete+h%C3%A4ufig+zwischen+den+Dreharbeiten+zu+seinen+Filmen+f%C3%BCr+das+Theater.+Seine+Begegnungen+mit+B%C3%BChnen-Schauspieler%2Ainnen+f%C3%BChrten+gelegentlich+zur+weiteren+Zusammenarbeit+%E2%80%93+diesmal+auf+der+Leinwand%3B+gelegentlich+war+es+auch+umgekehrt.+Seine+erste+B%C3%BChnenproduktion%2C+bei+der+er+instinktiv+beschloss%2C+das+Talent+von+Zbigniew+Cybulski+zu+nutzen%2C+mit+dem+er+kurz+zuvor+am+Set+von+%E2%80%9EAsche+und+Diamant%E2%80%9C+zusammengearbeitet+hatte%2C+war+%E2%80%9EKapelusz+pe%C5%82en+deszczu%E2%80%9C+%28Ein+Hut+voller+Regen%2C+1959%29+im+Teatr+Wybrze%C5%BCe+in+Gda%C5%84sk.+Es+folgten+Inszenierungen+von+%E2%80%9EHamlet%E2%80%9C+%28viermal%29%2C+%E2%80%9EDie+Hochzeit%E2%80%9C%2C+%E2%80%9EDie+D%C3%A4monen%E2%80%9C%2C+%E2%80%9EDanton%E2%80%9C%2C+%E2%80%9ENastasja+Filipowna%E2%80%9C%2C+%E2%80%9ESchuld+und+S%C3%BChne%E2%80%9C%2C+%E2%80%9EDer+Dibbuk%E2%80%9C+und+%E2%80%9EMacbeth%E2%80%9C+%28zweimal%29.+Die+R%C3%BCckkehr+zu+bereits+inszenierten+Werken+war+f%C3%BCr+Wajda+keine+Wiederholung+fr%C3%BCherer+Inszenierungen%2C+sondern+eine+neue+szenische+Lesart%2C+abh%C3%A4ngig+von+Personen+und+Gegebenheiten%2C+neu+aufgegriffen+aus+der+Perspektive+aktueller+Erfahrungen+des+Regisseurs+und+des+Publikums.+Wajda+inszenierte+auch+im+Ausland+%E2%80%93+unter+anderem+in+Stockholm%2C+Weimar%2C+Berlin%2C+Tokio%2C+Moskau%2C+Yale+und+Budapest.%0ADostojewski+betrachtete+er+als+seinen+gr%C3%B6%C3%9Ften+Lehrer+in+den+F%C3%A4chern+Dramatik+und+menschliche+Natur.+Wajda+sagte+%C3%BCber+ihn%3A+%E2%80%9EEr+war+ein+Vision%C3%A4r+und+Prophet+der+schlechten+Nachrichten.+Er+sah+die+Anspannung+der+Sehnen%2C+er+sah+die+dunklen+Seiten+unserer+Pers%C3%B6nlichkeit+und+leider+stellte+sich+heraus%2C+dass+er+mit+seiner+Beurteilung+anderer+Menschen+weitgehend+Recht+hatte.+Raskolnikow+schreibt%2C+bevor+er+die+Alte+mit+einer+Axt+t%C3%B6tet%2C+einen+ganzen+Artikel%2C+in+dem+er+dieses+Verbrechen+gewisserma%C3%9Fen+erkl%C3%A4rt.+Viele+Jahre+sp%C3%A4ter%2C+als+die+ganze+Welt+in+Blut+versank%2C+stellte+sich+heraus%2C+dass+auch+diese+Verbrechen+ideologisch+motiviert+waren%2C+in+Nazi-Deutschland+oder+in+der+Sowjetunion.+Dostojewski+hat+auch+diese+Morde+vorhergesehen.+Verbrechen%2C+die+zuerst+gerechtfertigt+und+dann+begangen+wurden.%E2%80%9C+Andrzej+Wajda+war+vor+allem+mit+Theatern+in+Gda%C5%84sk%2C+Warschau+und+Krak%C3%B3w+verbunden+und+auch+k%C3%BCnstlerischer+Leiter+des+Teatr+Powszechny+in+Warschau.%0A3+%2F+B%C3%9CRGER%0AAndrzej+Wajda+war+gesellschaftlich+au%C3%9Ferordentlich+engagiert+%E2%80%93+nicht+nur+mit+seinen+Filmen%2C+sondern+auch+durch+die+Initiierung+vieler+wichtiger+Veranstaltungen%2C+Traditionen+und+Projekte%2C+welche+die+polnische+Kulturlandschaft+nachhaltig+ver%C3%A4ndert+haben+und+deren+Wirkung+oft+weit+%C3%BCber+die+Grenzen+des+Landes+hinausreichte.%0AIn+der+Volksrepublik+Polen+sammelte+die+Geheimpolizei+%C3%BCber+1.000+Seiten+verschiedener+Materialien+%28Denunziationen%2C+Protokolle+privater+und+%C3%B6ffentlicher+Treffen%2C+Berichte%2C+Empfehlungen+usw.%29+%C3%BCber+den+mit+der+%E2%80%9ESolidarno%C5%9B%C4%87%E2%80%9D+verbundenen+Regisseur.%C2%A0+Aus+ihrem+Register+wurde+Wajda+erst+im+Juli+1989+gestrichen%2C+als+er+bereits+offiziell+Senator+der+Republik+Polen+war%2C+gew%C3%A4hlt+in+den+ersten+freien+Wahlen+seit+Kriegsende.+Die+Film-Trilogie+%E2%80%9EDer+Mann+aus+Marmor%E2%80%9C%2C+%E2%80%9EDer+Mann+aus+Eisen%E2%80%9C+und+%E2%80%9EWa%C5%82%C4%99sa.+Der+Mann+aus+Hoffnung%E2%80%9C+war+eine+Hommage+an+das+Ph%C3%A4nomen+Solidarno%C5%9B%C4%87+und+ihren+Anf%C3%BChrer+Lech+Wa%C5%82%C4%99sa.+Sie+half+der+Welt%2C+dieses+Ph%C3%A4nomen+und+seine+Funktionsweise+zu+verstehen.%0ANachdem+Andrzej+Wajda+1987+den+renommierten+Kyoto-Preis+%E2%80%93+auch+als+%E2%80%9Ejapanischer+Nobelpreis%E2%80%9C+bekannt+%E2%80%93+erhalten+hatte%2C+gr%C3%BCndete+der+f%C3%BCr+seine+Liebe+zur+japanischen+Kunst+bekannte+K%C3%BCnstler+in+Krak%C3%B3w+das+Museum+f%C3%BCr+japanische+Kunst+und+Technik+Manggha.+Es+beherbergt+die+%E2%80%9Eheimatlose%E2%80%9D+Sammlung+japanischer+Kunst+von+Feliks+%E2%80%9EManggha%E2%80%9D+Jasie%C5%84ski+%E2%80%93+einem+Reisenden+und+Sammler%2C+der+seine+Kollektion+1920+der+Stadt+Krak%C3%B3w+schenkte.+Diese+Sammlung+begeisterte+Wajda+als+jungen+Studenten+der+Akademie+der+Bildenden+K%C3%BCnste+in+Krak%C3%B3w.+Es+war+das+erste+Museum+in+Polen+nach+dem+Zweiten+Weltkrieg%2C+dessen+Bau+vollst%C3%A4ndig+aus+privaten+Mitteln+finanziert+wurde%2C+und+ist+heute+der+gr%C3%B6%C3%9Fte+Schatz+der+japanischen+Kultur+in+Mitteleuropa.+Es+umfasst+%C3%BCber+10.000+Exponate+japanischer+Kunst+und+Kunsthandwerks.%0AWajda+initiierte+auch+die+Errichtung+der+Stanis%C5%82aw-Wyspia%C5%84ski-+und+J%C3%B3zef-Czapski-Pavillons+in+Krak%C3%B3w%2C+in+denen+mit+Hilfe+von+Krystyna+Zachwatowicz-Wajdowa+und+dem+Nationalmuseum+Krak%C3%B3w+%E2%80%93+dem+Kuratorium+beider+Einrichtungen+%E2%80%93+Werke+und+Exponate+zusammengestellt+wurden%2C+die+mit+dem+Leben%2C+Schaffen+und+Erbe+dieser+f%C3%BCr+die+polnische+Kultur+bedeutenden+K%C3%BCnstler+in+Verbindung+stehen.%0AAndrzej+Wajda+schob+zahlreiche+weitere+kulturelle+und+museale+Initiativen+an%2C+darunter+das+Zentrum+f%C3%BCr+zeitgen%C3%B6ssische+Kunst+%E2%80%9EElektrownia%E2%80%9C+in+Radom%2C+das+der+Regisseur+gemeinsam+mit+seiner+Frau+unterst%C3%BCtzte%2C+indem+er+dem+Zentrum+viele+wertvolle+Exponate+und+Kunstwerke+aus+seiner+eigenen+Sammlung+schenkte.+Dar%C3%BCber+hinaus+organisierte+er+in+Polen+und+im+Ausland+zahlreiche+Ausstellungen+und+Initiativen+zur+F%C3%B6rderung+polnischer+K%C3%BCnstler+und+ihres+%C5%92uvres.%0AWajda+bekleidete+viele+verantwortungsvolle+und+prestigetr%C3%A4chtige+%C3%84mter+und+widmete+darin+seine+Zeit+dem+Wohl+der+Gesellschaft%2C+mit+der+er+sich+ideell+verbunden+f%C3%BChlte.+Als+Vorsitzender+des+Verbandes+Polnischer+Filmemacher+verhandelte+er+mit+Beh%C3%B6rden+%C3%BCber+neue+Regeln+f%C3%BCr+die+Kinematografie+in+Polen+%E2%80%93+insbesondere+%C3%BCber+Fragen+der+Unabh%C3%A4ngigkeit+der+Filmproduktion+und+der+Einschr%C3%A4nkung+von+Zensur.+Er+war+an+Lech+Wa%C5%82%C4%99sas+Vorbereitungen+auf+die+Wahlkampf-Rededuelle+beteiligt+und+unterst%C3%BCtzte+w%C3%A4hrend+des+Wahlkampfs+vor+den+ersten+freien+Wahlen+1989+die+Kandidaten+der+Opposition+inhaltlich+und+bei+der+Imageberatung.+Bei+diesen+Wahlen+wurde+Wajda+auch+selbst+zum+Senator+gew%C3%A4hlt.+Er+setzte+sich+aktiv+f%C3%BCr+freie+Medien+ein+%E2%80%93+in+seinem+Haus+im+Warschauer+Stadtteil+%C5%BBoliborz+wurde+der+Vertrag+%C3%BCber+die+Gr%C3%BCndung+der+Firma+Agora+unterzeichnet%2C+dem+Herausgeber+der+%E2%80%9EGazeta+Wyborcza%E2%80%9D+%E2%80%93+der+ersten+unabh%C3%A4ngigen+Tageszeitung+im+freien+Polen.+Wajda+war+einer+der+drei+Unterzeichner+des+Vertrags.%0A4+%2F+LEHRER%0AEin+wichtiger+T%C3%A4tigkeitsbereich+von+Andrzej+Wajda+war+die+P%C3%A4dagogik.+In+den+1960er-Jahren+war+er+Dozent+an+der+Fakult%C3%A4t+f%C3%BCr+Regie+der+Staatlichen+Hochschule+f%C3%BCr+Film%2C+Fernsehen+und+Theater+in+%C5%81%C3%B3d%C5%BA.+Er+war+Initiator+und+k%C3%BCnstlerischer+Leiter+des+von+1972+bis+1983+bestehenden+Filmstudios+%E2%80%9EX%E2%80%9D.+2002+gr%C3%BCndete+er+in+Warschau+die+Andrzej-Wajda-Meisterschule+f%C3%BCr+Filmregie%2C+die+bis+heute+erfolgreich+t%C3%A4tig+ist+und+zahlreiche+f%C3%BCr+das+polnische+Kino+bedeutende+Dokumentar-+und+Spielfilmregisseur%2Ainnen+hervorgebracht+hat.+Die+Wajda+School+hat+inzwischen+mehrere+hundert+Kurzfilme+produziert%2C+die+auf+den+gr%C3%B6%C3%9Ften+Filmfestivals+gezeigt+wurden.+Mit+ihrem+offenen%2C+interdisziplin%C3%A4ren+und+kollegialen+Ansatz+%E2%80%93+%C3%A4hnlich+wie+einst+die+Filmstudios+vor+1989+%E2%80%93+erm%C3%B6glicht+sie+es+Kandidat%2Ainnen+mit+vielversprechenden+Leistungen%2C+die+nicht+unbedingt+aus+Filmkreisen+stammen+m%C3%BCssen%2C+ihre+Projekte+umzusetzen+%E2%80%93+unter+Aufsicht+erfahrener+und+angesehener+P%C3%A4dagog%2Ainnen%2C+die+selbst+als+Filmschaffende+t%C3%A4tig+sind.+In+seinem+Testament+%C3%A4u%C3%9Ferte+Andrzej+Wajda+den+Wunsch%2C+dass+aus+den+Tantiemen+seiner+filmischen+Werke+Stipendien+f%C3%BCr+begabte+junge+Menschen+finanziert+werden+sollen.%0A5+%2F+PREISTR%C3%84GER%0AAndrzej+Wajda+wurde+mit+zahlreichen+nationalen+und+internationalen+Preisen+und+Auszeichnungen+geehrt+und+erhielt+Orden+f%C3%BCr+sein+k%C3%BCnstlerisches+Schaffen+ebenso+wie+f%C3%BCr+sein+soziales+Engagement.%0AZu+seinen+wichtigsten+Auszeichnungen+im+Rahmen+mit+seiner+Teilnahme+an+renommierten+Festivals+geh%C3%B6ren+die+Silberne+und+Goldene+Palme+in+Cannes%2C+FIPRESCI-Preise%2C+Goldene+L%C3%B6wen+des+Polnischen+Spielfilmfestivals+in+Gda%C5%84sk%2C+vier+Oscar-Nominierungen+und+ein+Oscar+f%C3%BCr+das+Lebenswerk%2C+C%C3%A9sars%2C+der+Europ%C3%A4ische+Filmpreis+Felix%2C+der+Goldene+L%C3%B6we+der+Internationalen+Filmfestspiele+von+Venedig%2C+die+Platinl%C3%B6wen+des+Polnischen+Spielfilmfestivals+von+Gdynia+f%C3%BCr+das+Lebenswerk%2C+der+Goldene+B%C3%A4r+der+Berlinale%2C+Preise+f%C3%BCr+sein+Lebenswerk+bei+den+Internationalen+Filmfestspielen+von+Sevilla+und+dem+Festival+Plus+Camerimage%2C+der+Preis+des+Polnischen+Filmverbandes+und+die+Goldene+Ente+des+Fachmagazins+%E2%80%9EFilm%E2%80%9C.%0AZu+den+h%C3%B6chsten+staatlichen+Auszeichnungen%2C+die+Wajda+verliehen+wurden%2C+geh%C3%B6ren+unter+anderem+das+Gro%C3%9Fkreuz+des+Ordens+Polonia+Restituta%2C+der+japanische+Orden+der+Aufgehenden+Sonne%2C+der+bulgarische+Kyrill-und-Method-Orden%2C+das+Komturkreuz+des+Verdienstordens+der+Bundesrepublik+Deutschland%2C+das+franz%C3%B6sische+Komturkreuz+der+Ehrenlegion%2C+das+Komturkreuz+des+Ordens+f%C3%BCr+Kunst+und+Literatur+und+Offizierskreuz+der+Ehrenlegion%2C+das+Komturkreuz+mit+Stern+des+Verdienstordens+der+Republik+Ungarn%2C+der+ukrainische+Orden+des+F%C3%BCrsten+Jaroslaw+des+Weisen%2C+die+Goldmedaille+Gloria+Artis%2C+der+Orden+des+Wei%C3%9Fen+Adlers%2C+der+Kyoto-Preis+der+japanischen+Inamori-Stiftung+f%C3%BCr+Verdienste+um+die+Entwicklung+von+Wissenschaft%2C+Technik+und+menschlichem+Denken+und+der+Gro%C3%9Fe+Preis+der+polnischen+Kulturstiftung.+Der+Regisseur+erhielt+au%C3%9Ferdem+Ehrendoktorw%C3%BCrden+zahlreicher+Hochschulen%2C+darunter+der+Kunstakademie+Warschau%2C+der+American+University+in+Washington%2C+der+Staatlichen+Hochschule+f%C3%BCr+Film%2C+Fernsehen+und+Theater+in+%C5%81%C3%B3d%C5%BA%2C+der+Jagiellonen-Universit%C3%A4t+in+Krak%C3%B3w%2C+der+Filmakademie+Moskau%2C+der+Belarusischen+Kunstakademie+und+der+P%C3%A4dagogischen+Universit%C3%A4t+in+Krak%C3%B3w.+Au%C3%9Ferdem+war+er+Ehrenmitglied+der+Franz%C3%B6sischen+Akademie+der+Sch%C3%B6nen+K%C3%BCnste.%0A6+%2F+FILMOGRAFIE%0AAndrzej+Wajda+hat+fast+60+Filme+gedreht+%E2%80%93+Spielfilme%2C+Dokumentarfilme%2C+Kurzfilme+sowie+zahlreiche+Fernsehproduktionen.+Im+Vorwort+zum+Album%2C+das+der+Gesamtausgabe+seiner+Werke+beiliegt+und+dem+Meister+zu+seinem+90.+Geburtstag+feierlich+%C3%BCberreicht+wurde%2C+schrieb+er%3A+%E2%80%9EMeine+Filme+entstanden+%C3%BCber+mehrere+Jahrzehnte+hinweg+in+verschiedenen+Epochen+des+Kinos.+Ich+habe+versucht%2C+an+den+politischen+Ereignissen+nicht+nur+unseres+Landes+teilzunehmen+%E2%80%93+ich+war+in+diesen+Jahren+auch+Teil+der+gesamteurop%C3%A4ischen+Ver%C3%A4nderungen+in+der+Filmkunst.+In+%E2%80%9EAsche+und+Diamant%E2%80%9C+habe+ich+dank+Cybulski+auf+amerikanische+Schauspiel-Vorbilder+zur%C3%BCckgegriffen.+Ich+war+kein+Einzelg%C3%A4nger%2C+deshalb+gab+es+polnische+Filme+weltweit+und+sie+konnten+andere+erreichen%2C+unabh%C3%A4ngig+von+Sprache+und+von+unserer+Vergangenheit%2C+die+auf+der+Leinwand+nicht+leicht+darzustellen+war.+%5B%E2%80%A6%5D+Ich+m%C3%B6chte+den+Menschen%2C+die+solche+Bedingungen+f%C3%BCr+das+polnische+Kino+erk%C3%A4mpft+haben%2C+meinen+Dank+aussprechen.+Unsere+Filmwelt+hat+seit+den+ersten+Nachkriegsjahren+Schritt+f%C3%BCr+Schritt+am+Prozess+der+Erlangung+politischer+und+k%C3%BCnstlerischer+Freiheit+teilgenommen.+Sie+hat+diese+Freiheiten+konsequent+erweitert+%E2%80%93+von+Aleksander+Ford+und+Wanda+Jakubowska+%C3%BCber+Jerzy+Kawalerowicz+und+Jerzy+Bossak+bis+hin+zum+Kampf+um+das+%C3%9Cberleben+des+Kinos+w%C3%A4hrend+des+Kriegszustands+in+den+1980er-Jahren.+Ich+bin+gl%C3%BCcklich%2C+dass+auch+ich+an+diesem+Prozess+teilnehmen+durfte+%E2%80%93+mit+meinen+Filmen+und+meiner+k%C3%BCnstlerischen+Autorit%C3%A4t+als+Regisseur.%E2%80%9C%0A1955+Pokolenie+%2F+Eine+Generation1957+Kana%C5%82+%2F+Der+Kanal1958+Popi%C3%B3%C5%82+i+diament+%2F+Asche+und+Diamant1959+Lotna1960+Niewinni+czarodzieje+%2F+Die+unschuldigen+Zauberer1961+Powiatowa+Lady+Makbet+%2F+Blut+der+Leidenschaft1961+Samson1962+Mi%C5%82o%C5%9B%C4%87+dwudziestolatk%C3%B3w+%2F+Liebe+mit+zwanzig+%2F+L%E2%80%99Amour+%C3%A0+vingt+ans1965+Popio%C5%82y+%2F+Legion%C3%A4re+%7C+Zwischen+Feuer+und+Asche+%2F+The+Ashes1968+Bramy+raju+%2F+Die+Pforten+des+Paradieses1968+Przek%C5%82adaniec+%2F+Rollkuchen1968+Wszystko+na+sprzeda%C5%BC+%2F+Alles+zu+verkaufen1969+Polowanie+na+muchy+%2F+Fliegenjagd1970+Krajobraz+po+bitwie+%2F+Landschaft+nach+der+Schlacht1970+Brzezina+%2F+Das+Birkenw%C3%A4ldchen1972+Pi%C5%82at+i+inni+%2F+Pilatus+und+andere+%E2%80%93+Ein+Film+f%C3%BCr+Karfreitag%C2%A0%2F+Pilate+and+Others1973+Wesele+%2F+Die+Hochzeit%C2%A0%2F+The+Wedding1975+Ziemia+obiecana+%2F+Das+gelobte+Land1976+Smuga+cienia+%2F+Die+Schattenlinie1976+Umar%C5%82a+klasa+%2F+Die+tote+Klasse1977+Cz%C5%82owiek+z+marmuru+%2F+Der+Mann+aus+Marmor1978+Bez+znieczulenia+%2F+Ohne+Bet%C3%A4ubung1979+Panny+z+Wilka+%2F+Die+M%C3%A4dchen+von+Wilko1980+Dyrygent+%2F+Der+Dirigent1981+Cz%C5%82owiek+z+%C5%BCelaza+%2F+Der+Mann+aus+Eisen1983+Danton1983+Mi%C5%82o%C5%9B%C4%87+w+Niemczech+%2F+Eine+Liebe+in+Deutschland1986+Kronika+wypadk%C3%B3w+mi%C5%82osnych+%2F+Chronik+von+Liebesunf%C3%A4llen%C2%A0%2F+A+Chronicle+of+Amorous+Accidents1988+Biesy+%2F+Die+D%C3%A4monen+%2F+Les+Poss%C3%A9d%C3%A9s%C2%A0%2F+The+Posessed1990+Korczak1993+Pier%C5%9Bcionek+z+or%C5%82em+w+koronie+%2F+Liebe+zwischen+den+Fronten1994+Nastazja+%2F+Nastasja1995+Wielki+tydzie%C5%84+%2F+Die+Karwoche1996+Panna+Nikt+%2F+Fr%C3%A4ulein+Niemand%C2%A0%2F+Miss+Nobody1999+Pan+Tadeusz+%2F+Sir+Thaddeus2000+Wyrok+na+Franciszka+Klosa+%2F+Die+Verurteilung+des+Franciszek+K%C5%82os2002+Zemsta%C2%A0%2F+Die+Rache2007+Katy%C5%84+%2F+Das+Massaker+von+Katyn2009+Tatarak+%2F+Der+Kalmus2013+Wa%C5%82%C4%99sa+%E2%80%93+Cz%C5%82owiek+z+nadziei+%2F+Wa%C5%82%C4%99sa.+Der+Mann+aus+Hoffnung2016+Powidoki+%2F+Afterimage%0A%C2%A0%0A%C2%A0%0A%C2%A0%0A%C2%A0%0ATexte%3A+Wajda+Film+Centre%C3%9Cbersetzung+%26amp%3B+Bearbeitung%3A+Rainer+Mende+%28Polnisches+Institut+Berlin+%E2%80%93+Filiale+Leipzig%29%0A%C2%A0%0AInfo%3A+wajda.pisf.pl%2C+https%3A%2F%2Fckf.waw.pl%2Fen%2Fandrzej-wajda-en%2Fbio%0A%C2%A0%0ATitelbild+%C2%A9+Wajda+Film+Centre%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F12%2F31%2Fandrzej-wajda-jahr-2026%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/17298.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Film <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"17298\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nweltweit\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch post_tag-Leipzig category-Musik post_tag-Musik category-Programm\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/09\/03\/nowicki-duo-structures-of-light-le\/\"><h5>Nowicki Duo: Structures of Light <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"tomorrow\" data-end=\"tomorrow\">\n\t\t\t\t\t\t\t<time itemprop=\"dtstart\" datetime=\"2026-09-03T19:30:00+02:00\"><span class=\"date date-single\">tomorrow<\/span> <span class=\"linking_word linking_word-from\">from<\/span> <span class=\"time time-start\">19:30<\/span> <span class=\"linking_word linking_word-to\">to<\/span> <span class=\"time time-end\">21:00<\/span>\n\t\t\t\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19672.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Nowicki+Duo%3A+Structures+of+Light&#038;dates=20260903T193000%2F20260903T210000&#038;location=Polnisches+Institut%2C+Markt+10%2C+04109+Leipzig&#038;details=Besetzung%3APiotr+Nowicki+%28Klavier%29Pawe%C5%82+Nowicki+%28Perkussion%29%0ADas+deutsch-polnische+Konzertprojekt+bringt+Musik+zeitgen%C3%B6ssischer+Komponisten+aus+beiden+L%C3%A4ndern+auf+die+B%C3%BChne.+Auf+dem+Programm+stehen+Kompositionen%2C+die+von+Licht+als+Naturph%C3%A4nomen+inspiriert+wurden.+Dabei+kann+Licht+verschiedenste+Gestaltformen+und+Strukturen+annehmen+und+so+auch+auf+unterschiedlichste+Weise+K%C3%BCnstler+in+ihrem+Schaffen+anregen%3A+im+Kleinen+als+%E2%80%9EFl%C3%A4mmchen%E2%80%9C+einer+Kerze+%28Artur+Kroschel%29%2C+im+Gro%C3%9Fen+als+Faszination+f%C3%BCr+eine+weit+entfernte+%E2%80%9EGalaxis%E2%80%9C+%28Peter+Helmut+Lang%29+oder+als+diffuses+Licht+eines+Kometenschweifs+%28%E2%80%9ECometa%E2%80%9C+von+Dariusz+Przybylski%29.+Ein+neues+Werk+von+Christian+Diemer+wird+dabei+auch+als+Urauff%C3%BChrung+erklingen.%0ADas+auff%C3%BChrende+Nowicki+Duo+aus+Gda%C5%84sk+geh%C3%B6rt+zu+den+renommiertesten+Ensembles+f%C3%BCr+zeitgen%C3%B6ssische+Musik+in+Polen+und+trat+bereits+auf+praktisch+allen+bedeutenden+Neue-Musik-Festivals+Polens+auf.+Die+Br%C3%BCder+arbeiten+seit+den+Neunzigerjahren+zusammen+und+haben+sich+auf+die+Auff%C3%BChrung+von+Kompositionen+f%C3%BCr+Schlaginstrumente+und+Klavier+spezialisiert%2C+wobei+der+Schwerpunkt+auf+Werken+liegt%2C+die+speziell+f%C3%BCr+diese+Besetzung+in+Auftrag+gegeben+wurden.+Zuletzt+erschien+bei+DUX+ihr+Album+%E2%80%9EWorks+for+Nowicki+Duo%E2%80%9C+mit+sieben+Kompositionen+von+Tadeusz+Wielecki%2C+Artur+Kroschel%2C+Maciej+Jab%C5%82o%C5%84ski%2C+Piotr+Peszat%2C+Magdalena+Gorwa%2C+Piotr+J%C4%99drzejczyk+und+Andrzej+Dziadek.%0AProgramm+%28%C3%84nderungen+vorbehalten%29%3A%0AMaciej+Jab%C5%82o%C5%84ski+%28%2A1974%29The+trail+of+night+butterflies+IVf%C3%BCr+Klavier+und+Perkussion+%282021%29%0AArtur+Kroschel+%28%2A1973%29Fl%C3%A4mmchenf%C3%BCr+Klavier+und+Perkussion+%282022%29%0AThomas+St%C3%B6%C3%9F+%28%2A1969%29Impromptuf%C3%BCr+Klavier+solo+%282016%29%0ADariusz+Przybylski+%28%2A1984%29Cometaf%C3%BCr+Perkussion+solo+%282026+%E2%80%93+deutsche+Erstauff%C3%BChrung%29%0AChristian+Diemer+%28%2A1986%29Rouen+1894+%28V%29f%C3%BCr+Klavier+und+Perkussion+%282026+%E2%80%93+Urauff%C3%BChrung%29%0APeter+Helmut+Lang+%28%2A1974%29Galaxisf%C3%BCr+Klavier+und+Perkussion+%282023%29%0AVeranstalter%3A+Atelier+f%C3%BCr+Kultur+und+Zukunft+e.V.+in+Kooperation+mit+dem+Polnischen+Institut+Berlin+%E2%80%93+Filiale+Leipzig%2C+mit+freundlicher+Unterst%C3%BCtzung+der+Kulturstiftung+des+Freistaats+Th%C3%BCringen%2C+JenaKultur+und+der+Stiftung+f%C3%BCr+deutsch-polnische+Zusammenarbeit%2C+Projektpartner%3A+Fundacja+muzyki+nowej+Kwartludium+%28Gda%C5%84sk%29%2C+K%C3%BCnstlerische+Abendschule+Jena+e.V.%2C+S%C3%A4chsischer+Musikbund+e.V.%0AVeranstaltung+auf+FacebookInfo%3A+nowickiduo.com%2C+youtube.com%2F%40Nowicki_DuoEintritt%3A+freiOrt%3A+Polnisches+Institut%2C+Markt+10%2C+04109+Leipzig%0A%C2%A0%0A%C2%A0%0AFoto+%C2%A9+Nowicki+Duo%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F09%2F03%2Fnowicki-duo-structures-of-light-le%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19672.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Musik <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19672\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nPolnisches Institut, Markt 10, 04109 Leipzig\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch post_tag-Leipzig category-Musik post_tag-Musik category-Programm\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/09\/04\/nowicki-duo-structures-of-light-je\/\"><h5>Nowicki Duo: Structures of Light <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"pi\u0105tek 4 wrze\u015bnia 2026\" data-end=\"pi\u0105tek 4 wrze\u015bnia 2026\">\n\t\t\t\t\t\t\t<time itemprop=\"dtstart\" datetime=\"2026-09-04T19:30:00+02:00\"><span class=\"date date-single\">4 wrze\u015bnia 2026<\/span> <span class=\"linking_word linking_word-from\">from<\/span> <span class=\"time time-start\">19:30<\/span> <span class=\"linking_word linking_word-to\">to<\/span> <span class=\"time time-end\">21:00<\/span>\n\t\t\t\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19684.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Nowicki+Duo%3A+Structures+of+Light&#038;dates=20260904T193000%2F20260904T210000&#038;location=K%C3%BCnstlerische+Abendschule%2C+Sophienstr.+18%2C+07743+Jena&#038;details=102.+Atelierkonzert+%E2%80%9EBegegnung+der+K%C3%BCnste%E2%80%9C%0ABesetzung%3APiotr+Nowicki+%28Klavier%29Pawe%C5%82+Nowicki+%28Perkussion%29%0AAusstellung%3A+Katrin+K%C3%B6nig%0ADas+deutsch-polnische+Konzertprojekt+bringt+Musik+zeitgen%C3%B6ssischer+Komponisten+aus+beiden+L%C3%A4ndern+auf+die+B%C3%BChne.+Auf+dem+Programm+stehen+Kompositionen%2C+die+von+Licht+als+Naturph%C3%A4nomen+inspiriert+wurden.+Dabei+kann+Licht+verschiedenste+Gestaltformen+und+Strukturen+annehmen+und+so+auch+auf+unterschiedlichste+Weise+K%C3%BCnstler+in+ihrem+Schaffen+anregen%3A+im+Kleinen+als+%E2%80%9EFl%C3%A4mmchen%E2%80%9C+einer+Kerze+%28Artur+Kroschel%29%2C+im+Gro%C3%9Fen+als+Faszination+f%C3%BCr+eine+weit+entfernte+%E2%80%9EGalaxis%E2%80%9C+%28Peter+Helmut+Lang%29+oder+als+diffuses+Licht+eines+Kometenschweifs+%28%E2%80%9ECometa%E2%80%9C+von+Dariusz+Przybylski%29.+Ein+neues+Werk+von+Christian+Diemer+wird+dabei+auch+als+Urauff%C3%BChrung+erklingen.%0ADas+auff%C3%BChrende+Nowicki-Duo+aus+Gda%C5%84sk+geh%C3%B6rt+zu+den+renommiertesten+Ensembles+f%C3%BCr+zeitgen%C3%B6ssische+Musik+in+Polen+und+trat+bereits+auf+praktisch+allen+bedeutenden+Neue-Musik-Festivals+Polens+auf.+Die+Br%C3%BCder+arbeiten+seit+den+Neunzigerjahren+zusammen+und+haben+sich+auf+die+Auff%C3%BChrung+von+Kompositionen+f%C3%BCr+Schlaginstrumente+und+Klavier+spezialisiert%2C+wobei+der+Schwerpunkt+auf+Werken+liegt%2C+die+speziell+f%C3%BCr+diese+Besetzung+in+Auftrag+gegeben+wurden.+Zuletzt+erschien+bei+DUX+ihr+Album+%E2%80%9EWorks+for+Nowicki+Duo%E2%80%9C+mit+sieben+Kompositionen+von+Tadeusz+Wielecki%2C+Artur+Kroschel%2C+Maciej+Jab%C5%82o%C5%84ski%2C+Piotr+Peszat%2C+Magdalena+Gorwa%2C+Piotr+J%C4%99drzejczyk+und+Andrzej+Dziadek.%0AProgramm+%28%C3%84nderungen+vorbehalten%29%3A%0AMaciej+Jab%C5%82o%C5%84ski+%28%2A1974%29The+trail+of+night+butterflies+IVf%C3%BCr+Klavier+und+Perkussion+%282021%29%0AArtur+Kroschel+%28%2A1973%29Fl%C3%A4mmchenf%C3%BCr+Klavier+und+Perkussion+%282022%29%0AThomas+St%C3%B6%C3%9F+%28%2A1969%29Impromptuf%C3%BCr+Klavier+solo+%282016%29%0ADariusz+Przybylski+%28%2A1984%29Cometaf%C3%BCr+Perkussion+solo+%282026+%E2%80%93+deutsche+Erstauff%C3%BChrung%29%0AChristian+Diemer+%28%2A1986%29Rouen+1894+%28V%29f%C3%BCr+Klavier+und+Perkussion+%282026+%E2%80%93+Urauff%C3%BChrung%29%0APeter+Helmut+Lang+%28%2A1974%29Galaxisf%C3%BCr+Klavier+und+Perkussion+%282023%29%0AVeranstalter%3A+Atelier+f%C3%BCr+Kultur+und+Zukunft+e.V.+in+Kooperation+mit+dem+Polnischen+Institut+Berlin+%E2%80%93+Filiale+Leipzig%2C+mit+freundlicher+Unterst%C3%BCtzung+der+Kulturstiftung+des+Freistaats+Th%C3%BCringen%2C+JenaKultur+und+der+Stiftung+f%C3%BCr+deutsch-polnische+Zusammenarbeit%2C+Projektpartner%3A+Fundacja+muzyki+nowej+Kwartludium+%28Gda%C5%84sk%29%2C+K%C3%BCnstlerische+Abendschule+Jena+e.V.%2C+S%C3%A4chsischer+Musikbund+e.V.%0AInfo%3A+nowickiduo.com%2C+youtube.com%2F%40Nowicki_Duo%2C+abendschule-jena.deKartenreservierung%3A+atelierfuerkultur%40yahoo.comOrt%3A+K%C3%BCnstlerische+Abendschule%2C+Sophienstr.+18%2C+07743+Jena%0A%C2%A0%0A%C2%A0%0AFoto+%C2%A9+Nowicki+Duo%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F09%2F04%2Fnowicki-duo-structures-of-light-je%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19684.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Musik <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19684\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nK\u00fcnstlerische Abendschule, Sophienstr. 18, 07743 Jena\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch post_tag-Leipzig category-Musik post_tag-Musik category-Programm\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/09\/10\/lipinski-quartet-monika-kruk\/\"><h5>Lipi\u0144ski Quartet &amp; Monika Kruk: Mendelssohn Kontexte <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"czwartek 10 wrze\u015bnia 2026\" data-end=\"czwartek 10 wrze\u015bnia 2026\">\n\t\t\t\t\t\t\t<time itemprop=\"dtstart\" datetime=\"2026-09-10T18:00:00+02:00\"><span class=\"date date-single\">10 wrze\u015bnia 2026<\/span> <span class=\"linking_word linking_word-from\">from<\/span> <span class=\"time time-start\">18:00<\/span> <span class=\"linking_word linking_word-to\">to<\/span> <span class=\"time time-end\">20:00<\/span>\n\t\t\t\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19866.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Lipi%C5%84ski+Quartet+%26amp%3B+Monika+Kruk%3A+Mendelssohn+Kontexte&#038;dates=20260910T180000%2F20260910T200000&#038;location=Polnisches+Institut%2C+Markt+10%2C+04109+Leipzig&#038;details=Monika+Kruk+%28Klavier%29%0ALipi%C5%84ski+Quartet%3AKarolina+Podorska+%281.+Geige%29Magdalena+Ziarkowska-Ko%C5%82acka+%282.+Geige%29Agnieszka+%C5%BByniewicz+%28Bratsche%29Marcin+Misiak+%28Violoncello%29%0ADas+Programm+des+Konzerts+zeigt+drei+%C3%A4u%C3%9Ferst+pers%C3%B6nliche+Facetten+der+Kammermusik+des+19.+und+20.+Jahrhunderts.+Obwohl+die+Werke+in+unterschiedlichen+Epochen+und+unter+verschiedenen+Umst%C3%A4nden+entstanden+sind%2C+verbindet+sie+die+Intensit%C3%A4t+der+Emotionen+sowie+die+au%C3%9Fergew%C3%B6hnliche+F%C3%A4higkeit%2C+individuelle+Erfahrungen+in+die+universelle+Sprache+der+Musik+zu+%C3%BCbersetzen.%0ADie+Kombination+dieser+drei+Kompositionen+erz%C3%A4hlt+eine+Geschichte+von+Erinnerung%2C+Verlust+und+der+Kraft+des+menschlichen+Geistes.+Von+Mendelssohn+Bartholdys+romantischer+Elegie+%C3%BCber+Weinbergs+spannungsreiche+und+nachdenkliche+Musik+bis+hin+zu+Laks%E2%80%98+subtiler%2C+von+innerer+Ausgeglichenheit+gepr%C3%A4gter+Sprache+zeigt+das+Programm%2C+wie+pers%C3%B6nliche+Erfahrungen+der+Komponisten+zur+Quelle+von+Werken+mit+zeitloser+Wirkungskraft+werden+k%C3%B6nnen.+Die+kammermusikalische+Besetzung+schr%C3%A4nkt+den+Ausdruck+hier+nicht+ein+%E2%80%93+im+Gegenteil%2C+sie+erm%C3%B6glicht+eine+au%C3%9Fergew%C3%B6hnliche+Aufrichtigkeit.%0AProgramm%3A%0AFelix+Mendelssohn+Bartholdy+%281809%E2%80%931847%29Streichquartett+Nr.+6+f-moll+op.+80%C2%A0%0ASzymon+Laks+%281901%E2%80%931983%29Klavierquintett%0AMieczys%C5%82aw+Weinberg+%281919%E2%80%931996%29Streichtrio%0ADen+Auftakt+des+Abends+bildet+das+6.+Streichquartett+in+f-Moll+op.+80+von+Felix+Mendelssohn+Bartholdy+%E2%80%93+das+letzte+vollendete+Kammermusikwerk+des+Komponisten.+Es+entstand+1847%2C+kurz+nach+dem+pl%C3%B6tzlichen+Tod+seiner+geliebten+Schwester+Fanny%2C+die+f%C3%BCr+Mendelssohn+Bartholdy+nicht+nur+seine+engste+Vertraute%2C+sondern+auch+eine+herausragende+Pianistin+und+Komponistin+war.+Im+Gegensatz+zu+den+fr%C3%BCheren+Quartetten+des+Komponisten+strahlt+das+Quartett+op.+80+Dramatik%2C+Unruhe+und+heftige+Kontraste+aus.+Es+ist+eine+musikalische+Aufzeichnung+von+Trauer%2C+Schmerz+und+innerer+Zerrissenheit%2C+die+als+eines+der+ergreifendsten+Werke+im+Schaffen+des+Komponisten+gilt.%0ADas+Schaffen+von+Mieczys%C5%82aw+Wejnberg%2C+einem+der+herausragendsten+Komponisten+des+20.+Jahrhunderts%2C+nimmt+%C2%A0erst+in+den+letzten+Jahrzehnten+den+ihm+geb%C3%BChrenden+Platz+im+weltweiten+Repertoire+ein.+In+Weinbergs+Musik+verflechten+sich+Einfl%C3%BCsse+der+j%C3%BCdischen%2C+russischen+und+mitteleurop%C3%A4ischen+Tradition%2C+und+seine+pers%C3%B6nlichen+Erfahrungen+mit+Krieg%2C+Emigration+und+dem+Verlust+seiner+Liebsten+spiegeln+sich+in+der+tiefen+Ausdruckskraft+seiner+Werke+wider.+Sein+Streichtrio+besticht+durch+seine+meisterhafte+Komposition%2C+seinen+reichhaltigen+Klang+sowie+seine+au%C3%9Fergew%C3%B6hnliche+Ausdruckskraft+und+f%C3%BChrt+die+Zuh%C3%B6rer%2Ainnen+von+Momenten+intimer+Besinnung+hin+zu+dramatisch+spannungsgeladenen+H%C3%B6hepunkten.%0ADen+Abschluss+des+Konzerts+bildet+das+Klavierquintett+von+Szymon+Laks+%E2%80%93+einem+Komponisten%2C+Dirigenten+und+Schriftsteller%2C+dessen+Leben+von+den+Erfahrungen+des+Zweiten+Weltkriegs+und+seiner+Zeit+im+Konzentrationslager+Auschwitz+gepr%C3%A4gt+wurde.+Obwohl+sich+sein+Schaffen+nicht+direkt+auf+seine+Kriegserlebnisse+bezieht%2C+zeichnet+es+sich+durch+eine+au%C3%9Fergew%C3%B6hnliche+Klarheit+der+Form+sowie+eine+subtile+Verbindung+der+franz%C3%B6sischen+Tradition+mit+polnischer+melodischer+Sensibilit%C3%A4t+aus.+Sein+Klavierquintett+ist+ein+Beispiel+f%C3%BCr+Laks%E2%80%98+reifen+Stil+%E2%80%93+voller+Lyrik%2C+rhythmischer+Energie+und+raffinierter+kammermusikalischer+Erz%C3%A4hlkunst%2C+in+der+jedes+Instrument+seine+eigene%2C+individuelle+Stimme+beh%C3%A4lt.%0ADas+Lipi%C5%84ski+Quartet+ist+ein+Streichquartett%2C+das+der+Musikakademie+in+Wroc%C5%82aw+verbunden+ist%2C+deren+Namenspatron+Karol+Lipi%C5%84ski+ist+%E2%80%93+ein+herausragender+polnischer+Geiger%2C+Komponist+und+Kammermusiker+des+19.+Jahrhunderts%2C+der+lange+Zeit+in+Dresden+wirkte.+Robert+Schumann+widmete+ihm+das+Werk+%E2%80%9ECarneval%E2%80%9C%2C+Niccolo+Paganni+w%C3%BCrdigte+Lipi%C5%84ski+als+%E2%80%9Ezweitbesten+Geiger+der+Welt%E2%80%9C.%0ADie+Musiker%2Ainnen+des+Lipi%C5%84ski+Quartet+verbindet+die+Leidenschaft+f%C3%BCr+die+Auff%C3%BChrung+von+Kammermusik%2C+aber+auch+eine+rege+Solist%2Ainnen-+und+Lehrt%C3%A4tigkeit.+Sie+sind+Preistr%C3%A4ger%2Ainnen+renommierter+Wettbewerbe+und+nehmen+aktiv+an+zahlreichen+internationalen+Festivals+teil%2C+darunter+das+Edinburgh+International+Festival%2C+der+Warschauer+Herbst%2C+die+%E2%80%9EVerr%C3%BCckten+Tage+der+Musik%E2%80%9C%2C+das+Vevey+Spring+Classic%2C+das+Felix-Mendelssohn-Kammermusikfestival+in+Duszniki+sowie+Wratislavia+Cantans.+Die+Musiker%2Ainnen+sind+zudem+im+renommierten+Ensemble+NFM+Orkiestra+Leopoldinum+vereint%2C+das+in+einer+der+bedeutendsten+Musikst%C3%A4tten+Europas+%E2%80%93+dem+Nationalen+Musikforum+in+Wroc%C5%82aw+%28Narodowe+Forum+Muzyczne+Wroc%C5%82aw%29+%E2%80%93+t%C3%A4tig+ist.%0A%5Bcaption+id%3D%22attachment_19868%22+align%3D%22aligncenter%22+width%3D%22700%22%5D+Monika%C2%A0Kruk%5B%2Fcaption%5D%0ADie+Pianistin+Monika%C2%A0Kruk+absolvierte+die+Karol-Lipi%C5%84ski-Musikhochschule+in+Wroc%C5%82aw+und+vertiefte+ihre+Ausbildung+durch+das+Vokalcoachingprofil.+Sie+studierte+in+der+Klavierklasse+von+Micha%C5%82+Szczepa%C5%84ski+und+Kammermusik+bei+Magdalena+Blum.+Weiterhin+absolvierte+sie+ein+Aufbaustudium+in+Liedgestaltung+in+Warschau.+Sie+erspielte+sich+zahlreiche+Stipendien+und+Preise+bei+Wettbewerben+und+traf+auf+Musikerinnen+wie+Jerzy+Marchwi%C5%84ski%2C+Olga+Pasiecznik%2C+Jadwiga+Rapp%C3%A9%2C+Stephen+Drury%2C+Esther+de+Bros%2C+Ubaldo+Fabbri+und+Ronan+O%E2%80%99Hora.+Mit+Aleksandra+Kubas-Kruk%C2%A0%28Sopran%29+und+Anna+Bernacka+%28Mezzosopran%29+wirkte+sie+an+der+Ersteinspielung+der+Lieder+von+Mieczys%C5%82aw+Weinberg+zu+Texten+von+Julian+Tuwim+und+Adam+Mickiewicz+mit%3A+%E2%80%9EWeinberg+%28un%29discovered%E2%80%9C+%28DUX%2C+2023%29.+Diese+Aufnahme+brachte+ihr+die+Nominierung+f%C3%BCr+den+renommierten+polnischen+Musikpreis+%E2%80%9EFryderyk%E2%80%9C+ein.+Mit+Micha%C5%82+Marcol+%28Violine%29+und+Krzysztof+Karpeta+%28Violoncello%29+spielte+sie+als+Weltpremiere+Kammermusik+von+Paul+Caro+ein+%28SPMK+Records%2C+2023%29.+Sie+konzertiert+als+Kammermusikerin+in+Polen+wie+im+Ausland+und+initiiert+Aufnahmen+von+Musik+zu+Texten+polnischer+Lyriker%2Ainnen.+F%C3%BCr+ihre+j%C3%BCngste+Aufnahme+mit+Werken+polnischer+Komponisten+f%C3%BCr+Oboe+und+Klavier+erhielt+sie+gro%C3%9Fe+Anerkennung+in+Polen+und+im+Ausland.+2019+erhielt+sie+ihren+k%C3%BCnstlerischen+Doktortitel.+Sie+arbeitet+an+der+Karol-Lipi%C5%84ski-Musikhochschule+in+Wroc%C5%82aw+in+den+Bereichen+Kammermusik+und+Korrepetition.%0AVeranstalter%3A+Polnisches+Institut+Berlin+%E2%80%93+Filiale+Leipzig%0AVeranstaltung+auf+FacebookInfo%3A+amuz.wroc.pl%2Fen%2Facademy%2Fensembles%2Flipinski-quartetEintritt%3A+freiOrt%3A+Polnisches+Institut%2C+Markt+10%2C+04109+Leipzig%0A%C2%A0%0A%C2%A0%0AFoto+Lipi%C5%84ski+Quartet+%C2%A9+%C5%81ukasz+Rajchert%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F09%2F10%2Flipinski-quartet-monika-kruk%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19866.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Musik <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19866\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nPolnisches Institut, Markt 10, 04109 Leipzig\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch category-Film post_tag-Film post_tag-G\u00f6rlitz post_tag-Kino category-Programm\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/10\/01\/franz-k-goerlitz\/\"><h5>Franz K. <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"czwartek 1 pa\u017adziernika 2026\" data-end=\"czwartek 1 pa\u017adziernika 2026\">\n\t\t\t\t\t\t\t<time itemprop=\"dtstart\" datetime=\"2026-10-01T18:15:00+02:00\"><span class=\"date date-single\">1 pa\u017adziernika 2026<\/span> <span class=\"linking_word linking_word-from\">from<\/span> <span class=\"time time-start\">18:15<\/span> <span class=\"linking_word linking_word-to\">to<\/span> <span class=\"time time-end\">20:30<\/span>\n\t\t\t\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19945.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Franz+K.&#038;dates=20261001T181500%2F20261001T203000&#038;location=Heine+Kinobar%2C+Nonnenstr.+18%2F19%2C+02826+G%C3%B6rlitz&#038;details=Spielfilm%2C+R%3A+Agnieszka+Holland%2C+CZ%2FD%2FPL+2025%2C+127+min%2C+FSK+16%2C+mit+Idan+Weiss%2C+Peter+Kurth%2C+Jenov%C3%A9fa+Bokov%C3%A1%2C+Ivan+Trojan%2C+Sandra+Korzeniak%2C+Katharina+Stark%2C+Sebastian+Schwarz+u.a.%0APrag%2C+Anfang+des+20.+Jahrhunderts%3A+Franz+Kafka+ist+zerrissen+zwischen+der+Autorit%C3%A4t+des+fordernden+Vaters%2C+der+Routine+im+Versicherungsb%C3%BCro+und+der+stillen+Sehnsucht+nach+k%C3%BCnstlerischer+Entfaltung.+W%C3%A4hrend+seine+Texte+erste+Leser%2Ainnen+finden%2C+beginnt+die+Reise+eines+jungen+Mannes%2C+der+sich+nach+Normalit%C3%A4t+sehnt%2C+jedoch+den+Widerspr%C3%BCchen+des+Lebens+begegnet%2C+dabei+Literaturgeschichte+schreibt+und+sich+immer+wieder+Hals+%C3%BCber+Kopf+verliebt.+Getrieben+von+Liebe%2C+Fantasie+und+dem+Wunsch+nach+Respekt%2C+unterst%C3%BCtzt+von+seinem+Freund+und+Verleger+Max+Brod%2C+entfaltet+sich+das+ebenso+ber%C3%BChrende+wie+skurrile+Portr%C3%A4t+eines+der+faszinierendsten+Denker+der+Moderne.+Ein+Film+wie+Kafkas+Werk+selbst%3A+%C3%BCberraschend%2C+poetisch+und+unvergesslich.%0A%5Bcaption+id%3D%22attachment_16439%22+align%3D%22aligncenter%22+width%3D%22800%22%5D+Peter+Kurth+%28Hermann+Kafka%29%2C+Daniel+Dongres+%28Franz+Kafka%29+%26amp%3B+Sandra+Korzeniak+%28Julia+Kafka%29%5B%2Fcaption%5D%0ADie+Oscar-nominierte+Regisseurin+Agnieszka+Holland+%28%22Green+Border%22%2C+%22In+Darkness%22%2C+%22Die+Spur%22%29+erschuf+mit+%22Franz+K.%22+ein+ebenso+komplexes+wie+humorvolles+Werk.+Sie+gibt+uns+einen+ganz+eigenen+Einblick+in+das+Wesen+und+Wirken+des+Ph%C3%A4nomens+Kafka.+Dabei+f%C3%A4ngt+sie+die+Monotonie+und+Beengtheit+seines+Alltags+genauso+ein+wie+die+Vielschichtigkeit+seines+Wesens+und+Vielsprachigkeit+seiner+Zeit.+In+sinnlich-surrealistischen+Bildern+ist+ein+fesselndes+Kaleidoskop+des+weltber%C3%BChmten+Schriftstellers+entstanden%2C+inspiriert+von+seinem+Leben%2C+seinem+Werk%2C+seiner+Fantasie+%E2%80%93+%C3%BCber+einen+Menschen%2C+der+seiner+Zeit+auf+faszinierende+Weise+weit+voraus+war.+Idan+Weiss+als+Franz+Kafka+verk%C3%B6rpert+den+zerrissenen+K%C3%BCnstler+mit+bemerkenswerter+Intensit%C3%A4t.%0A%5Bcaption+id%3D%22attachment_16440%22+align%3D%22aligncenter%22+width%3D%22800%22%5D+Idan+Weiss+%28Franz+Kafka%29%5B%2Fcaption%5D%0ABeim+50.+Polnischen+Spielfilm-Festival+in+Gdynia+gewann+der+Film+die+Silbernen+L%C3%B6wen+als+zweitbester+Film+des+Jahres+sowie+Preise+f%C3%BCr+die+beste+Kamera+%28Tomasz+Naumiuk%29%2C+die+beste+m%C3%A4nnliche+Hauptrolle+%28Idan+Weiss%29+und+die+beste+Maske+%28Gabriela+Pol%C3%A1kov%C3%A1%29.%0ADas+Projekt+%E2%80%9EG%C3%B6rlitzer+Interkulturelle+Filmtage%E2%80%9C%2C+das+2023+von+der+Volkshochschule+G%C3%B6rlitz+ins+Leben+gerufen+wurde%2C+hat+sich+als+fester+Bestandteil+des+interkulturellen+und+filmkulturellen+Lebens+in+G%C3%B6rlitz+etabliert.+Ziel+des+Projekts+ist+es%2C+durch+internationale+Filmkunst+den+Austausch+zwischen+Menschen+unterschiedlicher+Herkunft+zu+f%C3%B6rdern%2C+Empathie+zu+st%C3%A4rken+und+vielf%C3%A4ltige+gesellschaftliche+Perspektiven+sichtbar+zu+machen.+Die+Filmtage+2025+pr%C3%A4sentieren+ein+sorgf%C3%A4ltig+kuratiertes+Programm+aus+Filmen%2C+die+an+unterschiedlichen+Abenden+und+Veranstaltungsorten+gezeigt+werden.+Das+Projekt+richtet+sich+an+Zugewanderte+ebenso+wie+an+die+gesamte+interessierte+Stadtgesellschaft+%E2%80%93+unabh%C3%A4ngig+von+Alter%2C+Herkunft+oder+Vorwissen.+Die+Filme+stammen+aus+verschiedenen+L%C3%A4ndern+Europas+und+Afrikas+und+greifen+relevante+Themen+wie+Umweltschutz%2C+Migration%2C+Identit%C3%A4t+und+Gleichberechtigung+auf.+Ein+besonderes+Highlight+jedes+Filmabends+sind+Kuchen+aus+verschiedenen+L%C3%A4ndern%2C+die+von+Kursteilnehmerinnen+der+vhs+G%C3%B6rlitz+gebacken+werden.%0AVeranstalter%3A+Polnisches+Institut+Berlin+%E2%80%93+Filiale+Leipzig+in+Kooperation+mit+der+Volkshochschule+G%C3%B6rlitz+e.V.+im+Rahmen+der+Interkulturellen+Woche+2026%0ADie+Interkulturellen+Filmtage+werden+gef%C3%B6rdert+vom+S%C3%A4chsischen+Staatsministerium+f%C3%BCr+Soziales+und+Gesellschaftlichen+Zusammenhalt+%26amp%3B+Integration+Sachsen.%0AInfo%3A+x-verleih.de%2Ffilme%2Ffranz-k%2C+heine-kinobar.deEintritt%3A+freiOrt%3A+Heine+Kinobar%2C+Nonnenstr.+18%2F19%2C+02826+G%C3%B6rlitz%0A%C2%A0%0A%C2%A0%0AFotos+%C2%A9+Marlene+Film+Production+%2F+X-Verleih+AG%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F10%2F01%2Ffranz-k-goerlitz%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19945.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Film <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19945\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nHeine Kinobar, Nonnenstr. 18\/19, 02826 G\u00f6rlitz\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch category-Diskussion category-Film category-Programm\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/10\/01\/vika-le-kuhne\/\"><h5>PolDok: Vika! <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"czwartek 1 pa\u017adziernika 2026\" data-end=\"czwartek 1 pa\u017adziernika 2026\">\n\t\t\t\t\t\t\t<time itemprop=\"dtstart\" datetime=\"2026-10-01T19:00:00+02:00\"><span class=\"date date-single\">1 pa\u017adziernika 2026<\/span> <span class=\"linking_word linking_word-from\">from<\/span> <span class=\"time time-start\">19:00<\/span> <span class=\"linking_word linking_word-to\">to<\/span> <span class=\"time time-end\">21:00<\/span>\n\t\t\t\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19687.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=PolDok%3A+Vika%21&#038;dates=20261001T190000%2F20261001T210000&#038;location=Polnisches+Institut%2C+Markt+10%2C+04109+Leipzig&#038;details=%C3%84lterwerden%2C+Lebensfreude+und+Selbstbestimmung%0AZum+Internationalen+Tag+der+%C3%A4lteren+Menschen%0AR%3A+Agnieszka+Zwiefka%2C+PL%2FD%2FFIN+2024%2C+74+min%2C+dt.+Voiceover-Fassung%0Azu+Gast%3A+Sibylle+Kuhne+%28deutsche+Synchronstimme+von+DJ+Vika%29%0ABegr%C3%BC%C3%9Fung%3A+Mandy+Uhlig+%28Gleichstellungsbeauftragte+der+Stadt+Leipzig%29%0A%5Bgallery+link%3D%22file%22+columns%3D%222%22+size%3D%22large%22+ids%3D%2213243%2C13242%22%5D%0ADJ+Vika%2C+eigentlich+Wirginia+Szmyt%2C+ist+85+Jahre+alt+und+Star+der+Musikclubs+von+Warschau.+Sie+weigert+sich%2C+alt+zu+werden+und+zu+Hause+zu+sitzen.+Stattdessen+feiert+sie+das+Leben%2C+sich+selbst+und+genie%C3%9Ft+die+Musik.+Wenn+sie+auf+ihr+Leben+zuru%CC%88ckblickt%2C+erinnert+sie+sich+an+ihren+Job+als+Gefa%CC%88ngnispa%CC%88dagogin%2C+ihre+Kinder+und+eine+schwierige+Kindheit.+Gelebt+hat+sie+vor+allem+fu%CC%88r+andere.+Nach+dem+Eintritt+in+den+Ruhestand+begann+sie+sich+neu+zu+erfinden+und+nur+noch+das+zu+tun%2C+was+sie+mit+Leidenschaft+erfu%CC%88llt.+Sie+weigert+sich%2C+den+Erwartungen+anderer+zu+entsprechen+und+in+eine+Rolle+zu+schlu%CC%88pfen%2C+die+ihr+nicht+gerecht+wird.+Das+erste+Mal+in+ihrem+Leben+lebt+Vika+ihren+Traum.%0A%5Bgallery+columns%3D%222%22+size%3D%22large%22+link%3D%22file%22+ids%3D%2213240%2C13241%22%5D%0ADer+Film+der+preisgekr%C3%B6nten+Regisseurin+Agnieszka+Zwiefka+portr%C3%A4tiert+in+einer+Mischung+aus+Dokumentar-Szenen+und+Videoclips+den+schwierigen+Spagat+zwischen+Selbstverwirklichung+und+stabilen+Sozialkontakten.+Er+gewann+zahlreiche+Preise+auf+Festivals+und+entwickelte+sich+dort+schnell+zum+Publikumsliebling.%0A%5Bcaption+id%3D%22attachment_19711%22+align%3D%22aligncenter%22+width%3D%22700%22%5D+Sibylle+Kuhne+und+DJ+Vika+bei+der+Leipzig-Premiere+von+%E2%80%9EVika%21%E2%80%9C+im+Januar+2025%5B%2Fcaption%5D%0ATrailer%3A+https%3A%2F%2Fwww.youtube.com%2Fwatch%3Fv%3Dvkgf3EMvqdc%0ABisher+in+der+Reihe+%E2%80%9EPolDok%E2%80%9C%3A21.04.2026+Po-Lin.+Okruchy+pami%C4%99ci+%2F+Spuren+der+Erinnerung19.05.2026+Poci%C4%85gi+%2F+Trains16.06.2026+Listy+z+Wilczej+%2F+Briefe+aus+der+Wilcza01.10.2026+Vika%21%0AVeranstalter%3A+Referat+Gleichstellung+f%C3%BCr+Frau+und+Mann+der+Stadt+Leipzig+in+Kooperation+mit+dem+Polnischen+Institut+Berlin+%E2%80%93+Filiale+Leipzig+und+der+Beauftragten+f%C3%BCr+Seniorinnen+und+Senioren+der+Stadt+Leipzig%0AInfo%3A+jip-film.de%2Fvika%2C+sibylle-kuhne.de+Eintritt%3A+freiOrt%3A+Polnisches+Institut%2C+Markt+10%2C+04109+Leipzig%0A%C2%A0%0A%C2%A0%0A%C2%A0%0AFotos+%C2%A9+jip+film+%26amp%3B+verleih%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F10%2F01%2Fvika-le-kuhne%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19687.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Diskussion <\/span>\t\t\t\t\t<span  class=\"event_category\">Film <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19687\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nPolnisches Institut, Markt 10, 04109 Leipzig\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode language-Deutsch post_tag-Leipzig category-Literatur category-Musik post_tag-Musik category-Programm category-Vortrag\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/10\/04\/der-reiche-bogacz\/\"><h5>Der Reiche \u2013 Bogacz <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"niedziela 4 pa\u017adziernika 2026\" data-end=\"niedziela 4 pa\u017adziernika 2026\">\n\t\t\t\t\t\t\t<time itemprop=\"dtstart\" datetime=\"2026-10-04T16:00:00+02:00\"><span class=\"date date-single\">4 pa\u017adziernika 2026<\/span> <span class=\"linking_word linking_word-from\">from<\/span> <span class=\"time time-start\">16:00<\/span> <span class=\"linking_word linking_word-to\">to<\/span> <span class=\"time time-end\">18:00<\/span>\n\t\t\t\t\t\t\t<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19768.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=Der+Reiche+%E2%80%93+Bogacz&#038;dates=20261004T160000%2F20261004T180000&#038;location=St.+Trinitatis%2C+Nonnenm%C3%BChlgasse+2%2C+04107+Leipzig&#038;details=Das+polnisch-deutsche+Programm+mit+literarischen+Texten+und+Musik+zum+Thema+Reichtum+und+Armut+vor+500+Jahren%2C+das+zuvor+unter+anderem+in+Zelisz%C3%B3w+aufgef%C3%BChrt+wurde%2C+pr%C3%A4sentiert+Kompositionen+und+Texte%2C+die+unter+anderem+von+Angelus+Silesius+%2F+Anio%C5%82+%C5%9Al%C4%85zak%2C+Wac%C5%82aw+z+Szamotu%C5%82+%2F+Wenzel+von+Samter+und+Miko%C5%82aj+z+Krakowa+%2F+Nicolaus+Cracoviensis+sowie+aus+mittelalterlichen+Handschriften+stammen+%E2%80%93+dem+Krasi%C5%84ski-Kodex%2C+der+Tabulatur+des+Johannes+von+Lublin+und+dem+Glogauer+Liederbuch.%0ADas+Programm+umfasst+zudem+u.a.+den+polnischen+Tanz+%E2%80%9EChorea+Polonica%E2%80%9C%2C+der+f%C3%A4lschlicherweise+Wojciech+D%C5%82ugoraj+zugeschrieben+wurde%2C+Kompositionen+von+Arnold+von+Bruck%2C+Jobst+von+Brandt%2C+Ana+Maria+Leyrsederin%2C+Paul+Hofhaimer%2C+Ludwig+Senfl%2C+Johann+Cr%C3%BCger+%2F+Jan+Kryga%C5%95%2C+Martin+Luther%2C+Antonio+Scandello%2C+Jobst+von+Brandt%2C+David+Wolkenstein+und+Melchior+Franck+sowie+Texte+von+Sophokles%2C+Dschal%C4%81l+ad-D%C4%ABn+Muhammad+R%C5%ABm%C4%AB%2C+Bertolt+Brecht%2C+Husam+Maarouf%2C+Peter+Weiss+und+Rosa+Luxemburg.%0A%5Bgallery+columns%3D%222%22+link%3D%22file%22+size%3D%22large%22+ids%3D%2219898%2C19897%22%5D%0AEin+Mann+baut+sich+ein+Leben+aus+Handel%2C+Mut+und+Visionen.+Er+reist+durch+Europa%2C+verbindet+Kulturen%2C+h%C3%A4uft+Reichtum+an+%E2%80%93+und+sucht+doch+nach+etwas%2C+das+%C3%BCberdauert.+Hans+Frenzel+%E2%80%93+der+Reiche.+Kaufmann%2C+Stifter+und+Mensch+auf+der+Suche+nach+mehr.+500+Jahre+sp%C3%A4ter+wird+seine+Geschichte+h%C3%B6rbar+%E2%80%93+in+Musik%2C+die+sich+nicht+an+Grenzen+h%C3%A4lt+und+in+Stimmen%2C+die+fragen.+Wie+wird+man+eigentlich+reich%3F+Und+wozu%3F%0AAlte+Lieder+aus+Deutschland+und+Polen+erklingen+neben+neuen+Texten.+Eine+Schauspielerin+spiegelt+Gedanken+und+l%C3%A4sst+sich+von+einer+festgeschriebenen+Biografie+nicht+aufhalten.%0AM%C4%99%C5%BCczyzna+buduje+swoje+%C5%BCycie+z+handlu%2C+odwagi+i+wizji.+Podr%C3%B3%C5%BCuje+po+Europie%2C+%C5%82%C4%85czy+kultury%2C+gromadzi+bogactwo+%E2%80%93+ale+szuka+czego%C5%9B%2C+co+przetrwa.+Hans+Frenzel+%E2%80%93+bogacz.+Kupiec%2C+fundator+i+cz%C5%82owiek+w+poszukiwaniu+czego%C5%9B+wi%C4%99cej.+500+lat+p%C3%B3%C5%BAniej+jego+historia+staje+si%C4%99+s%C5%82yszalna+%E2%80%93+w+muzyce%2C+kt%C3%B3ra+nie+zna+granic+i+w+g%C5%82osach%2C+kt%C3%B3re+zadaj%C4%85+pytania.+Jak+sta%C4%87+si%C4%99+bogatym%3F+I+po+co%3F%0AStare+pie%C5%9Bni+z+Niemiec+i+Polski+przeplataj%C4%85+si%C4%99+z+nowymi+tekstami.+Aktorka+odzwierciedla+my%C5%9Bli+i+nie+zatrzymuje+si%C4%99+na+zdefiniowanej+biografii.%0A%C2%A0%0A%5Bgallery+columns%3D%222%22+link%3D%22file%22+size%3D%22large%22+ids%3D%2219895%2C19896%22%5D%0ADauer%3A+ca.+90+min+%28ohne+Pause%29%0AAuff%C3%BChrende%3AClarissa+Renner+%28Sopran%29Pedro+Matos+%28Tenor%29Margot+Simon+%28Blockfl%C3%B6te%2C+Dulzian%29Uwe+Ulbrich+%28Rebec%2C+Diskantgambe%29Simon+Linn%C3%A9+%28Laute%2C+Zister%29Hannes+Malkowski+%28Perkussion%29Masafumi+Sakamoto+%28Renaissanceposaune%29Maria+Anne+M%C3%BCller+%28Schauspiel%29%0ARegie+%26amp%3B+Texte%3A+Maria+Anne+M%C3%BCllerGrafik%2FLayout%2FFotos%3A+Ewa+Milun-Walczak%0A%5Bgallery+link%3D%22file%22+columns%3D%222%22+size%3D%22large%22+ids%3D%2219910%2C19909%22%5D%0AVeranstalter%3A+Leipziger+Concert+e.V.+in+Kooperation+mit+dem+Polnischen+Institut+Berlin+%E2%80%93+Filiale+Leipzig%2C+unterst%C3%BCtzt+von+der+Stadt+Leipzig+und+der+Deutsch-polnischen+Stiftung+Kulturpflege+und+Denkmalschutz%0AProgrammheft+als+PDF+%2810+MB%29Info%3A+sospiratem.de%2Fprogramme%2Fder-reiche-bogacz%2C+propstei-leipzig.deReservierung%3A+sospiratem.de%2FreservierungOrt%3A+Propsteikirche+St.+Trinitatis%2C+Nonnenm%C3%BChlgasse+2%2C+04107+Leipzig%0A%C2%A0%0A%C2%A0%0A%C2%A0%0A%C2%A0%0ATitelfoto+%C2%A9+Ewa+Milun-Walczak%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F10%2F04%2Fder-reiche-bogacz%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19768.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Literatur <\/span>\t\t\t\t\t<span  class=\"event_category\">Musik <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span>\t\t\t\t\t<span  class=\"event_category\">Vortrag <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19768\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nSt. Trinitatis, Nonnenm\u00fchlgasse 2, 04107 Leipzig\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-OfflineEventAttendanceMode post_tag-Chopin language-Deutsch post_tag-Leipzig category-Musik post_tag-Musik category-Programm\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/10\/18\/36-leipziger-chopin-tage\/\"><h5>XXXVI. Leipziger Chopin-Tage \u201eChopin, Grande op\u00e9ra et deux piano\u201c <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"\u015broda 14 pa\u017adziernika 2026\" data-end=\"niedziela 18 pa\u017adziernika 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-10-14T00:00:00+00:00\">14 pa\u017adziernika 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-10-18T00:00:00+00:00\">18 pa\u017adziernika 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19776.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=XXXVI.+Leipziger+Chopin-Tage+%E2%80%9EChopin%2C+Grande+op%C3%A9ra+et+deux+piano%E2%80%9C&#038;dates=20261014%2F20261018&#038;location=versch.+Orte+in+Leipzig+und+Markkleeberg&#038;details=14.10.+%2F+20%3A00+%2F+Leipzig+%2F+Polnisches+Institut+%2F+Eintritt+freiEr%C3%B6ffnungskonzertmit+Irina+Chistiakova+%28Klavier+%26amp%3B+Gesang%29%0AFryderyk+Chopin+%281810%E2%80%931849%293+Walzer+As-Dur%2C+a-Moll%2C+F-Dur+op.+34Nocturne+fis-Moll+op.+48%2F2Impromptu+As-Dur+op.+29Fantasie-Impromptu+cis-Moll+op.+66+poth.2.+Ballade+F-Dur+op.+383.+Ballade+f-Moll+op.+52%0AFranz+Liszt+%281811%E2%80%931886%29Reminiscences+de+Norma+nach+Themen+aus+der+gleichnamigen+Oper+von+Vincenco+Bellini%0ACamille+Saint-Sa%C3%ABns+%281835%E2%80%931921%29Samson+et+Dalila+%E2%80%93+Arie+der+Dalila+%E2%80%9EMon+coeur+s%27ouvre+%C3%A0+ta+voix%E2%80%9C%0A15.10.+%2F+19%3A30+%2F+Leipzig+%2F+Hochschule+f%C3%BCr+Musik+und+Theater+%2F+Eintritt+freiDeux+PianosKlavierabend%0AWolfgang+Amadeus+Mozart+%281756%E2%80%931791%29Sonate+D-Dur+KV+448+f%C3%BCr+zwei+Klaviere%0AMarie+und+Florentine+Lehnert+%28Klavier%29%0AIgnaz+Moscheles+%7B1794%E2%80%931870%29Klavierkonzert+F-Dur+op.+45+%E2%80%93+1.+Allegro+maestoso%0AAgnes+und+Katrin+Lehnert+%28Klavier%29%0AFryderyk+Chopin+%281810%E2%80%931849%29Rondo+f%C3%BCr+zwei+Klaviere+C-Dur+op.+73+posth.%0AMarie+und+Florentine+Lehnert+%28Klavier%29%0AFryderyk+Chopin+%281810%E2%80%931849%29Klavierkonzert+Nr.+2+f-Moll+op.+21%0ABabett+und+Katrin+Lehnert+%28Klavier%29%0A16.10.+%2F+20%3A00+%2F+Leipzig+%2F+Gewandhaus+%2F+Mendelssohn-SaalGrzegorz+Niemczuk+spielt+legend%C3%A4re+KlaviersonatenGespr%C3%A4chskonzert+mit+Werken+von+Mozart%2C+Beethoven+und+Chopin%0AWolfgang+Amadeus+Mozart+%281756%E2%80%931791%29Sonate+A-Dur+KV+331+%28KV+300i%29%0ALudwig+van+Beethoven+%281770%E2%80%931827%29Sonate+cis-Moll+op.+27%2F2+%28%E2%80%9EMondscheinsonate%E2%80%9D%29%0AFryderyk+Chopin+%281810%E2%80%931849%29Sonate+b-Moll+op.+353.+Sonate+f%C3%BCr+Klavier+h-Moll+op.+58%0AInfo+%26amp%3B+Tickets%3A+gewandhausorchester.de%0A17.10.+%2F+09%3A00%E2%80%9320%3A00+%2F+Leipzig+%2F+Hochschule+f%C3%BCr+Musik+und+Theater8.+Leipziger+Clara-Schumann-Wettbewerb+f%C3%BCr+junge+Pianist%2Ainnen%C3%96ffentliche+VorspieleJury%3A+Heike+Angela+Moser+%28Ur-Ururenkelin+von+Clara+und+Robert+Schumann%29%2C+Prof.+Gudrun+Franke+%28HMT+Leipzig%29%2C+Sonia+Achkar+%28HMDK+Stuttgart%29%2C+Prof.+Katharina+Treutler+%28mdw+Wien%29+%26amp%3B+Prof.+Alexander+Meinel+%28HMT+Leipzig%29%0AEingeladen+sind+junge+Pianistinnen+und+Pianisten+ab+dem+Alter+von+zehn+Jahren+mit+Wohnsitz+in+Deutschland%2C+die+nicht+im+Hauptstudium+Klavier+an+einer+Hochschule+eingeschrieben+waren+oder+sind.+Sie+spielen1.+ein+oder+mehrere+Originalwerk%28e%29+von+Clara+Schumann+oder%2Fund+einer+anderen+zwischen+1800+und+1896+geborenen+Komponistin+oder%2Fund+einer%2Feines+anderen+zwischen+1680+und+1800+geborenen+Komponistin%2FKomponisten%3B2.+ein+oder+mehrere+Originalwerk%28e%29+von+Fryderyk+Chopin+oder%2Fund+einer%2Feines+anderen+zwischen+1800+und+1849+geborenen+Komponistin%2FKomponisten.Anmeldeschluss+war+der+30.+Juni+2026.%0AInfo%3A+neue-leipziger-chopin-gesellschaft.de%0A18.10.+%2F+11%3A00+%2F+Leipzig+%2F+Schumann-HausPreistr%C3%A4ger%2Ainnenkonzertdes+8.+Leipziger+Clara-Schumann-Wettbewerbs%0ADie+Neue+Leipziger+Chopin-Gesellschaft+e.V.+l%C3%A4dt+j%C3%A4hrlich+junge+Pianist%2Ainnen+zum+deutschlandweit+ausgeschriebenen+Wettbewerb+nach+Leipzig+ein.+Gewidmet+ist+er+der+in+Leipzig+geborenen+Klaviervirtuosin%2C+Komponistin+und+ersten+Klavierprofessorin+in+Deutschland+Clara+Schumann+%281819%E2%80%931896%29.+Mit+ihrer+Ur-Ururenkelin+Heike-Angela+Moser+in+der+Wettbewerbsjury+f%C3%BChren+die+Traditionslinien+von+heute+direkt+in+das+als+bedeutendes+europ%C3%A4isches+Musikzentrum+des+19.+Jahrhunderts+bekannte+Leipzig+zur%C3%BCck.+Das+Wettbewerbsprogramm+bezieht+sich+auf+die+stilistische+Vielfalt+des+Solorepertoires+von+Clara+Schumann+w%C3%A4hrend+ihrer+60-j%C3%A4hrigen+Konzertkarriere.+Es+umfasste+eigene+Kompositionen+wie+auch+Werke+vom+Barock+bis+zu+ihren+Zeitgenossen.+Im+Schumann-Saal+sind+die+Ergebnisse+des+diesj%C3%A4hrigen+Wettbewerbs+zu+h%C3%B6ren.%0AInfo+%26amp%3B+Tickets%3A+schumannhaus.de%0A18.10.+%2F+18%3A00+%2F+Markkleeberg+%2F+Wei%C3%9Fes+HausFestlicher+Salon+zum+Abschluss+der+Chopin-Tage%0AFryderyk+Chopin+%281810%E2%80%931849%29Klaviersonate+Nr.+2+b-Moll+op.+35%0AGioachino+Rossini+%281792%E2%80%931868%29Guillaume+Tell+%E2%80%93+Ouvert%C3%BCre+f%C3%BCr+Klavier+zu+vier+H%C3%A4nden+%26amp%3B+Arie+der+Matilde+%E2%80%9ESombre+for%C3%AAt%E2%80%9C%0AGioachino+Rossini+%2F+Moritz+Strakosch+%281825%E2%80%931887%29Pregheria+%28Klavierfassung+der+Arie+der+Desdemona+%E2%80%9EDeh%21+Calma+o+ciel%E2%80%9D+aus+der+Oper+%E2%80%9EOtello%E2%80%9C%29%0AFryderyk+ChopinPolonaise+Des-Dur+op.+posth.+%E2%80%9EAdieu%21+An+Wilhelm+Kolberg%E2%80%9C%0AGioachino+RossiniIl+barbiere+di+Siviglia+%E2%80%93+Arie+der+Rosina+%E2%80%9EUna+voce+poco+fa%E2%80%9C%0AFryderyk+ChopinTrois+Mazurkas+op.+59%0AGiacomo+Meyerbeer+%281791%E2%80%931864%29Robert+le+diable+%E2%80%93+Arie+der+Isabelle+%E2%80%9ERobert%2C+toi+que+j%27aime%E2%80%9C%0AWolfgang+Amadeus+Mozart+%281756%E2%80%931791%29Le+nozze+di+Figaro+%E2%80%93+Arie+des+Cherubino+%E2%80%9EVoi+che+sapete%E2%80%9CKlaviertrio+G-Dur+KV+564Le+nozze+di+Figaro+%E2%80%93+Arie+des+Cherubino+%E2%80%9ENon+so+pi%C3%B9%E2%80%9C%0AAlbert+Lavignac+%281846%E2%80%931918%29Galop-marche+D-Dur+f%C3%BCr+acht+H%C3%A4nde%0Amit+Simone+Grundmann+%28Mezzosopran%29%2C+Augustin+Johann+Erices+%28Violine%29%2C+Gabriel+Bruns+%28Violoncello%29%2C+Karine+Terterian%2C+Paulina+Eichhoff%2C+Gudrun+Franke%2C+Franziska+Franke-Kern%2C+Vreni+Scheiter%2C+Hiroko+Tatsumi+und+Van+Trang+Truong+%28Klavier%29%0AVeranstalter%3A+Neue+Leipziger+Chopin-Gesellschaft+e.+V.+in+Kooperation+mit+dem+Polnischen+Institut+Berlin+%E2%80%93+Filiale+Leipzig%2C+der+Europ%C3%A4ischen+Stiftung+der+Rahn+Dittrich+Group+f%C3%BCr+Bildung+und+Kultur%2C+der+Stadt+Markkleeberg%2C+Grzegorz+Niemczuk+%E2%80%93+Piano+Studio+und+weiteren+Partnern%2C+unterst%C3%BCtzt+von+der+Stadt+Leipzig%0AInfo%3A+www.neue-leipziger-chopin-gesellschaft.deOrte%3A+versch.+Orte+in+Leipzig+und+Markkleeberg%0A%C2%A0%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F10%2F18%2F36-leipziger-chopin-tage%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19776.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Musik <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<address \tdata-id=\"19776\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-latitude=\"51.28362182766469\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-longitude=\"12.376354797697585\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-marker=\"\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-iconcode=\"f230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-icon=\"\uf230\"\n\t\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#000000\" itemprop=\"adr\" class=\"eventpost-address\">\n\t\t\t\t\t\t\t<span>\nversch. Orte in Leipzig und Markkleeberg\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/address>\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><div class=\"event_item event_future status-EventScheduled location-type-MixedEventAttendanceMode post_tag-Animationsfilm language-Deutsch category-Diskussion post_tag-DOK post_tag-Dokumentarfilm post_tag-Festival category-Film post_tag-Film post_tag-Leipzig category-Programm\" data-color=\"000000\" style=\"\"><a href=\"https:\/\/instytutpolski.pl\/leipzig\/2025\/11\/01\/69-dok-leipzig\/\"><h5>DOK Leipzig <\/h5><\/a><div class=\"event_data event_date \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<div class=\"event_date\" data-start=\"poniedzia\u0142ek 26 pa\u017adziernika 2026\" data-end=\"niedziela 1 listopada 2026\"> <span class=\"linking_word linking_word-from\">from<\/span> <time class=\"date date-start\" itemprop=\"dtstart\" datetime=\"2026-10-26T00:00:00+00:00\">26 pa\u017adziernika 2026<\/time> <span class=\"linking_word linking_word-to\">to<\/span> <time class=\"date date-to\" itemprop=\"dtend\" datetime=\"2026-11-01T00:00:00+00:00\">1 listopada 2026<\/time>\n\t\t\t\t\t\t<\/div><!-- .event_date --><span class=\"eventpost-status\">Scheduled<\/span>\n\t\t\t\t\t\t\t<span class=\"eventpost-date-export\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19964.ics\" class=\"event_link event-export ics\" target=\"_blank\" title=\"Download ICS file\">ical<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;trp=false&#038;sprop=name&#038;text=DOK+Leipzig&#038;dates=20261026%2F20261101&#038;location&#038;details=Jahr+f%C3%BCr+Jahr+versammelt+DOK+Leipzig+im+Herbst+Filmemacher%2Ainnen%2C+Kritiker%2Ainnen%2C+Produzent%2Ainnen+und+vor+allem+scharenweise+Zuschauer%2Ainnen+aus+der+ganzen+Welt+an+der+Plei%C3%9Fe%2C+um+aktuelle+Produktionen+zu+sichten%2C+spannende+Wettbewerbe+zu+verfolgen%2C+in+Workshops+von+Meister%2Ainnen+ihres+Fachs+zu+lernen+oder+in+Retrospektiven+vergessene+Perlen+wiederzuentdecken.+Ebenso+regelm%C3%A4%C3%9Fig+sind+polnische+Filme+Stammg%C3%A4ste+auf+den+Leipziger+Leinw%C3%A4nden+%E2%80%93+sowohl+Animationsfilme+als+auch+kurze+und+lange+Dokumentarfilme+konnten+in+den+letzten+Jahren+Preise+ergattern+und+werden+auch+diesmal+wieder+die+Wettbewerbe+pr%C3%A4gen.%0AProgrammdetails+folgen.%0AIm+September+2025+wurde+dem+Festival+DOK+Leipzig+beim+20.+Polnischen+Filmfestival+filmPOLSKA+in+Berlin+der+filmPOLSKA+Award+f%C3%BCr+seine+Verdienste+um+die+Verbreitung+des+polnischen+Filmschaffens+in+Deutschland+verliehen.%0A%C2%A0%0A%5Bcaption+id%3D%22attachment_16227%22+align%3D%22aligncenter%22+width%3D%22800%22%5D+filmPOLSKA+Award-Verleihung+an+DOK+Leipzig+am+10.09.2025+in+Berlin+%28v.l.+Katarzyna+Sitko%2C+Lina+Dinkla%2C+Jana+Kraft+%26amp%3B+Christoph+Terhechte%29%5B%2Fcaption%5D%0A%C2%A0%0ASeit+1.+Januar+2026+ist+Aleksandra+%28Ola%29+Staszel+die+neue+Intendantin+von+DOK+Leipzig+sowie+Gesch%C3%A4ftsf%C3%BChrerin+der+Leipziger+Dok-Filmwochen+GmbH.+Staszel+war+vorher+Leiterin+des+deutsch-polnisch-tschechischen+Nei%C3%9Fe+Filmfestivals.+Sie+studierte+Film-+und+Literaturwissenschaften+sowie+Europastudien+an+den+Universit%C3%A4ten+Wroc%C5%82aw+und+Aachen.+Ab+1999+lebte+sie+lange+Zeit+in+Berlin.+Ola+Staszel+gr%C3%BCndete+und+leitete+das+Festival+des+mobilen+Kinos+%E2%80%9EThe+Rolling+Movies%E2%80%9D+und+war+von+2014+bis+2025+Jurymitglied+bei+der+Deutschen+Film-+und+Medienbewertung+%28FBW%29+in+Wiesbaden.%0A%C2%A0%0A%5Bcaption+id%3D%22attachment_16596%22+align%3D%22aligncenter%22+width%3D%22700%22%5D+Ola+Staszel+%40+DOK+Leipzig+%2F+Alena+Flemming%5B%2Fcaption%5D%0A%C2%A0%0A%C2%A0%0AF%C3%BCr+die+Filmvorf%C3%BChrungen+im+Polnischen+Institut+gilt+wie+immer%3A+Eintritt+frei%2C+keine+Eintrittskarten%2C+kein+Vorverkauf%2C+keine+Reservierungen%2C+Einlass+30+Minuten+vor+Beginn.%0A%C2%A0%0AVeranstalter%3A+Leipziger+Dokfilmwochen+GmbH+in+Kooperation+mit+dem+Polnischen+Institut+Berlin+%E2%80%93+Filiale+Leipzig+und+weiteren+Partnern%0AInfo+%26amp%3B+Programm%3A+www.dok-leipzig.deOrte%3A+verschiedene+Orte+in+Leipzig%0A%C2%A0%0A%C2%A0%0ALogo+%26amp%3B+Bilder+%C2%A9+Leipziger+Dokfilmwochen+GmbH+%2F+Viktoria+Conzelmann%2C+Logodesign%3A+Stefan+Ibrahim%0A%0Ahttps%3A%2F%2Finstytutpolski.pl%2Fleipzig%2F2025%2F11%2F01%2F69-dok-leipzig%2F&#038;gmt=%2B02&#038;ctz=Europe\/Warsaw\" class=\"event_link event-export gcal\" target=\"_blank\" title=\"Add to Google calendar\">Google<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/instytutpolski.pl\/leipzig\/eventpost\/19964.vcs\" class=\"event_link event-export vcs\" target=\"_blank\" title=\"Add to Outlook\">outlook<\/a>\n\t\t\t\t\t\t\t\t<i class=\"dashicons-before dashicons-calendar\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div><!-- .event_date --><div class=\"event_data event_category \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\t\t\t\t<span class=\"event_categories\">\t\t\t\t\t<span  class=\"event_category\">Diskussion <\/span>\t\t\t\t\t<span  class=\"event_category\">Film <\/span>\t\t\t\t\t<span  class=\"event_category\">Programm <\/span><\/span>\n\t\t\t\t\t<\/div><!-- .event_category --><div class=\"event_data event_location \" itemscope itemtype=\"http:\/\/microformats.org\/profile\/hcard\">\n\t\t\n\t\t\t\t\t<\/div><!-- .event_location --><\/div><!-- .event_item --><\/div><!-- .event_loop -->","protected":false},"excerpt":{"rendered":"<p>#SolidarityWithUkraine R: Elwira Niewiera &amp; Piotr Roso\u0142owski, D\/PL 2022, 85 min, OmdU Leipzig-Premiere der deutschen Kino-Fassung mit der Regisseurin Elwira NiewieraModeration: Rainer Mende (Polnisches Institut Berlin \u2013 Filiale Leipzig) Wenige Monate vor der Invasion Russlands in die Ukraine 2022 nehmen f\u00fcnf junge Frauen und M\u00e4nner an einem einzigartigen Theaterprojekt teil. Darin versuchen sie, ihre Kriegserfahrungen [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":7450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[179],"tags":[253,115,101],"class_list":["post-7580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programmarchiv","tag-auschwitz","tag-dresden","tag-vortrag"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Syndrom Hamleta \/ Das Hamlet Syndrom - Instytut Polski w Lipsku<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Syndrom Hamleta \/ Das Hamlet Syndrom - Instytut Polski w Lipsku\" \/>\n<meta property=\"og:description\" content=\"#SolidarityWithUkraine R: Elwira Niewiera &amp; Piotr Roso\u0142owski, D\/PL 2022, 85 min, OmdU Leipzig-Premiere der deutschen Kino-Fassung mit der Regisseurin Elwira NiewieraModeration: Rainer Mende (Polnisches Institut Berlin \u2013 Filiale Leipzig) Wenige Monate vor der Invasion Russlands in die Ukraine 2022 nehmen f\u00fcnf junge Frauen und M\u00e4nner an einem einzigartigen Theaterprojekt teil. Darin versuchen sie, ihre Kriegserfahrungen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/\" \/>\n<meta property=\"og:site_name\" content=\"Instytut Polski w Lipsku\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-22T09:49:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-23T09:53:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rainer Mende\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rainer Mende\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"event\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/\",\"url\":\"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/\",\"name\":\"Syndrom Hamleta \/ Das Hamlet Syndrom\",\"isPartOf\":{\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/#primaryimage\"},\"image\":[\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg\",\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web-300x162.jpg\",\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web-1024x553.jpg\",\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg\"],\"thumbnailUrl\":\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg\",\"datePublished\":\"2022-01-22T09:49:00+02:00\",\"dateModified\":\"2023-01-23T09:53:13+02:00\",\"author\":{\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/a74d20cf3dac53f5579b2a3ec40f22dd\"},\"breadcrumb\":{\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/\"]}],\"@context\":\"https:\/\/schema.org\",\"startDate\":\"2023-01-22T01:00:00+02:00\",\"endDate\":\"2023-01-22T03:00:00+02:00\",\"eventStatus\":\"EventScheduled\",\"eventAttendanceMode\":\"OfflineEventAttendanceMode\",\"location\":{\"@type\":\"place\",\"name\":\"Passage Kinos, Hainstra\u00dfe 19a, 04109 Leipzig\",\"address\":\"Passage Kinos, Hainstra\u00dfe 19a, 04109 Leipzig\",\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"51.28362182766469\",\"longitude\":\"12.376354797697585\"}},\"description\":\"#SolidarityWithUkraine\\nR: Elwira Niewiera &amp; Piotr Roso\u0142owski, D\/PL 2022, 85 min, OmdU\\nLeipzig-Premiere der deutschen Kino-Fassung mit der Regisseurin Elwira NiewieraModeration: Rainer Mende (Polnisches Institut Berlin \u2013 Filiale Leipzig)\\nWenige Monate vor der Invasion Russlands in die Ukraine 2022 nehmen f\u00fcnf junge Frauen und M\u00e4nner an einem einzigartigen Theaterprojekt teil. Darin versuchen sie, ihre Kriegserfahrungen mit Shakespeares Theaterst\u00fcck \u201eHamlet\u201c in Beziehung zu setzen. Die B\u00fchne ist eine Plattform, auf der sie ihre Trauer und Traumata anhand der ber\u00fchmten Frage \u201eSein oder Nichtsein\u201c reflektieren k\u00f6nnen, die sich in ihrem Leben widerspiegelt.\\nDie Protagonist*innen k\u00e4mpfen an gegen Entt\u00e4uschung, Ohnmacht und Wut. Sie versuchen, ihr Leben wieder zu ordnen und gleichzeitig die schmerzhafte Vergangenheit zu verarbeiten: Slavik, der als Soldat durch die H\u00f6lle des Krieges und der Gefangenschaft gegangen ist, Katya, die in den Krieg zog und sich nun nach der Vergebung ihrer Mutter sehnt, weil sie in den Krieg zog, Rodion, der aus dem Donbas geflohen ist und nun mit wachsender Homophobie konfrontiert ist, Roman, der immer noch mit den traumatischen Erinnerungen als Sanit\u00e4ter auf dem Schlachtfeld k\u00e4mpft, und Oxana, die einfach nur vergessen und das Land verlassen will.\\nDie Proben f\u00fcr das St\u00fcck werden mit einem intensiven Einblick in das Leben der Protagonist*innen kombiniert: ein kraftvolles Portr\u00e4t einer Generation, die mit dem Trauma des Krieges zurechtzukommen versucht, der seit 2014 in der Ostukraine andauert und nun nach dem Einmarsch Russlands in die Ukraine noch verst\u00e4rkt ihre Gegenwart und Zukunft pr\u00e4gt.\\n[embed]https:\/\/youtu.be\/BxySD52pheg[\/embed]\\nElwira Niewiera und Piotr Roso\u0142owski drehten gemeinsam bereits die preisgekr\u00f6nten Dokumentarfilme \\\"Efekt Domina \/ Domino Effekt\\\" und \\\"Ksi\u0105\u017c\u0119 i dybuk \/ Der Prinz und der Dibbuk\\\", die ebenfalls deutsch-polnische Koproduktionen waren. \\\"Syndrom Hamleta \/ Das Hamlet Syndrom\\\" wurde u.a. auf Filmfestivals in Adelaide, Krak\u00f3w und Opole ausgezeichnet.\\nVeranstalter: Passage Kinos Leipzig in Kooperation mit dem Polnischen Institut Berlin \u2013 Filiale Leipzig\\nVeranstaltung auf FacebookInfo: realfictionfilme.de\/das-hamlet-syndrom.html, facebook.com\/TheHamletSyndrome, passage-kinos.de\/das-hamlet-syndromOrt: Passage Kinos, Hainstra\u00dfe 19a, 04109 Leipzig\\nFotos \u00a9 Kundschafter Filmproduktion\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/#primaryimage\",\"url\":\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg\",\"contentUrl\":\"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg\",\"width\":2000,\"height\":1081},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/instytutpolski.pl\/leipzig\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Syndrom Hamleta \/ Das Hamlet Syndrom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#website\",\"url\":\"https:\/\/instytutpolski.pl\/leipzig\/\",\"name\":\"Instytut Polski w Lipsku\",\"description\":\"Kolejna witryna sieci &#8222;Instytuty Polskie&#8221;\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/instytutpolski.pl\/leipzig\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/a74d20cf3dac53f5579b2a3ec40f22dd\",\"name\":\"Rainer Mende\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/61382ed949dec269ce106c2fd5871a60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/61382ed949dec269ce106c2fd5871a60?s=96&d=mm&r=g\",\"caption\":\"Rainer Mende\"},\"url\":\"https:\/\/instytutpolski.pl\/leipzig\/author\/mender\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Syndrom Hamleta \/ Das Hamlet Syndrom - Instytut Polski w Lipsku","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/","og_locale":"pl_PL","og_type":"article","og_title":"Syndrom Hamleta \/ Das Hamlet Syndrom - Instytut Polski w Lipsku","og_description":"#SolidarityWithUkraine R: Elwira Niewiera &amp; Piotr Roso\u0142owski, D\/PL 2022, 85 min, OmdU Leipzig-Premiere der deutschen Kino-Fassung mit der Regisseurin Elwira NiewieraModeration: Rainer Mende (Polnisches Institut Berlin \u2013 Filiale Leipzig) Wenige Monate vor der Invasion Russlands in die Ukraine 2022 nehmen f\u00fcnf junge Frauen und M\u00e4nner an einem einzigartigen Theaterprojekt teil. Darin versuchen sie, ihre Kriegserfahrungen [&hellip;]","og_url":"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/","og_site_name":"Instytut Polski w Lipsku","article_published_time":"2022-01-22T09:49:00+00:00","article_modified_time":"2023-01-23T09:53:13+00:00","og_image":[{"width":2000,"height":1081,"url":"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg","type":"image\/jpeg"}],"author":"Rainer Mende","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Rainer Mende","Szacowany czas czytania":"3 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"event","@id":"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/","url":"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/","name":"Syndrom Hamleta \/ Das Hamlet Syndrom","isPartOf":{"@id":"https:\/\/instytutpolski.pl\/leipzig\/#website"},"primaryImageOfPage":{"@id":"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/#primaryimage"},"image":["https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg","https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web-300x162.jpg","https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web-1024x553.jpg","https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg"],"thumbnailUrl":"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg","datePublished":"2022-01-22T09:49:00+02:00","dateModified":"2023-01-23T09:53:13+02:00","author":{"@id":"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/a74d20cf3dac53f5579b2a3ec40f22dd"},"breadcrumb":{"@id":"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/"]}],"@context":"https:\/\/schema.org","startDate":"2023-01-22T01:00:00+02:00","endDate":"2023-01-22T03:00:00+02:00","eventStatus":"EventScheduled","eventAttendanceMode":"OfflineEventAttendanceMode","location":{"@type":"place","name":"Passage Kinos, Hainstra\u00dfe 19a, 04109 Leipzig","address":"Passage Kinos, Hainstra\u00dfe 19a, 04109 Leipzig","geo":{"@type":"GeoCoordinates","latitude":"51.28362182766469","longitude":"12.376354797697585"}},"description":"#SolidarityWithUkraine\nR: Elwira Niewiera &amp; Piotr Roso\u0142owski, D\/PL 2022, 85 min, OmdU\nLeipzig-Premiere der deutschen Kino-Fassung mit der Regisseurin Elwira NiewieraModeration: Rainer Mende (Polnisches Institut Berlin \u2013 Filiale Leipzig)\nWenige Monate vor der Invasion Russlands in die Ukraine 2022 nehmen f\u00fcnf junge Frauen und M\u00e4nner an einem einzigartigen Theaterprojekt teil. Darin versuchen sie, ihre Kriegserfahrungen mit Shakespeares Theaterst\u00fcck \u201eHamlet\u201c in Beziehung zu setzen. Die B\u00fchne ist eine Plattform, auf der sie ihre Trauer und Traumata anhand der ber\u00fchmten Frage \u201eSein oder Nichtsein\u201c reflektieren k\u00f6nnen, die sich in ihrem Leben widerspiegelt.\nDie Protagonist*innen k\u00e4mpfen an gegen Entt\u00e4uschung, Ohnmacht und Wut. Sie versuchen, ihr Leben wieder zu ordnen und gleichzeitig die schmerzhafte Vergangenheit zu verarbeiten: Slavik, der als Soldat durch die H\u00f6lle des Krieges und der Gefangenschaft gegangen ist, Katya, die in den Krieg zog und sich nun nach der Vergebung ihrer Mutter sehnt, weil sie in den Krieg zog, Rodion, der aus dem Donbas geflohen ist und nun mit wachsender Homophobie konfrontiert ist, Roman, der immer noch mit den traumatischen Erinnerungen als Sanit\u00e4ter auf dem Schlachtfeld k\u00e4mpft, und Oxana, die einfach nur vergessen und das Land verlassen will.\nDie Proben f\u00fcr das St\u00fcck werden mit einem intensiven Einblick in das Leben der Protagonist*innen kombiniert: ein kraftvolles Portr\u00e4t einer Generation, die mit dem Trauma des Krieges zurechtzukommen versucht, der seit 2014 in der Ostukraine andauert und nun nach dem Einmarsch Russlands in die Ukraine noch verst\u00e4rkt ihre Gegenwart und Zukunft pr\u00e4gt.\n[embed]https:\/\/youtu.be\/BxySD52pheg[\/embed]\nElwira Niewiera und Piotr Roso\u0142owski drehten gemeinsam bereits die preisgekr\u00f6nten Dokumentarfilme \"Efekt Domina \/ Domino Effekt\" und \"Ksi\u0105\u017c\u0119 i dybuk \/ Der Prinz und der Dibbuk\", die ebenfalls deutsch-polnische Koproduktionen waren. \"Syndrom Hamleta \/ Das Hamlet Syndrom\" wurde u.a. auf Filmfestivals in Adelaide, Krak\u00f3w und Opole ausgezeichnet.\nVeranstalter: Passage Kinos Leipzig in Kooperation mit dem Polnischen Institut Berlin \u2013 Filiale Leipzig\nVeranstaltung auf FacebookInfo: realfictionfilme.de\/das-hamlet-syndrom.html, facebook.com\/TheHamletSyndrome, passage-kinos.de\/das-hamlet-syndromOrt: Passage Kinos, Hainstra\u00dfe 19a, 04109 Leipzig\nFotos \u00a9 Kundschafter Filmproduktion"},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/#primaryimage","url":"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg","contentUrl":"https:\/\/instytutpolski.pl\/leipzig\/wp-content\/uploads\/sites\/29\/2022\/06\/2023-01-19-FILM-Das-Hamlet-Syndrom-Pressebild-1-Kundschafter-Filmproduktion_web.jpg","width":2000,"height":1081},{"@type":"BreadcrumbList","@id":"https:\/\/instytutpolski.pl\/leipzig\/2022\/01\/22\/das-hamlet-syndrom-le\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/instytutpolski.pl\/leipzig\/"},{"@type":"ListItem","position":2,"name":"Syndrom Hamleta \/ Das Hamlet Syndrom"}]},{"@type":"WebSite","@id":"https:\/\/instytutpolski.pl\/leipzig\/#website","url":"https:\/\/instytutpolski.pl\/leipzig\/","name":"Instytut Polski w Lipsku","description":"Kolejna witryna sieci &#8222;Instytuty Polskie&#8221;","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/instytutpolski.pl\/leipzig\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Person","@id":"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/a74d20cf3dac53f5579b2a3ec40f22dd","name":"Rainer Mende","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/instytutpolski.pl\/leipzig\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/61382ed949dec269ce106c2fd5871a60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61382ed949dec269ce106c2fd5871a60?s=96&d=mm&r=g","caption":"Rainer Mende"},"url":"https:\/\/instytutpolski.pl\/leipzig\/author\/mender\/"}]}},"_links":{"self":[{"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/posts\/7580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/comments?post=7580"}],"version-history":[{"count":13,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/posts\/7580\/revisions"}],"predecessor-version":[{"id":7807,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/posts\/7580\/revisions\/7807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/media\/7450"}],"wp:attachment":[{"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/media?parent=7580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/categories?post=7580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instytutpolski.pl\/leipzig\/wp-json\/wp\/v2\/tags?post=7580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}