{"id":28886,"date":"2026-01-16T13:33:57","date_gmt":"2026-01-16T12:33:57","guid":{"rendered":"https:\/\/instytutpolski.pl\/wien\/?p=28886"},"modified":"2026-04-29T13:45:32","modified_gmt":"2026-04-29T11:45:32","slug":"the-world-without-us","status":"publish","type":"post","link":"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/","title":{"rendered":"Gruppenausstellung mit Werken von u.a. Micha\u0142 Zawada: &#8222;The World Without Us&#8221;"},"content":{"rendered":"\n<p><strong>Ausstellungsdauer:\u00a0bis<\/strong>\u00a0<strong>So.,\u00a010. Mai 2026\u00a0<u><br \/>Ort:<\/u> Lentos Kunstmuseum Linz, Ernst-Koref-Promenade 1, 4020 Linz<br \/><\/strong><strong><u><a href=\"https:\/\/www.lentos.at\/ausstellungen\/the-world-without-us\" target=\"_blank\" rel=\"noopener\">Info und Karten<\/a><br \/><br \/><\/u><\/strong><\/p>\n\n\n\n<p style=\"text-align: justify\">Die Gruppenausstellung &#8222;<em>The World Without Us&#8221;<\/em> zeigt k\u00fcnstlerische Positionen, die sich mit einem Weltbild auseinandersetzen, in dem der Mensch nicht mehr im Zentrum steht. Infolge der Aufkl\u00e4rung dehnten die Wissenschaften die tradierte westliche Vorstellung von Raum und Zeit ins schier Unendliche. Das Universum wurde \u00e4lter, gr\u00f6\u00dfer und k\u00e4lter. Damit verbunden ist die Erfahrung einer Verunsicherung: nicht mehr im Mittelpunkt des Universums zu stehen und nicht mehr in einem Weltbild verankert zu sein, das der Geschichte ihren finalen Sinn abzuringen vermag. Die Bedrohung einer Apokalypse wurde abgel\u00f6st durch eine geologische Kontinuit\u00e4t von Katastrophen und Ver\u00e4nderungen.<\/p>\n<p style=\"text-align: justify\">Es d\u00e4mmert das Bewusstsein einer unheimlichen, erhabenen Indifferenz gegen\u00fcber dem menschlichen Ma\u00df in einem Universum, das weder leer noch belebt, sondern untot ist. Die Ausstellung greift Begriffe wie <em>Deep Time<\/em> auf \u2013 Zeitr\u00e4ume von Milliarden Jahren, in denen das menschliche Dasein kaum mehr als ein Augenblick ist \u2013 sowie <em>Cosmic Horror,<\/em> ein Gef\u00fchl zwischen Faszination und Schrecken angesichts einer f\u00fcr unsere Zeit- und Raumvorstellungen unfassbaren nichtmenschlichen Existenz.<\/p>\n<p style=\"text-align: justify\">Bei der Gruppenausstellung &#8222;<em>The World Without Us&#8221; <\/em>im Lentos in Linz sind Werke des polnischen K\u00fcnstlers Micha\u0142 Zawada zu sehen. Zawada wurde 1985 in Krakau geboren, wo er Kunstgeschichte und Malerei studierte und 2023 sein Doktorat abschloss. 2020 gr\u00fcndete er gemeinsam mit Micha\u0142 Sroka und Filip Rybkowski die Galerie Piana in Krakau. Neben der Malerei besch\u00e4ftigt sich Zawada auch mit Fotografie und Videokunst und verkn\u00fcpft wissenschaftliche und theoretische Konzepte mit kunsthistorischen Referenzen. Dabei entstehen poetisch-surrealistische Landschaften mit dystopischen Z\u00fcgen, in denen die Menschheit Naturgeschehnissen untergeordnet ist oder g\u00e4nzlich ausgeblendet wird.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Kurator:innen:<\/strong> Mar\u00adkus Pro\u00adschek, Hem\u00adma Schmutz<br \/><strong>Kura\u00adto\u00adri\u00adsche Assis\u00adtenz:<\/strong> San\u00addra Eichinger<\/p>\n\n\n\n<hr \/>\n<p><span style=\"text-decoration: underline\"><strong>Veranstalter:<\/strong><\/span> Lentos Kunstmuseum Linz<br \/><span style=\"text-decoration: underline\"><strong>Partner:<\/strong><\/span> Polnisches Institut Wien<br \/><br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ausstellungsdauer:\u00a0bis\u00a0So.,\u00a010. Mai 2026\u00a0Ort: Lentos Kunstmuseum Linz, Ernst-Koref-Promenade 1, 4020 LinzInfo und Karten Die Gruppenausstellung &#8222;The World Without Us&#8221; zeigt k\u00fcnstlerische Positionen, die sich mit einem Weltbild auseinandersetzen, in dem der Mensch nicht mehr im Zentrum steht. Infolge der Aufkl\u00e4rung dehnten die Wissenschaften die tradierte westliche Vorstellung von Raum und Zeit ins schier Unendliche. Das Universum [&hellip;]<\/p>\n","protected":false},"author":216,"featured_media":28887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[53,27],"tags":[],"class_list":["post-28886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kunst","category-programm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gruppenausstellung mit Werken von u.a. Micha\u0142 Zawada: &quot;The World Without Us&quot; - Instytut Polski w Wiedniu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gruppenausstellung mit Werken von u.a. Micha\u0142 Zawada: &quot;The World Without Us&quot; - Instytut Polski w Wiedniu\" \/>\n<meta property=\"og:description\" content=\"Ausstellungsdauer:\u00a0bis\u00a0So.,\u00a010. Mai 2026\u00a0Ort: Lentos Kunstmuseum Linz, Ernst-Koref-Promenade 1, 4020 LinzInfo und Karten Die Gruppenausstellung &#8222;The World Without Us&#8221; zeigt k\u00fcnstlerische Positionen, die sich mit einem Weltbild auseinandersetzen, in dem der Mensch nicht mehr im Zentrum steht. Infolge der Aufkl\u00e4rung dehnten die Wissenschaften die tradierte westliche Vorstellung von Raum und Zeit ins schier Unendliche. Das Universum [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Instytut Polski w Wiedniu\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-16T12:33:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T11:45:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1934\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fabianskai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"fabianskai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"event\",\"@id\":\"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/\",\"url\":\"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/\",\"name\":\"Gruppenausstellung mit Werken von u.a. Micha\u0142 Zawada: \\\"The World Without Us\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/instytutpolski.pl\/wien\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/#primaryimage\"},\"image\":[\"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg\",\"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-227x300.jpg\",\"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-774x1024.jpg\",\"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg\"],\"thumbnailUrl\":\"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg\",\"datePublished\":\"2026-01-16T12:33:57+02:00\",\"dateModified\":\"2026-04-29T11:45:32+02:00\",\"author\":{\"@id\":\"https:\/\/instytutpolski.pl\/wien\/#\/schema\/person\/f6f31f979736d8bebf0e5af2ab4517db\"},\"breadcrumb\":{\"@id\":\"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/\"]}],\"@context\":\"https:\/\/schema.org\",\"startDate\":\"2026-02-06T06:00:00+02:00\",\"endDate\":\"2026-05-10T08:00:00+02:00\",\"eventStatus\":\"EventScheduled\",\"eventAttendanceMode\":\"OfflineEventAttendanceMode\",\"location\":{\"@type\":\"place\",\"name\":\"\",\"address\":\"\",\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"\",\"longitude\":\"\"}},\"description\":\"Ausstellungsdauer:\u00a0bis\u00a0So.,\u00a010. Mai 2026\u00a0Ort: Lentos Kunstmuseum Linz, Ernst-Koref-Promenade 1, 4020 LinzInfo und Karten\\nDie Gruppenausstellung \\\"The World Without Us\\\" zeigt k\u00fcnstlerische Positionen, die sich mit einem Weltbild auseinandersetzen, in dem der Mensch nicht mehr im Zentrum steht. Infolge der Aufkl\u00e4rung dehnten die Wissenschaften die tradierte westliche Vorstellung von Raum und Zeit ins schier Unendliche. Das Universum wurde \u00e4lter, gr\u00f6\u00dfer und k\u00e4lter. Damit verbunden ist die Erfahrung einer Verunsicherung: nicht mehr im Mittelpunkt des Universums zu stehen und nicht mehr in einem Weltbild verankert zu sein, das der Geschichte ihren finalen Sinn abzuringen vermag. Die Bedrohung einer Apokalypse wurde abgel\u00f6st durch eine geologische Kontinuit\u00e4t von Katastrophen und Ver\u00e4nderungen.\\nEs d\u00e4mmert das Bewusstsein einer unheimlichen, erhabenen Indifferenz gegen\u00fcber dem menschlichen Ma\u00df in einem Universum, das weder leer noch belebt, sondern untot ist. Die Ausstellung greift Begriffe wie Deep Time auf \u2013 Zeitr\u00e4ume von Milliarden Jahren, in denen das menschliche Dasein kaum mehr als ein Augenblick ist \u2013 sowie Cosmic Horror, ein Gef\u00fchl zwischen Faszination und Schrecken angesichts einer f\u00fcr unsere Zeit- und Raumvorstellungen unfassbaren nichtmenschlichen Existenz.\\nBei der Gruppenausstellung \\\"The World Without Us\\\" im Lentos in Linz sind Werke des polnischen K\u00fcnstlers Micha\u0142 Zawada zu sehen. Zawada wurde 1985 in Krakau geboren, wo er Kunstgeschichte und Malerei studierte und 2023 sein Doktorat abschloss. 2020 gr\u00fcndete er gemeinsam mit Micha\u0142 Sroka und Filip Rybkowski die Galerie Piana in Krakau. Neben der Malerei besch\u00e4ftigt sich Zawada auch mit Fotografie und Videokunst und verkn\u00fcpft wissenschaftliche und theoretische Konzepte mit kunsthistorischen Referenzen. Dabei entstehen poetisch-surrealistische Landschaften mit dystopischen Z\u00fcgen, in denen die Menschheit Naturgeschehnissen untergeordnet ist oder g\u00e4nzlich ausgeblendet wird.\\n\u00a0\\nKurator:innen: Mar\u00adkus Pro\u00adschek, Hem\u00adma SchmutzKura\u00adto\u00adri\u00adsche Assis\u00adtenz: San\u00addra Eichinger\\nVeranstalter: Lentos Kunstmuseum LinzPartner: Polnisches Institut Wien\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/#primaryimage\",\"url\":\"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg\",\"contentUrl\":\"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg\",\"width\":1934,\"height\":2560,\"caption\":\"\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/instytutpolski.pl\/wien\/pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gruppenausstellung mit Werken von u.a. Micha\u0142 Zawada: &#8222;The World Without Us&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/instytutpolski.pl\/wien\/#website\",\"url\":\"https:\/\/instytutpolski.pl\/wien\/\",\"name\":\"Instytut Polski w Wiedniu\",\"description\":\"Instytuty Polskie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/instytutpolski.pl\/wien\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/instytutpolski.pl\/wien\/#\/schema\/person\/f6f31f979736d8bebf0e5af2ab4517db\",\"name\":\"fabianskai\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/instytutpolski.pl\/wien\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/156ecae343fbe263bf21ea2fc3d3d7c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/156ecae343fbe263bf21ea2fc3d3d7c9?s=96&d=mm&r=g\",\"caption\":\"fabianskai\"},\"url\":\"https:\/\/instytutpolski.pl\/wien\/author\/fabianskai\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gruppenausstellung mit Werken von u.a. Micha\u0142 Zawada: \"The World Without Us\" - Instytut Polski w Wiedniu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/","og_locale":"pl_PL","og_type":"article","og_title":"Gruppenausstellung mit Werken von u.a. Micha\u0142 Zawada: \"The World Without Us\" - Instytut Polski w Wiedniu","og_description":"Ausstellungsdauer:\u00a0bis\u00a0So.,\u00a010. Mai 2026\u00a0Ort: Lentos Kunstmuseum Linz, Ernst-Koref-Promenade 1, 4020 LinzInfo und Karten Die Gruppenausstellung &#8222;The World Without Us&#8221; zeigt k\u00fcnstlerische Positionen, die sich mit einem Weltbild auseinandersetzen, in dem der Mensch nicht mehr im Zentrum steht. Infolge der Aufkl\u00e4rung dehnten die Wissenschaften die tradierte westliche Vorstellung von Raum und Zeit ins schier Unendliche. Das Universum [&hellip;]","og_url":"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/","og_site_name":"Instytut Polski w Wiedniu","article_published_time":"2026-01-16T12:33:57+00:00","article_modified_time":"2026-04-29T11:45:32+00:00","og_image":[{"width":1934,"height":2560,"url":"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg","type":"image\/jpeg"}],"author":"fabianskai","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"fabianskai","Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"event","@id":"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/","url":"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/","name":"Gruppenausstellung mit Werken von u.a. Micha\u0142 Zawada: \"The World Without Us\"","isPartOf":{"@id":"https:\/\/instytutpolski.pl\/wien\/#website"},"primaryImageOfPage":{"@id":"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/#primaryimage"},"image":["https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg","https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-227x300.jpg","https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-774x1024.jpg","https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg"],"thumbnailUrl":"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg","datePublished":"2026-01-16T12:33:57+02:00","dateModified":"2026-04-29T11:45:32+02:00","author":{"@id":"https:\/\/instytutpolski.pl\/wien\/#\/schema\/person\/f6f31f979736d8bebf0e5af2ab4517db"},"breadcrumb":{"@id":"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/"]}],"@context":"https:\/\/schema.org","startDate":"2026-02-06T06:00:00+02:00","endDate":"2026-05-10T08:00:00+02:00","eventStatus":"EventScheduled","eventAttendanceMode":"OfflineEventAttendanceMode","location":{"@type":"place","name":"","address":"","geo":{"@type":"GeoCoordinates","latitude":"","longitude":""}},"description":"Ausstellungsdauer:\u00a0bis\u00a0So.,\u00a010. Mai 2026\u00a0Ort: Lentos Kunstmuseum Linz, Ernst-Koref-Promenade 1, 4020 LinzInfo und Karten\nDie Gruppenausstellung \"The World Without Us\" zeigt k\u00fcnstlerische Positionen, die sich mit einem Weltbild auseinandersetzen, in dem der Mensch nicht mehr im Zentrum steht. Infolge der Aufkl\u00e4rung dehnten die Wissenschaften die tradierte westliche Vorstellung von Raum und Zeit ins schier Unendliche. Das Universum wurde \u00e4lter, gr\u00f6\u00dfer und k\u00e4lter. Damit verbunden ist die Erfahrung einer Verunsicherung: nicht mehr im Mittelpunkt des Universums zu stehen und nicht mehr in einem Weltbild verankert zu sein, das der Geschichte ihren finalen Sinn abzuringen vermag. Die Bedrohung einer Apokalypse wurde abgel\u00f6st durch eine geologische Kontinuit\u00e4t von Katastrophen und Ver\u00e4nderungen.\nEs d\u00e4mmert das Bewusstsein einer unheimlichen, erhabenen Indifferenz gegen\u00fcber dem menschlichen Ma\u00df in einem Universum, das weder leer noch belebt, sondern untot ist. Die Ausstellung greift Begriffe wie Deep Time auf \u2013 Zeitr\u00e4ume von Milliarden Jahren, in denen das menschliche Dasein kaum mehr als ein Augenblick ist \u2013 sowie Cosmic Horror, ein Gef\u00fchl zwischen Faszination und Schrecken angesichts einer f\u00fcr unsere Zeit- und Raumvorstellungen unfassbaren nichtmenschlichen Existenz.\nBei der Gruppenausstellung \"The World Without Us\" im Lentos in Linz sind Werke des polnischen K\u00fcnstlers Micha\u0142 Zawada zu sehen. Zawada wurde 1985 in Krakau geboren, wo er Kunstgeschichte und Malerei studierte und 2023 sein Doktorat abschloss. 2020 gr\u00fcndete er gemeinsam mit Micha\u0142 Sroka und Filip Rybkowski die Galerie Piana in Krakau. Neben der Malerei besch\u00e4ftigt sich Zawada auch mit Fotografie und Videokunst und verkn\u00fcpft wissenschaftliche und theoretische Konzepte mit kunsthistorischen Referenzen. Dabei entstehen poetisch-surrealistische Landschaften mit dystopischen Z\u00fcgen, in denen die Menschheit Naturgeschehnissen untergeordnet ist oder g\u00e4nzlich ausgeblendet wird.\n\u00a0\nKurator:innen: Mar\u00adkus Pro\u00adschek, Hem\u00adma SchmutzKura\u00adto\u00adri\u00adsche Assis\u00adtenz: San\u00addra Eichinger\nVeranstalter: Lentos Kunstmuseum LinzPartner: Polnisches Institut Wien"},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/#primaryimage","url":"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg","contentUrl":"https:\/\/instytutpolski.pl\/wien\/wp-content\/uploads\/sites\/2\/2025\/12\/3.2_\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled.jpg","width":1934,"height":2560,"caption":"\u00a9Michal-Zawada-Landscape-Meteorite-and-a-Hand-scaled."},{"@type":"BreadcrumbList","@id":"https:\/\/instytutpolski.pl\/wien\/2026\/01\/16\/the-world-without-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/instytutpolski.pl\/wien\/pl\/"},{"@type":"ListItem","position":2,"name":"Gruppenausstellung mit Werken von u.a. Micha\u0142 Zawada: &#8222;The World Without Us&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/instytutpolski.pl\/wien\/#website","url":"https:\/\/instytutpolski.pl\/wien\/","name":"Instytut Polski w Wiedniu","description":"Instytuty Polskie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/instytutpolski.pl\/wien\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Person","@id":"https:\/\/instytutpolski.pl\/wien\/#\/schema\/person\/f6f31f979736d8bebf0e5af2ab4517db","name":"fabianskai","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/instytutpolski.pl\/wien\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/156ecae343fbe263bf21ea2fc3d3d7c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/156ecae343fbe263bf21ea2fc3d3d7c9?s=96&d=mm&r=g","caption":"fabianskai"},"url":"https:\/\/instytutpolski.pl\/wien\/author\/fabianskai\/"}]}},"_links":{"self":[{"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/posts\/28886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/users\/216"}],"replies":[{"embeddable":true,"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/comments?post=28886"}],"version-history":[{"count":21,"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/posts\/28886\/revisions"}],"predecessor-version":[{"id":30650,"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/posts\/28886\/revisions\/30650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/media\/28887"}],"wp:attachment":[{"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/media?parent=28886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/categories?post=28886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instytutpolski.pl\/wien\/wp-json\/wp\/v2\/tags?post=28886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}